{"id":7473,"date":"2023-07-16T08:53:54","date_gmt":"2023-07-16T08:53:54","guid":{"rendered":"https:\/\/www.infinox.com\/fsc\/?p=7473"},"modified":"2023-07-19T05:37:42","modified_gmt":"2023-07-19T05:37:42","slug":"ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/","title":{"rendered":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown"},"content":{"rendered":"\n<p>\u0e17\u0e2d\u0e07\u0e04\u0e33 \u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile \u0e40\u0e1b\u0e47\u0e19 D-Shape \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 Dow Jones (US30) \u0e23\u0e32\u0e04\u0e32 breakdown \u0e25\u0e07\u0e21\u0e32\u0e43\u0e15\u0e49 balance area \u0e17\u0e33\u0e43\u0e2b\u0e49 short-term \u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e1b\u0e47\u0e19 Imbalance (DOWN) phase<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"Economic Calendar:\">Economic Calendar:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>?? Unemployment Rate<\/strong> (\u0e40\u0e27\u0e25\u0e32 19:30GMT+7). \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c 3.6%, \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 3.7%<\/li>\n\n\n\n<li><strong>?? Non Farm Payrolls<\/strong> (\u0e40\u0e27\u0e25\u0e32 19:30GMT+7). \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c 225K, \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 339K<\/li>\n\n\n\n<li><strong>?? Average Hourly Earnings MoM<\/strong> (\u0e40\u0e27\u0e25\u0e32 19:30GMT+7). \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c 0.3%, \u0e15\u0e31\u0e27\u0e40\u0e25\u0e02\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 0.3%<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"MAJOR Markets Outlook\">MAJOR Markets Outlook<\/h2>\n\n\n\n<p><strong>Commodities:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gold<\/strong><br>Previous Day: sellers active \u0e17\u0e35\u0e48 Prev.VPOC \u0e41\u0e25\u0e49\u0e27\u0e23\u0e32\u0e04\u0e32\u0e01\u0e47 directional move \u0e25\u0e07\u0e2a\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21 scenario \u0e17\u0e35\u0e48 2 \u0e02\u0e2d\u0e07 profile D-Shape \u0e40\u0e2d\u0e32\u0e23\u0e32\u0e04\u0e32\u0e25\u0e07\u0e21\u0e32\u0e2a\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e42\u0e14\u0e22\u0e15\u0e25\u0e32\u0e14\u0e08\u0e1a\u0e25\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35 Profile shape \u0e40\u0e1b\u0e47\u0e19 Short b-Shape with Double Distribution<br><img decoding=\"async\" src=\"https:\/\/media.infinox.com\/cdn-cgi\/image\/format=auto\/articles\/95ebcaa909ee9242d3c97cc71ace8b25.png\" alt=\"\"><br>Today: \u0e23\u0e32\u0e04\u0e32\u0e22\u0e31\u0e07\u0e04\u0e07\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 12 day balance area \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e16\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e21\u0e32\u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e23\u0e07\u0e01\u0e25\u0e32\u0e07 balancing range \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e23\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e19\u0e31\u0e49\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e36\u0e49\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e16\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e23\u0e14\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e35\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e16\u0e49\u0e32\u0e04\u0e34\u0e14\u0e16\u0e36\u0e07 reward to risk ratio \u0e17\u0e38\u0e01 \u0e46 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 balance area \u0e08\u0e30\u0e21\u0e35 area \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 good trade location \u0e2d\u0e22\u0e39\u0e48 2 \u0e08\u0e38\u0e14 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e17\u0e35\u0e48 value area high\/low \u0e41\u0e25\u0e30 balance area high\/low (\u0e02\u0e2d\u0e1a\u0e1a\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e1a\u0e25\u0e48\u0e32\u0e07)<br><br>\u0e01\u0e32\u0e23\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21 Volume Profile : \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile \u0e43\u0e19\u0e27\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19 Short b-Shape \u0e19\u0e31\u0e48\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e21\u0e35 sellers control market \u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e08\u0e30\u0e25\u0e07\u0e44\u0e1b\u0e17\u0e33 new low \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19 \u0e16\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e15\u0e49 Prev.VPOC<br><br>&lt;&#8211;Balance Rules Apply!&#8211;&gt;<br>\u0e01\u0e0f\u0e42\u0e14\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e04\u0e37\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14 Break Out<br>Break Out \u0e02\u0e36\u0e49\u0e19\u0e02\u0e49\u0e32\u0e07\u0e1a\u0e19 (Look above and go) &#8211; \u0e40\u0e23\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19 Buyer<br>Break Down \u0e25\u0e07\u0e02\u0e49\u0e32\u0e07\u0e25\u0e48\u0e32\u0e07 (Look below and go) &#8211; \u0e40\u0e23\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19 Seller<br>Monitor for continuation (Acceptance) or Lack of.<br>Lack of continuation (Failed breakout \/ Look above\/below and fail)<br>&#8211; \u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32 Fade Setup (\u0e40\u0e17\u0e23\u0e14\u0e2a\u0e27\u0e19) target \u0e04\u0e37\u0e2d \u0e02\u0e2d\u0e1a\u0e02\u0e2d\u0e07 balancing area \u0e43\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21<br><br>Directional Bias\/Control<br>&#8211; Short-term = IN BALANCE<br>&#8211; Medium-term = IMD<br>&#8211; Bigger Picture = IN BALANCE<br><br>Profile Shape = Short b-Shape<br><br>10 Days Range Analysis<br>&#8211; Maximum: 27.000<br>&#8211; Minimum: 12.100<br>&#8211; Average: 20.400<\/li>\n<\/ul>\n\n\n\n<p><strong>Forex:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>EUR\/USD<\/strong><br>Previous Day: buyers active \u0e17\u0e35\u0e48 balance area low \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 breakdown \u0e25\u0e07\u0e44\u0e1b\u0e43\u0e15\u0e49 balance area \u0e44\u0e14\u0e49 \u0e1a\u0e27\u0e01\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a profile shape \u0e40\u0e1b\u0e47\u0e19 Short P-Shape \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e21\u0e35 trapped buyers \u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e08\u0e30 pull back \u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\u0e01\u0e47\u0e21\u0e35\u0e2a\u0e39\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01 \u0e42\u0e14\u0e22\u0e15\u0e25\u0e32\u0e14\u0e08\u0e1a\u0e25\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35 Profile shape \u0e40\u0e1b\u0e47\u0e19 D-Shape with Single Distribution<br><img decoding=\"async\" src=\"https:\/\/media.infinox.com\/cdn-cgi\/image\/format=auto\/articles\/0d767850bbca16119bce3d73b5de8c40.png\" alt=\"\"><br>Today: \u0e23\u0e32\u0e04\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e2a\u0e39\u0e48 HVN \u0e02\u0e2d\u0e07 15 day balance area \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e21\u0e32\u0e08\u0e32\u0e01 balance area low \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e16\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e21\u0e32\u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e23\u0e07\u0e01\u0e25\u0e32\u0e07 balancing range \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e23\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e19\u0e31\u0e49\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e36\u0e49\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e16\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e23\u0e14\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e35\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e16\u0e49\u0e32\u0e04\u0e34\u0e14\u0e16\u0e36\u0e07 reward to risk ratio \u0e17\u0e38\u0e01 \u0e46 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 balance area \u0e08\u0e30\u0e21\u0e35 area \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 good trade location \u0e2d\u0e22\u0e39\u0e48 2 \u0e08\u0e38\u0e14 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e17\u0e35\u0e48 value area high\/low \u0e41\u0e25\u0e30 balance area high\/low (\u0e02\u0e2d\u0e1a\u0e1a\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e1a\u0e25\u0e48\u0e32\u0e07)<br><br>\u0e01\u0e32\u0e23\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21 Volume Profile : \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile \u0e43\u0e19\u0e27\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19 D-shape \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e17\u0e32\u0e07 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d 1. \u0e15\u0e25\u0e32\u0e14 balancing \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e02\u0e2d\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e2b\u0e23\u0e37\u0e2d VPOC \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07 directional move<br><br>&lt;&#8211;Balance Rules Apply!&#8211;&gt;<br>\u0e01\u0e0f\u0e42\u0e14\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e04\u0e37\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14 Break Out<br>Break Out \u0e02\u0e36\u0e49\u0e19\u0e02\u0e49\u0e32\u0e07\u0e1a\u0e19 (Look above and go) &#8211; \u0e40\u0e23\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19 Buyer<br>Break Down \u0e25\u0e07\u0e02\u0e49\u0e32\u0e07\u0e25\u0e48\u0e32\u0e07 (Look below and go) &#8211; \u0e40\u0e23\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19 Seller<br>Monitor for continuation (Acceptance) or Lack of.<br>Lack of continuation (Failed breakout \/ Look above\/below and fail)<br>&#8211; \u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32 Fade Setup (\u0e40\u0e17\u0e23\u0e14\u0e2a\u0e27\u0e19) target \u0e04\u0e37\u0e2d \u0e02\u0e2d\u0e1a\u0e02\u0e2d\u0e07 balancing area \u0e43\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21<br><br>Directional Bias\/Control<br>&#8211; Short-term = IN BALANCE<br>&#8211; Medium-term = IMU<br>&#8211; Bigger Picture = IN BALANCE<br><br>Profile Shape = D-Shape<br><br>10 Days Range Analysis<br>&#8211; Maximum: 115.1<br>&#8211; Minimum: 32.9<br>&#8211; Average: 71.5<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>GBP\/USD<\/strong><br>Previous Day: \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session buyers active \u0e17\u0e35\u0e48 Prev.VPOC \u0e41\u0e25\u0e49\u0e27\u0e23\u0e32\u0e04\u0e32 expand \u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21 profile \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 D-Shape \u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48 US session sellers \u0e01\u0e47\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e40\u0e2d\u0e32\u0e23\u0e32\u0e04\u0e32\u0e01\u0e25\u0e31\u0e1a\u0e25\u0e07\u0e21\u0e32\u0e2a\u0e39\u0e48 value area low \u0e17\u0e35\u0e48\u0e0b\u0e36\u0e48\u0e07 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 defense \u0e42\u0e14\u0e22\u0e15\u0e25\u0e32\u0e14\u0e08\u0e1a\u0e25\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35 Profile shape \u0e40\u0e1b\u0e47\u0e19 Long b-Shape with Double Distribution<br><img decoding=\"async\" src=\"https:\/\/media.infinox.com\/cdn-cgi\/image\/format=auto\/articles\/e7b18cd2598fac7a0b7c600af5049181.png\" alt=\"\"><br>Today: \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21\u0e23\u0e32\u0e04\u0e32\u0e22\u0e31\u0e07\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 balance area \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e16\u0e49\u0e32\u0e23\u0e32\u0e04\u0e32\u0e21\u0e32\u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e23\u0e07\u0e01\u0e25\u0e32\u0e07 balancing range \u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e31\u0e49\u0e19\u0e08\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e2a\u0e39\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e23\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e08\u0e32\u0e01\u0e08\u0e38\u0e14\u0e19\u0e31\u0e49\u0e19\u0e23\u0e32\u0e04\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e36\u0e49\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e25\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e09\u0e30\u0e19\u0e31\u0e49\u0e19\u0e16\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e40\u0e17\u0e23\u0e14\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e19\u0e35\u0e49\u0e08\u0e30\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e16\u0e49\u0e32\u0e04\u0e34\u0e14\u0e16\u0e36\u0e07 reward to risk ratio \u0e17\u0e38\u0e01 \u0e46 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19 balance area \u0e08\u0e30\u0e21\u0e35 area \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19 good trade location \u0e2d\u0e22\u0e39\u0e48 2 \u0e08\u0e38\u0e14 \u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d\u0e17\u0e35\u0e48 value area high\/low \u0e41\u0e25\u0e30 balance area high\/low (\u0e02\u0e2d\u0e1a\u0e1a\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e1a\u0e25\u0e48\u0e32\u0e07)<br><br>\u0e01\u0e32\u0e23\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21 Volume Profile : \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile \u0e43\u0e19\u0e27\u0e31\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19 Long b-Shape \u0e19\u0e31\u0e48\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e21\u0e35 trapped sellers \u0e15\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07 \u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32 pull-back \u0e25\u0e07\u0e21\u0e32\u0e08\u0e36\u0e07\u0e21\u0e35\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e35\u0e48 buyers \u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07<br><br>&lt;&#8211;Balance Rules Apply!&#8211;&gt;<br>\u0e01\u0e0f\u0e42\u0e14\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e04\u0e37\u0e2d \u0e40\u0e17\u0e23\u0e14\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14 Break Out<br>Break Out \u0e02\u0e36\u0e49\u0e19\u0e02\u0e49\u0e32\u0e07\u0e1a\u0e19 (Look above and go) &#8211; \u0e40\u0e23\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19 Buyer<br>Break Down \u0e25\u0e07\u0e02\u0e49\u0e32\u0e07\u0e25\u0e48\u0e32\u0e07 (Look below and go) &#8211; \u0e40\u0e23\u0e32\u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19 Seller<br>Monitor for continuation (Acceptance) or Lack of.<br>Lack of continuation (Failed breakout \/ Look above\/below and fail)<br>&#8211; \u0e15\u0e49\u0e2d\u0e07\u0e2b\u0e32 Fade Setup (\u0e40\u0e17\u0e23\u0e14\u0e2a\u0e27\u0e19) target \u0e04\u0e37\u0e2d \u0e02\u0e2d\u0e1a\u0e02\u0e2d\u0e07 balancing area \u0e43\u0e19\u0e1d\u0e31\u0e48\u0e07\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21<br><br>Directional Bias\/Control<br>&#8211; Short-term = IN BALANCE<br>&#8211; Medium-term = IMU<br>&#8211; Bigger Picture = IN BALANCE<br><br>Profile Shape = Long b-Shape<br><br>10 Days Range Analysis<br>&#8211; Maximum: 145.4<br>&#8211; Minimum: 46.9<br>&#8211; Average: 85.9<\/li>\n<\/ul>\n\n\n\n<p><strong>Indices:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>US30 <\/strong><strong><br><\/strong>Previous Day: \u0e1b\u0e23\u0e32\u0e01\u0e0f\u0e27\u0e48\u0e32\u0e23\u0e32\u0e04\u0e32 breakdown \u0e25\u0e07\u0e21\u0e32\u0e43\u0e15\u0e49 5 day balance area \u0e41\u0e25\u0e30 expand range \u0e25\u0e07\u0e21\u0e32\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e44\u0e01\u0e25 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e15\u0e25\u0e32\u0e14\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e08\u0e32\u0e01 balance phase \u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19 Imbalance (DOWN) phase \u0e43\u0e19 short-term \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 Imbalance (UP) \u0e43\u0e19 medium time-frame \u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19 balance phase \u0e14\u0e49\u0e27\u0e22 \u0e42\u0e14\u0e22\u0e15\u0e25\u0e32\u0e14\u0e08\u0e1a\u0e25\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e21\u0e35 Profile shape \u0e40\u0e1b\u0e47\u0e19 Poor structure with Multiple Distribution<br><img decoding=\"async\" src=\"https:\/\/media.infinox.com\/cdn-cgi\/image\/format=auto\/articles\/92893d1a566f13f4268219a6f37ae3e2.png\" alt=\"\"><br>Today: \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e23\u0e32\u0e04\u0e32 breakdown \u0e15\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22 trend down day \u0e01\u0e47\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e41\u0e1b\u0e25\u0e01\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19 Profile \u0e40\u0e1b\u0e47\u0e19 poor strucrture \u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e23\u0e32\u0e04\u0e32\u0e21\u0e32 hold \u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e2d Prev.VPOC \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35<br>\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32 fix poor structure \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e17\u0e35\u0e48 sellers control market \u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49\u0e08\u0e30\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19 sellers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48 breakdown area \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e23\u0e32\u0e04\u0e32\u0e08\u0e30\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e16\u0e36\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1b\u0e25\u0e48\u0e32<br>\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e23\u0e32\u0e04\u0e32 break \u0e25\u0e07\u0e17\u0e33 new low target \u0e02\u0e2d\u0e07 sellers \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e2d\u0e32\u0e23\u0e32\u0e04\u0e32\u0e25\u0e07\u0e44\u0e1b\u0e40\u0e17\u0e2a 7 day balance area low \u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e2a\u0e39\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19 reaction \u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e32\u0e01\u0e01\u0e47\u0e19\u0e49\u0e2d\u0e22<br><br>\u0e01\u0e32\u0e23\u0e15\u0e35\u0e04\u0e27\u0e32\u0e21 Volume Profile :<br><br>Directional Bias\/Control<br>&#8211; Short-term = IMD<br>&#8211; Medium-term = IN BALANCE<br>&#8211; Bigger Picture = IN BALANCE<br><br>Profile Shape = Poor Structure<br><br>10 Days Range Analysis<br>&#8211; Maximum: 522.600<br>&#8211; Minimum: 174.600<br>&#8211; Average: 292.070<\/li>\n<\/ul>\n\n\n\n<p><strong>Direction Bias &amp; Key Reference Areas<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.infinox.com\/cdn-cgi\/image\/format=auto\/articles\/a23646b31dbb94c2baa10da297d42c7a.png\" alt=\"\"\/><\/figure>\n\n\n\n<p>*\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19 (\u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e04\u0e27\u0e23\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19) \u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19 \u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e2d\u0e37\u0e48\u0e19\u0e46, INFINOX \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e47\u0e19\u0e43\u0e14\u0e43\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e41\u0e19\u0e30\u0e19\u0e33\u0e08\u0e32\u0e01 INFINOX \u0e2b\u0e23\u0e37\u0e2d\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e35\u0e22\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e25\u0e22\u0e38\u0e17\u0e18\u0e4c\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19, \u0e01\u0e32\u0e23\u0e17\u0e33\u0e18\u0e38\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e43\u0e14 \u0e46 \u0e19\u0e31\u0e49\u0e19\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e43\u0e14\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape<\/p>\n","protected":false},"author":28,"featured_media":7474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[588,35,606,590,594,598,582,592,584],"tags":[],"class_list":["post-7473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-market-news","category-financial-data-commentary","category-indices","category-latest-articles","category-research","category-forex","category-commodities"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFINOX\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-07-16T08:53:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-07-19T05:37:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#blogposting\",\"name\":\"IX Daily 7 \\u0e01.\\u0e04. 23: Euro \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 balance area low, GBP \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 Prev.VPOC, \\u0e17\\u0e2d\\u0e07\\u0e04\\u0e33\\u0e40\\u0e08\\u0e2d sellers \\u0e17\\u0e35\\u0e48 Prev.VPOC, US30 breakdown - INFINOX\",\"headline\":\"IX Daily 7 \\u0e01.\\u0e04. 23: Euro \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 balance area low, GBP \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 Prev.VPOC, \\u0e17\\u0e2d\\u0e07\\u0e04\\u0e33\\u0e40\\u0e08\\u0e2d sellers \\u0e17\\u0e35\\u0e48 Prev.VPOC, US30 breakdown\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/07\\\/iStock-1486828834.jpg\",\"width\":724,\"height\":483,\"caption\":\"The analyst works on a laptop showing data business analysis and Data Management System with KPI and metrics connected to the database for technology finance operations Data Analytics Statistics.\"},\"datePublished\":\"2023-07-16T08:53:54+00:00\",\"dateModified\":\"2023-07-19T05:37:42+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, \\u0e02\\u0e48\\u0e32\\u0e27\\u0e2a\\u0e32\\u0e23\\u0e15\\u0e25\\u0e32\\u0e14, \\u0e04\\u0e27\\u0e32\\u0e21\\u0e04\\u0e34\\u0e14\\u0e40\\u0e2b\\u0e47\\u0e19\\u0e40\\u0e01\\u0e35\\u0e48\\u0e22\\u0e27\\u0e01\\u0e31\\u0e1a\\u0e02\\u0e49\\u0e2d\\u0e21\\u0e39\\u0e25\\u0e17\\u0e32\\u0e07\\u0e01\\u0e32\\u0e23\\u0e40\\u0e07\\u0e34\\u0e19, \\u0e14\\u0e31\\u0e0a\\u0e19\\u0e35, \\u0e1a\\u0e17\\u0e04\\u0e27\\u0e32\\u0e21\\u0e25\\u0e48\\u0e32\\u0e2a\\u0e38\\u0e14, \\u0e1a\\u0e17\\u0e04\\u0e27\\u0e32\\u0e21\\u0e27\\u0e34\\u0e08\\u0e31\\u0e22, \\u0e1f\\u0e2d\\u0e40\\u0e23\\u0e47\\u0e01\\u0e0b\\u0e4c, \\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\\u0e42\\u0e20\\u0e04\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c, \\u0e20\\u0e32\\u0e29\\u0e32\\u0e44\\u0e17\\u0e22\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"\\u0e1a\\u0e17\\u0e04\\u0e27\\u0e32\\u0e21\\u0e27\\u0e34\\u0e08\\u0e31\\u0e22\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"\\u0e1a\\u0e17\\u0e04\\u0e27\\u0e32\\u0e21\\u0e27\\u0e34\\u0e08\\u0e31\\u0e22\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/commodities\\\/#listItem\",\"name\":\"\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\\u0e42\\u0e20\\u0e04\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/commodities\\\/#listItem\",\"position\":4,\"name\":\"\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\\u0e42\\u0e20\\u0e04\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/commodities\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#listItem\",\"name\":\"IX Daily 7 \\u0e01.\\u0e04. 23: Euro \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 balance area low, GBP \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 Prev.VPOC, \\u0e17\\u0e2d\\u0e07\\u0e04\\u0e33\\u0e40\\u0e08\\u0e2d sellers \\u0e17\\u0e35\\u0e48 Prev.VPOC, US30 breakdown\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"\\u0e1a\\u0e17\\u0e04\\u0e27\\u0e32\\u0e21\\u0e27\\u0e34\\u0e08\\u0e31\\u0e22\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#listItem\",\"position\":5,\"name\":\"IX Daily 7 \\u0e01.\\u0e04. 23: Euro \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 balance area low, GBP \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 Prev.VPOC, \\u0e17\\u0e2d\\u0e07\\u0e04\\u0e33\\u0e40\\u0e08\\u0e2d sellers \\u0e17\\u0e35\\u0e48 Prev.VPOC, US30 breakdown\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-intel\\\/research\\\/commodities\\\/#listItem\",\"name\":\"\\u0e2a\\u0e34\\u0e19\\u0e04\\u0e49\\u0e32\\u0e42\\u0e20\\u0e04\\u0e20\\u0e31\\u0e13\\u0e11\\u0e4c\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/\",\"name\":\"INFINOX\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"INFINOX\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/\",\"name\":\"IX Daily 7 \\u0e01.\\u0e04. 23: Euro \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 balance area low, GBP \\u0e40\\u0e08\\u0e2d buyers \\u0e17\\u0e35\\u0e48 Prev.VPOC, \\u0e17\\u0e2d\\u0e07\\u0e04\\u0e33\\u0e40\\u0e08\\u0e2d sellers \\u0e17\\u0e35\\u0e48 Prev.VPOC, US30 breakdown - INFINOX\",\"description\":\"Euro \\u0e40\\u0e17\\u0e23\\u0e14\\u0e2d\\u0e22\\u0e39\\u0e48\\u0e17\\u0e35\\u0e48 good trade location \\u0e2a\\u0e33\\u0e2b\\u0e23\\u0e31\\u0e1a buyers \\u0e17\\u0e35\\u0e48 balance area low \\u0e17\\u0e33\\u0e43\\u0e2b\\u0e49 buyers \\u0e01\\u0e25\\u0e31\\u0e1a\\u0e40\\u0e02\\u0e49\\u0e32\\u0e21\\u0e32 active \\u0e15\\u0e32\\u0e21\\u0e04\\u0e32\\u0e14 \\u0e43\\u0e19\\u0e02\\u0e13\\u0e30\\u0e17\\u0e35\\u0e48 GBP buyers active \\u0e43\\u0e19\\u0e0a\\u0e48\\u0e27\\u0e07 London session \\u0e17\\u0e35\\u0e48 Prev.VPOC \\u0e40\\u0e1b\\u0e47\\u0e19\\u0e44\\u0e1b\\u0e15\\u0e32\\u0e21\\u0e04\\u0e32\\u0e14\\u0e01\\u0e32\\u0e23\\u0e13\\u0e4c\\u0e40\\u0e21\\u0e37\\u0e48\\u0e2d\\u0e40\\u0e23\\u0e32\\u0e21\\u0e35 Profile D-Shape Euro \\u0e40\\u0e17\\u0e23\\u0e14\\u0e2d\\u0e22\\u0e39\\u0e48\\u0e17\\u0e35\\u0e48 good trade location \\u0e2a\\u0e33\\u0e2b\\u0e23\\u0e31\\u0e1a buyers \\u0e17\\u0e35\\u0e48 balance area low \\u0e17\\u0e33\\u0e43\\u0e2b\\u0e49 buyers \\u0e01\\u0e25\\u0e31\\u0e1a\\u0e40\\u0e02\\u0e49\\u0e32\\u0e21\\u0e32 active \\u0e15\\u0e32\\u0e21\\u0e04\\u0e32\\u0e14 \\u0e43\\u0e19\\u0e02\\u0e13\\u0e30\\u0e17\\u0e35\\u0e48 GBP buyers active \\u0e43\\u0e19\\u0e0a\\u0e48\\u0e27\\u0e07 London session \\u0e17\\u0e35\\u0e48 Prev.VPOC \\u0e40\\u0e1b\\u0e47\\u0e19\\u0e44\\u0e1b\\u0e15\\u0e32\\u0e21\\u0e04\\u0e32\\u0e14\\u0e01\\u0e32\\u0e23\\u0e13\\u0e4c\\u0e40\\u0e21\\u0e37\\u0e48\\u0e2d\\u0e40\\u0e23\\u0e32\\u0e21\\u0e35 Profile D-Shape\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/07\\\/iStock-1486828834.jpg\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#mainImage\",\"width\":724,\"height\":483,\"caption\":\"The analyst works on a laptop showing data business analysis and Data Management System with KPI and metrics connected to the database for technology finance operations Data Analytics Statistics.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/th\\\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\\\/#mainImage\"},\"datePublished\":\"2023-07-16T08:53:54+00:00\",\"dateModified\":\"2023-07-19T05:37:42+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX","description":"Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape","canonical_url":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#blogposting","name":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX","headline":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2023\/07\/iStock-1486828834.jpg","width":724,"height":483,"caption":"The analyst works on a laptop showing data business analysis and Data Management System with KPI and metrics connected to the database for technology finance operations Data Analytics Statistics."},"datePublished":"2023-07-16T08:53:54+00:00","dateModified":"2023-07-19T05:37:42+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#webpage"},"articleSection":"IX Daily, IX Intel, \u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e15\u0e25\u0e32\u0e14, \u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19, \u0e14\u0e31\u0e0a\u0e19\u0e35, \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14, \u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22, \u0e1f\u0e2d\u0e40\u0e23\u0e47\u0e01\u0e0b\u0e4c, \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c, \u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/#listItem","name":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/#listItem","position":3,"name":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22","item":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/commodities\/#listItem","name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/commodities\/#listItem","position":4,"name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c","item":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/commodities\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#listItem","name":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/#listItem","name":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#listItem","position":5,"name":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/commodities\/#listItem","name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/infinox\/","name":"INFINOX","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g","width":96,"height":96,"caption":"INFINOX"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#webpage","url":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/","name":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX","description":"Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2023\/07\/iStock-1486828834.jpg","@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#mainImage","width":724,"height":483,"caption":"The analyst works on a laptop showing data business analysis and Data Management System with KPI and metrics connected to the database for technology finance operations Data Analytics Statistics."},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/#mainImage"},"datePublished":"2023-07-16T08:53:54+00:00","dateModified":"2023-07-19T05:37:42+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX","og:description":"Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape","og:url":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/","article:published_time":"2023-07-16T08:53:54+00:00","article:modified_time":"2023-07-19T05:37:42+00:00","twitter:card":"summary_large_image","twitter:title":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown - INFINOX","twitter:description":"Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape"},"aioseo_meta_data":{"post_id":"7473","title":null,"description":"#post_excerpt Euro \u0e40\u0e17\u0e23\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48 good trade location \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a buyers \u0e17\u0e35\u0e48 balance area low \u0e17\u0e33\u0e43\u0e2b\u0e49 buyers \u0e01\u0e25\u0e31\u0e1a\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32 active \u0e15\u0e32\u0e21\u0e04\u0e32\u0e14 \u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48 GBP buyers active \u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 London session \u0e17\u0e35\u0e48 Prev.VPOC \u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e04\u0e32\u0e14\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e21\u0e35 Profile D-Shape","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-15 01:48:42","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-07-16 08:53:56","updated":"2025-11-27 02:35:32"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/th\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/\" title=\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22\">\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/commodities\/\" title=\"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c\">\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tIX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/"},{"label":"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22","link":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/"},{"label":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e42\u0e20\u0e04\u0e20\u0e31\u0e13\u0e11\u0e4c","link":"https:\/\/www.infinox.com\/global\/th\/ix-intel\/research\/commodities\/"},{"label":"IX Daily 7 \u0e01.\u0e04. 23: Euro \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 balance area low, GBP \u0e40\u0e08\u0e2d buyers \u0e17\u0e35\u0e48 Prev.VPOC, \u0e17\u0e2d\u0e07\u0e04\u0e33\u0e40\u0e08\u0e2d sellers \u0e17\u0e35\u0e48 Prev.VPOC, US30 breakdown","link":"https:\/\/www.infinox.com\/global\/th\/ix-daily-7-a-c-23-euro-meets-buyers-at-balance-area-low-gbp-meets-buyers-at-prev-vpoc\/"}],"lang":"th","translations":{"th":7473},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/7473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=7473"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/7473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/7474"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=7473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=7473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=7473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}