{"id":27562,"date":"2025-09-29T11:14:18","date_gmt":"2025-09-29T11:14:18","guid":{"rendered":"https:\/\/www.infinox.com\/global\/?p=27562"},"modified":"2025-09-29T11:14:24","modified_gmt":"2025-09-29T11:14:24","slug":"acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/","title":{"rendered":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana"},"content":{"rendered":"\n<p>Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma revis\u00e3o para cima do crescimento do segundo trimestre, o que pesou nas expectativas de flexibiliza\u00e7\u00e3o iminente da pol\u00edtica monet\u00e1ria. Apesar da recupera\u00e7\u00e3o tardia, os principais \u00edndices ainda encerraram uma sequ\u00eancia de tr\u00eas semanas de ganhos, refletindo a cautela dos investidores em rela\u00e7\u00e3o ao caminho das taxas de juros e \u00e0 persistente fraqueza nas a\u00e7\u00f5es de tecnologia. No exterior, os mercados europeus e asi\u00e1ticos tamb\u00e9m foram impactados por novos an\u00fancios de tarifas da Casa Branca, com o setor farmac\u00eautico sob press\u00e3o, enquanto os pre\u00e7os da energia subiram ap\u00f3s preocupa\u00e7\u00f5es renovadas com o abastecimento, ligadas ao conflito entre R\u00fassia e Ucr\u00e2nia.<\/p>\n\n\n\n<p>Principias Pontos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dow se Recupera, mas Termina a Semana em Queda: O Dow Jones Industrial Average subiu 299,97 pontos, ou 0,65%, fechando em 46.247,29. O \u00edndice quebrou uma sequ\u00eancia de tr\u00eas dias de perdas com a alta de sexta-feira, mas ainda caiu 0,2% durante a semana, registrando seu primeiro decl\u00ednio em quatro semanas.<\/li>\n\n\n\n<li>O S&amp;P 500 Quebra Sequ\u00eancia de Tr\u00eas Semanas de Alta: O S&amp;P 500 subiu 0,59% na sexta-feira, fechando em 6.643,70, ap\u00f3s uma recupera\u00e7\u00e3o tardia. No entanto, o \u00edndice de refer\u00eancia recuou 0,3% ao longo da semana, encerrando uma sequ\u00eancia de tr\u00eas semanas de ganhos, \u00e0 medida que preocupa\u00e7\u00f5es com a pol\u00edtica monet\u00e1ria reduziram o apetite por risco.<\/li>\n\n\n\n<li>Nasdaq Sob Press\u00e3o de Perdas no Setor de Tecnologia: O Nasdaq Composite ganhou 0,44% no dia, fechando em 22.484,07, embora tenha perdido 0,7% na semana. As a\u00e7\u00f5es de software e vinculadas \u00e0 IA pesaram significativamente no sentimento, com a Oracle caindo mais de 8% ao longo da semana.<\/li>\n\n\n\n<li>Mercados Europeus Sobem Apesar da Press\u00e3o da Ind\u00fastria Farmac\u00eautica: As a\u00e7\u00f5es europeias avan\u00e7aram na sexta-feira, com o \u00edndice Stoxx 600 subindo 0,8% e os principais \u00edndices nacionais em alta. O FTSE 100 de Londres subiu 0,74% para 9.284,83, o CAC 40 de Paris ganhou 0,86%, o FTSE MIB de Mil\u00e3o subiu 0,96% e o DAX de Frankfurt aumentou 0,87%. No entanto, o \u00edndice Stoxx Europe 600 Healthcare terminou est\u00e1vel ap\u00f3s o presidente dos EUA, Donald Trump, confirmar tarifas de 100% sobre as importa\u00e7\u00f5es farmac\u00eauticas a partir de outubro. As empresas dinamarquesas Zealand Pharma e Novo Nordisk ca\u00edram 2,4% e 3,5% respectivamente, enquanto a Orion da Finl\u00e2ndia deslizou 1,9%. Os analistas do JP Morgan sugeriram que o impacto geral pode ser limitado devido aos planos de fabrica\u00e7\u00e3o nos EUA. As tens\u00f5es comerciais mais amplas continuaram em foco, j\u00e1 que relat\u00f3rios indicaram que a UE est\u00e1 preparando tarifas de at\u00e9 50% sobre o a\u00e7o chin\u00eas. Al\u00e9m disso, as a\u00e7\u00f5es da Orsted ca\u00edram 2% em meio a especula\u00e7\u00f5es de que poderia vender uma participa\u00e7\u00e3o no seu projeto e\u00f3lico Hornsea 3 no Reino Unido.<\/li>\n\n\n\n<li>\u00c1sia mista enquanto a\u00e7\u00f5es de farmac\u00eauticas caem devido a tarifas: As a\u00e7\u00f5es asi\u00e1ticas ficaram mistas, com quedas significativas no setor farmac\u00eautico ap\u00f3s Trump anunciar taxas de 100% sobre importa\u00e7\u00f5es de medicamentos de marca. O \u00edndice Topix Pharma caiu 1,47%, com Daiichi Sankyo caindo 2,11%, Chugai recuando 3,64% e Sumitomo despencando 5,33%. Na Coreia do Sul, Samsung Biologics e SK Bio Pharmaceuticals perderam 1,71% e 3,71%. As a\u00e7\u00f5es da Alibaba Health e JD Health listadas em Hong Kong recuaram 2,92% e 2,23%. De forma mais ampla, o Nikkei 225 do Jap\u00e3o ficou est\u00e1vel, enquanto o Topix subiu 0,59% para um novo recorde hist\u00f3rico. O Kospi da Coreia do Sul caiu 2,02%, o Kosdaq caiu 1,57% e o Hang Seng de Hong Kong perdeu 0,86%. O \u00edndice CSI 300 da China terminou est\u00e1vel, enquanto o ASX 200 da Austr\u00e1lia caiu marginalmente. Os dados de infla\u00e7\u00e3o de T\u00f3quio tamb\u00e9m chamaram aten\u00e7\u00e3o, com os pre\u00e7os ao consumidor subindo 2,5% em setembro, abaixo da previs\u00e3o de 2,8%.<\/li>\n\n\n\n<li>Gastos do consumidor nos EUA fortes, mas o sentimento cai: Os gastos do consumidor aumentaram 0,6% em agosto, superando a previs\u00e3o de 0,5%, estendendo o s\u00f3lido ganho de julho e mantendo o crescimento do PIB em uma base firme. Os analistas esperam que o ritmo desacelere at\u00e9 o final do ano, \u00e0 medida que os pre\u00e7os mais altos pesam sobre as fam\u00edlias, embora as estimativas de crescimento do terceiro trimestre permane\u00e7am pr\u00f3ximas de 2,5%. Ao mesmo tempo, o \u00edndice de sentimento do consumidor da Universidade de Michigan para setembro caiu para 55,1, uma queda mensal de 5,3%, com decl\u00ednios em quase todas as demografias. Notavelmente, o sentimento entre as fam\u00edlias com maiores participa\u00e7\u00f5es em a\u00e7\u00f5es se manteve est\u00e1vel, refletindo uma diverg\u00eancia ligada \u00e0 riqueza do mercado. As expectativas de infla\u00e7\u00e3o permaneceram amplamente ancoradas, com a perspectiva de um ano em 4,7% e a de cinco anos em 3,7%.<\/li>\n\n\n\n<li>Ganho do Petr\u00f3leo devido a Preocupa\u00e7\u00f5es com o Fornecimento Russo: Os pre\u00e7os do petr\u00f3leo subiram ap\u00f3s ataques de drones ucranianos a refinarias russas interromperem as exporta\u00e7\u00f5es. O Brent fechou a $69,78, alta de 0,52%, enquanto o WTI subiu 0,54% para $65,32. A R\u00fassia tamb\u00e9m estendeu as restri\u00e7\u00f5es \u00e0s exporta\u00e7\u00f5es de gasolina e anunciou uma proibi\u00e7\u00e3o parcial das exporta\u00e7\u00f5es de diesel at\u00e9 o final do ano, restringindo ainda mais os suprimentos.<\/li>\n\n\n\n<li>Rendimentos Mant\u00eam-se Est\u00e1veis Conforme Infla\u00e7\u00e3o Atinge Previs\u00f5es: Os rendimentos dos t\u00edtulos do Tesouro dos EUA mantiveram-se praticamente inalterados depois que o \u00edndice PCE n\u00facleo subiu 2,9% no ano, em linha com as expectativas. O rendimento de 10 anos fechou perto de 4,18%, o de 2 anos em 3,65%, e o de 30 anos em 4,76%. Os dados confirmaram que a infla\u00e7\u00e3o est\u00e1 moderando, mas permanece acima da meta de 2% do Fed, enquanto n\u00fameros mais fortes de pedidos de aux\u00edlio-desemprego e de PIB no in\u00edcio da semana limitaram as expectativas de cortes mais profundos nas taxas.<\/li>\n<\/ul>\n\n\n\n<p>FX Hoje:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1970\" height=\"792\" src=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-29Sep25-3.png\" alt=\"\" class=\"wp-image-27563\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-29Sep25-3.png 1970w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-29Sep25-3-768x309.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-29Sep25-3-1536x618.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-29Sep25-3-710x285.png 710w\" sizes=\"(max-width: 1970px) 100vw, 1970px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>EUR\/USD Mant\u00e9m-se Acima do Suporte Chave: O par EUR\/USD fechou em 1,1704, com alta de 0,33%, ap\u00f3s oscilar entre 1,1659 e 1,1706, encerrando pr\u00f3ximo aos m\u00e1ximos com uma vela de estabiliza\u00e7\u00e3o. O repique ocorreu quando compradores voltaram a atuar em torno de 1,1650, limitando a press\u00e3o de baixa ap\u00f3s uma semana de menor impulso. A m\u00e9dia m\u00f3vel de 50 dias em 1,1680 continua a atuar como suporte pr\u00f3ximo, enquanto a m\u00e9dia de 100 dias em 1,1589 e a de 200 dias em 1,1176 sustentam a tend\u00eancia de longu\u00edssimo prazo de m\u00ednimas mais altas desde junho. A resist\u00eancia imediata est\u00e1 em 1,1750, seguida por 1,1850, onde avan\u00e7os anteriores estancaram. Pelo lado da queda, um rompimento sustentado abaixo de 1,1650 poderia levar a um movimento em dire\u00e7\u00e3o a 1,1580, deixando o vi\u00e9s mais defensivo caso os compradores n\u00e3o consigam manter o suporte.<\/li>\n\n\n\n<li>GBP\/USD Recupera de Fraqueza Recente: O GBP\/USD fechou em 1,3407, com alta de 0,47%, depois de oscilar entre 1,3330 e 1,3415, encerrando perto do topo do intervalo ap\u00f3s testar o suporte em 1,3350. A recupera\u00e7\u00e3o ajudou a aliviar a press\u00e3o ap\u00f3s a maior queda semanal da libra esterlina desde julho, embora o par permane\u00e7a limitado abaixo da m\u00e9dia m\u00f3vel de 50 dias em 1,3469 e da m\u00e9dia m\u00f3vel de 100 dias em 1,3489. A m\u00e9dia m\u00f3vel de 200 dias em 1,3128 fornece uma base mais ampla, mantendo uma perspectiva de longo prazo construtiva apesar da fraqueza recente. A a\u00e7\u00e3o de pre\u00e7o tem sido marcada por m\u00e1ximas mais baixas desde meados de setembro, sublinhando uma perda de momentum ap\u00f3s repetidas falhas perto de 1,3700. A resist\u00eancia est\u00e1 em 1,3450 e 1,3550, enquanto o suporte permanece firme em 1,3350, seguido por 1,3250 se os vendedores retomarem o controle.<\/li>\n\n\n\n<li>USD\/JPY Recuar Abaixo de 150.00: O USD\/JPY fechou em 149.47, uma queda de 0,21%, ap\u00f3s negociar entre 149.40 e 149.96, recuando ap\u00f3s estagnar logo abaixo da marca psicol\u00f3gica de 150.00. A retra\u00e7\u00e3o ocorreu ap\u00f3s um forte rali no in\u00edcio da semana, deixando uma pequena vela de baixa que mostrou os vendedores defendendo a resist\u00eancia. A m\u00e9dia de 20 dias em 147.72 e a de 50 dias em 146.45 est\u00e3o ambas em tend\u00eancia de alta, enquanto a m\u00e9dia de 100 dias em 148.46 e a de 200 dias em 148.93 continuam fornecendo n\u00edveis de refer\u00eancia chave. Uma quebra sustentada acima de 149.80 reabriria o caminho em dire\u00e7\u00e3o a 150.50\u2013151.00, enquanto o suporte inicial agora est\u00e1 em 149.00 e depois em 148.50 se a press\u00e3o aumentar.<\/li>\n\n\n\n<li>Prata Estende Rally em Dire\u00e7\u00e3o a 47.00: A prata fechou a $46,08, uma alta de 2,02%, ap\u00f3s ter oscilado entre $44,61 e $46,62, terminando perto das m\u00e1ximas com mais uma forte vela de alta. O metal agora acumulou sucessivos ganhos durante setembro, sustentado por m\u00e9dias m\u00f3veis ascendentes com o pre\u00e7o m\u00e9dio de 20 dias a $41,79, de 50 dias a $39,79, de 100 dias a $37,47, e de 200 dias a $34,59, todas alinhadas em alta. A quebra acima de $45,00 transformou esse n\u00edvel em suporte imediato, enquanto os compradores agora miram a resist\u00eancia em $47,00. Um movimento al\u00e9m dessa barreira abriria caminho para a faixa de $47,50\u2013$48,00.<\/li>\n\n\n\n<li>O ouro consolida-se perto das m\u00e1ximas acima de $3740: O ouro fechou a $3767, uma alta de 0,47%, ap\u00f3s variar entre $3749 e $3784, mantendo sua recente ruptura acima de $3700 com outro fechamento positivo. O metal continua a ser apoiado por um alinhamento otimista das m\u00e9dias m\u00f3veis, com a m\u00e9dia de 20 dias em $3612, 50 dias em $3475, 100 dias em $3400 e 200 dias em $3158, todas subindo firmemente. A tend\u00eancia de alta desde o in\u00edcio de agosto permanece em vigor, com sucessivas m\u00ednimas mais altas confirmando uma forte demanda subjacente. A resist\u00eancia agora est\u00e1 em $3785, depois $3800, enquanto o suporte \u00e9 visto em $3740 e na zona de ruptura perto de $3700.<\/li>\n<\/ul>\n\n\n\n<p>Movimentos de Mercado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A\u00e7\u00f5es de Energia Avan\u00e7am Com os Pre\u00e7os do Petr\u00f3leo: Produtores de energia e empresas de servi\u00e7os se recuperaram juntamente com o petr\u00f3leo, \u00e0 medida que o WTI atingiu uma alta de 1,75 meses. A Devon Energy ganhou mais de 3%, a Schlumberger subiu mais de 2%, enquanto a Exxon Mobil, ConocoPhillips e Marathon Petroleum fecharam todas em alta.<\/li>\n\n\n\n<li>A Electronic Arts Dispara com Conversas para Aquisi\u00e7\u00e3o Privada: A EA subiu mais de 14% ap\u00f3s relatos de que a empresa est\u00e1 em negocia\u00e7\u00f5es avan\u00e7adas para ser adquirida por um cons\u00f3rcio liderado pela Silver Lake.<\/li>\n\n\n\n<li>As a\u00e7\u00f5es da Crinetics Pharmaceuticals disparam com a aprova\u00e7\u00e3o da FDA: As a\u00e7\u00f5es da Crinetics subiram mais de 27% ap\u00f3s a empresa conseguir a aprova\u00e7\u00e3o de seu tratamento Palsonify para adultos com acromegalia.<\/li>\n\n\n\n<li>Paccar sobe com impulso de tarifas para caminh\u00f5es nos EUA: Paccar teve um aumento de mais de 5% ap\u00f3s a confirma\u00e7\u00e3o de que as importa\u00e7\u00f5es de caminh\u00f5es pesados ser\u00e3o atingidas com uma tarifa de 25%, apoiando a demanda por ve\u00edculos fabricados nos EUA.<\/li>\n\n\n\n<li>Mirion Technologies ganha destaque com cobertura positiva: Mirion Technologies subiu mais de 10% ap\u00f3s o JPMorgan iniciar a cobertura com uma classifica\u00e7\u00e3o &#8220;overweight&#8221; e um pre\u00e7o-alvo de $28.<\/li>\n\n\n\n<li>Concentrix cai devido a fraca previs\u00e3o de lucros: Concentrix caiu mais de 13% ap\u00f3s emitir uma orienta\u00e7\u00e3o para o quarto trimestre bem abaixo das expectativas dos analistas, desapontando os investidores.<\/li>\n\n\n\n<li>RH sofre perdas com novas tarifas sobre importa\u00e7\u00f5es de arm\u00e1rios: A RH perdeu mais de 4% ap\u00f3s os EUA anunciarem uma tarifa de 50% sobre arm\u00e1rios de cozinha, pias de banheiro e produtos relacionados importados, com vig\u00eancia a partir de outubro.<\/li>\n\n\n\n<li>Costco recua ap\u00f3s resultados mistos de vendas: as a\u00e7\u00f5es da Costco ca\u00edram mais de 2% depois que as vendas compar\u00e1veis trimestrais nos EUA aumentaram 5,1%, ligeiramente abaixo da expectativa consensual de 5,21%.<\/li>\n<\/ul>\n\n\n\n<p>A recupera\u00e7\u00e3o de sexta-feira ajudou a limitar os danos da semana para os mercados de a\u00e7\u00f5es, mas n\u00e3o foi suficiente para impedir os principais \u00edndices dos EUA de interromperem suas sequ\u00eancias de ganhos de v\u00e1rias semanas. Os dados de infla\u00e7\u00e3o atenderam \u00e0s previs\u00f5es e estabilizaram o sentimento ap\u00f3s os n\u00fameros mais fortes de crescimento e trabalho terem provocado uma instabilidade nas expectativas no in\u00edcio da semana. Com as tarifas remodelando as perspectivas para os setores farmac\u00eautico e industrial, e os pre\u00e7os da energia subindo devido a novos riscos de oferta, os investidores enfrentam uma mistura complexa de sinais ao entrar no pr\u00f3ximo trimestre. O tom do mercado permanece de cautela, com os negociadores equilibrando o otimismo em rela\u00e7\u00e3o ao consumo est\u00e1vel contra a incerteza sobre o ritmo do afrouxamento da pol\u00edtica do Federal Reserve.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma<a href=\"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":28,"featured_media":27552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[530,30,548],"tags":[569,566,575],"class_list":["post-27562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-market-news","tag-market-updates","tag-international-news","tag-whats-new"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFINOX\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-29T11:14:18+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-29T11:14:24+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#blogposting\",\"name\":\"A\\u00e7\\u00f5es sobem com relat\\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX\",\"headline\":\"A\\u00e7\\u00f5es sobem com relat\\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/9-1-scaled.jpg\",\"width\":2560,\"height\":1280},\"datePublished\":\"2025-09-29T11:14:18+00:00\",\"dateModified\":\"2025-09-29T11:14:24+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Not\\u00edcias do mercado, Atualiza\\u00e7\\u00f5es de mercado, Not\\u00edcias internacionais, O que h\\u00e1 de novo, Portugu\\u00eas, pll_68da678e89685\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Pesquisa\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#listItem\",\"name\":\"A\\u00e7\\u00f5es sobem com relat\\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#listItem\",\"position\":5,\"name\":\"A\\u00e7\\u00f5es sobem com relat\\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/\",\"name\":\"INFINOX\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"INFINOX\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/\",\"name\":\"A\\u00e7\\u00f5es sobem com relat\\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX\",\"description\":\"Wall Street conseguiu um rali de al\\u00edvio na sexta-feira, j\\u00e1 que os dados de infla\\u00e7\\u00e3o vieram amplamente em linha com as previs\\u00f5es, ajudando a conter uma queda de tr\\u00eas dias nos principais \\u00edndices. A recupera\\u00e7\\u00e3o seguiu leituras econ\\u00f4micas mais fortes do que o esperado no in\\u00edcio da semana, incluindo n\\u00fameros s\\u00f3lidos de empregos e uma\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/9-1-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#mainImage\",\"width\":2560,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\\\/#mainImage\"},\"datePublished\":\"2025-09-29T11:14:18+00:00\",\"dateModified\":\"2025-09-29T11:14:24+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX","description":"Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma","canonical_url":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#blogposting","name":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX","headline":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/9-1-scaled.jpg","width":2560,"height":1280},"datePublished":"2025-09-29T11:14:18+00:00","dateModified":"2025-09-29T11:14:24+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#webpage"},"articleSection":"IX Daily, IX Intel, Not\u00edcias do mercado, Atualiza\u00e7\u00f5es de mercado, Not\u00edcias internacionais, O que h\u00e1 de novo, Portugu\u00eas, pll_68da678e89685"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","position":3,"name":"Pesquisa","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#listItem","name":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#listItem","position":5,"name":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/infinox\/","name":"INFINOX","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g","width":96,"height":96,"caption":"INFINOX"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#webpage","url":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/","name":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX","description":"Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/9-1-scaled.jpg","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#mainImage","width":2560,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/#mainImage"},"datePublished":"2025-09-29T11:14:18+00:00","dateModified":"2025-09-29T11:14:24+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX","og:description":"Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma","og:url":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/","article:published_time":"2025-09-29T11:14:18+00:00","article:modified_time":"2025-09-29T11:14:24+00:00","twitter:card":"summary_large_image","twitter:title":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana - INFINOX","twitter:description":"Wall Street conseguiu um rali de al\u00edvio na sexta-feira, j\u00e1 que os dados de infla\u00e7\u00e3o vieram amplamente em linha com as previs\u00f5es, ajudando a conter uma queda de tr\u00eas dias nos principais \u00edndices. A recupera\u00e7\u00e3o seguiu leituras econ\u00f4micas mais fortes do que o esperado no in\u00edcio da semana, incluindo n\u00fameros s\u00f3lidos de empregos e uma"},"aioseo_meta_data":{"post_id":"27562","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-29 11:13:28","updated":"2025-09-29 11:14:28"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/\" title=\"Pesquisa\">Pesquisa<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tA\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/"},{"label":"Pesquisa","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/"},{"label":"A\u00e7\u00f5es sobem com relat\u00f3rio do PCE, mas fraqueza da tecnologia pesa na semana","link":"https:\/\/www.infinox.com\/global\/pt\/acoes-sobem-com-relatorio-do-pce-mas-fraqueza-da-tecnologia-pesa-na-semana\/"}],"lang":"pt","translations":{"pt":27562,"vi":27555,"en":27551,"zh_cn":27558,"th":27564,"ko":27566,"zh_tw":27568,"es":27570,"jp":27572},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/27562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=27562"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/27562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/27552"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=27562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=27562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=27562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}