{"id":23896,"date":"2025-09-04T06:39:48","date_gmt":"2025-09-04T06:39:48","guid":{"rendered":"https:\/\/www.infinox.com\/global\/?p=23896"},"modified":"2025-09-04T06:39:54","modified_gmt":"2025-09-04T06:39:54","slug":"el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/","title":{"rendered":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias."},"content":{"rendered":"\n<p>Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo intacto, pero el sentimiento se mantuvo cauteloso antes del informe de empleos del viernes, tras una ca\u00edda en las ofertas de trabajo. Los rendimientos del Tesoro a largo plazo subieron brevemente antes de relajarse, mientras que la incertidumbre arancelaria persistente y la reputaci\u00f3n de septiembre como un mes dif\u00edcil para las acciones continuaron reduciendo el apetito por el riesgo. El Dow tuvo un desempe\u00f1o inferior dado su menor peso en tecnolog\u00eda, mientras que el S&amp;P 500 y el Nasdaq obtuvieron apoyo del complejo de IA; aun as\u00ed, las preocupaciones por una desaceleraci\u00f3n econ\u00f3mica y mayores costos de financiamiento limitaron el seguimiento.<\/p>\n\n\n\n<p>Puntos Clave:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Dow cierra a la baja mientras energ\u00eda y bancos arrastran: El promedio industrial Dow Jones cay\u00f3 24.58 puntos, o un 0.05%, a 45,271.23, con p\u00e9rdidas en las acciones de bancos y productores de energ\u00eda contrarrestando leves ganancias en otros sectores.<\/li>\n\n\n\n<li>El S&amp;P 500 avanza gracias a la fortaleza de las grandes capitalizaciones: El S&amp;P 500 subi\u00f3 un 0,51% hasta los 6,448.26, recuper\u00e1ndose de la ca\u00edda del martes, ya que las ganancias en las acciones de crecimiento de gran peso superaron la presi\u00f3n de los sectores industriales y energ\u00e9ticos.<\/li>\n\n\n\n<li>El Nasdaq supera al alza con un auge tecnol\u00f3gico: El Nasdaq Composite subi\u00f3 un 1.03% hasta los 21,497.73, respaldado por fuertes repuntes en Alphabet y Apple. Las dos acciones a\u00f1adieron puntos significativos al \u00edndice mientras los operadores celebraban la claridad regulatoria.<\/li>\n\n\n\n<li>Los mercados europeos se recuperan con amplias ganancias: Las acciones europeas rebotaron despu\u00e9s de las p\u00e9rdidas de la sesi\u00f3n anterior, con el Stoxx 600 cerrando un 0,67% m\u00e1s alto en 546,79 y todas las principales bolsas avanzando. El FTSE 100 de Londres gan\u00f3 un 0,67%, el CAC 40 de Par\u00eds subi\u00f3 un 0,86% y el DAX de Alemania a\u00f1adi\u00f3 un 0,46%, mientras que el FTSE MIB de Italia solo logr\u00f3 un aumento moderado del 0,1%, ya que la atenci\u00f3n se mantuvo en el mercado de bonos tras ca\u00eddas acentuadas anteriormente. Los datos de la encuesta mostraron que el PMI compuesto de la eurozona subi\u00f3 a 51.0 desde 50.9, con nuevos pedidos aumentando por primera vez desde mayo de 2024, pero la demanda de exportaciones cay\u00f3 al ritmo m\u00e1s r\u00e1pido desde marzo. El \u00edndice de servicios de Espa\u00f1a se desaceler\u00f3 a 53.2 desde 55.1, aunque a\u00fan m\u00e1s fuerte que el 51.9 de junio y el 51.3 de mayo. Los servicios en Italia se redujeron a 51.5 desde 52.3, su lectura m\u00e1s d\u00e9bil desde enero, aunque la manufactura se expandi\u00f3 por primera vez en casi 18 meses, elevando el compuesto a 51.7. Aun as\u00ed, la econom\u00eda de Italia se contrajo el \u00faltimo trimestre y el gobierno recort\u00f3 su pron\u00f3stico de crecimiento para 2026 a solo 0.6%. Alemania fue el claro perdedor, con los servicios volviendo a la contracci\u00f3n en 49.3 desde 50.6, dejando el compuesto pr\u00e1cticamente sin cambios en 50.5.<\/li>\n\n\n\n<li>Los mercados asi\u00e1ticos fueron mixtos debido a las preocupaciones por los rendimientos y las tarifas: Las transacciones en la regi\u00f3n fueron desiguales, con la incertidumbre de las tarifas y los rendimientos globales m\u00e1s altos pesando en el sentimiento. El Hang Seng de Hong Kong cay\u00f3 un 0.6% a 25,343.43, mientras que el CSI 300 de China continental perdi\u00f3 un 0.68% a pesar de que el PMI de servicios aument\u00f3 a un m\u00e1ximo de 15 meses de 53.0. El Nikkei de Jap\u00f3n baj\u00f3 un 0.88% y el Topix se desliz\u00f3 un 1.07% a 3,048.89 a medida que los rendimientos de los JGB a largo plazo subieron. El rendimiento a 10 a\u00f1os subi\u00f3 3.3 puntos b\u00e1sicos a 1.636%, el de 20 a\u00f1os agreg\u00f3 5.5 puntos b\u00e1sicos a 2.686% (su nivel m\u00e1s alto en 26 a\u00f1os), y el de 30 a\u00f1os gan\u00f3 8.7 puntos b\u00e1sicos a 3.298% despu\u00e9s de alcanzar un m\u00e1ximo hist\u00f3rico intrad\u00eda. El ASX 200 de Australia cay\u00f3 un 1.82%, su peor ca\u00edda desde abril, con tecnolog\u00eda y bienes ra\u00edces liderando las p\u00e9rdidas, aunque el crecimiento del PIB del segundo trimestre se aceler\u00f3 a un 1.8% interanual, por encima de las previsiones. El Kospi de Corea del Sur subi\u00f3 un 0.38% y el Kosdaq un 0.35%, mientras que en India, el Nifty 50 agreg\u00f3 un 0.23% y el Sensex un 0.12% a medida que el PMI de servicios se dispar\u00f3 a 62.9, extendiendo la fortaleza en la demanda interna.<\/li>\n\n\n\n<li>Bajan el petr\u00f3leo antes de la reuni\u00f3n de la OPEP+: El Brent cay\u00f3 $1.64 o 2.37% a $67.50 y el WTI perdi\u00f3 $1.69 o 2.59% a $63.89 mientras los comerciantes se posicionan para la reuni\u00f3n del domingo de la OPEP+, donde los miembros pueden considerar aumentar a\u00fan m\u00e1s los objetivos de producci\u00f3n de octubre. Otro aumento acelerar\u00eda la eliminaci\u00f3n de restricciones anteriores, adem\u00e1s de los aumentos de 2.2 mb\/d de abril a septiembre y los 300 kb\/d adicionales de los Emiratos \u00c1rabes Unidos.<\/li>\n\n\n\n<li>Los rendimientos del Tesoro retroceden despu\u00e9s de un breve repunte de 30 a\u00f1os: los rendimientos a largo plazo disminuyeron despu\u00e9s de datos laborales suaves. El rendimiento del bono a 30 a\u00f1os toc\u00f3 brevemente el 5% durante la noche en medio de la incertidumbre sobre los aranceles y preocupaciones sobre la independencia de la Fed, luego cay\u00f3 8 puntos b\u00e1sicos al 4.899%. El rendimiento del bono a 10 a\u00f1os disminuy\u00f3 m\u00e1s de 7 puntos b\u00e1sicos al 4.219%. El retroceso reflej\u00f3 temores m\u00e1s moderados sobre la trayectoria de las tasas a medida que los indicadores de crecimiento se suavizaban de cara a los datos de n\u00f3minas del viernes.<\/li>\n\n\n\n<li>Las ofertas de empleo en EE. UU. disminuyen mientras la contrataci\u00f3n carece de impulso: Las ofertas de trabajo del informe JOLTS cayeron en 176,000 a 7.181 millones en julio (frente a los 7.378 millones esperados), mientras que la contrataci\u00f3n aument\u00f3 en 41,000 a 5.308 millones y los despidos aumentaron en 12,000 a 1.808 millones. Los economistas esperan una cifra de n\u00f3minas no agr\u00edcolas de alrededor de 75,000 en agosto despu\u00e9s de los 73,000 en julio, con el desempleo previsto en un aumento al 4.3%, lo que convierte al informe del viernes en la pr\u00f3xima prueba clave para el apetito por el riesgo.<\/li>\n<\/ul>\n\n\n\n<p>FX Hoy:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1964\" height=\"786\" src=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-3Sep25-2-8.png\" alt=\"\" class=\"wp-image-23897\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-3Sep25-2-8.png 1964w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-3Sep25-2-8-768x307.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-3Sep25-2-8-1536x615.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/Currency-Strenght-3Sep25-2-8-710x284.png 710w\" sizes=\"(max-width: 1964px) 100vw, 1964px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El EUR\/USD se mantiene estable mientras los compradores mantienen el soporte por encima de 1.1650: el EUR\/USD cerr\u00f3 en 1.1659, subiendo un 0.16% despu\u00e9s de operar entre 1.1659 y 1.1682, dejando el precio contenido dentro del corredor m\u00e1s amplio de 1.1600\u20131.1750. Los compradores han defendido repetidamente el \u00e1rea de 1.1600, haci\u00e9ndola un nivel de soporte firme, mientras que los repuntes se han detenido consistentemente por debajo de la resistencia de 1.1720\u20131.1750. La imagen m\u00e1s amplia sigue estando respaldada por m\u00ednimos m\u00e1s altos desde el m\u00ednimo de mayo en 1.1350. Para recuperar el impulso, el par necesita un cierre diario decisivo por encima de 1.1750, lo que reafirmar\u00eda el control alcista y abrir\u00eda espacio para m\u00e1s ganancias. Una ca\u00edda por debajo de 1.1600, sin embargo, cambiar\u00eda el enfoque a 1.1500 como el pr\u00f3ximo piso estructural y equilibrar\u00eda el sentimiento a favor de los vendedores.<\/li>\n\n\n\n<li>Rebote del GBP\/USD cuando la demanda reaparece cerca del soporte: El GBP\/USD finaliz\u00f3 en 1.3439, ganando un 0.32% despu\u00e9s de fluctuar entre 1.3332 y 1.3486, recuperando terreno tras la abrupta ca\u00edda de ayer. La demanda regres\u00f3 cerca de 1.3330, reforzando esa \u00e1rea como una base clave, con el precio continuando su comercio dentro de la zona de consolidaci\u00f3n m\u00e1s amplia de 1.3330\u20131.3550. La correcci\u00f3n a la baja desde el pico de julio en 1.3850 sigue pesando, con m\u00e1ximos m\u00e1s bajos desde mediados de agosto dejando el impulso fr\u00e1gil hasta que los compradores puedan romper la resistencia. Un cierre sostenido por encima de 1.3485 reabrir\u00eda 1.3550 y aliviar\u00eda la presi\u00f3n a corto plazo, mientras que una ca\u00edda por debajo de 1.3400 volver\u00eda a enfocar la atenci\u00f3n en 1.3330. Perder ese nivel podr\u00eda acelerar la baja hacia 1.3250, haciendo que las pr\u00f3ximas sesiones sean cr\u00edticas para determinar si los compradores pueden estabilizar la tendencia general.<\/li>\n\n\n\n<li>AUD\/USD avanza a medida que la recuperaci\u00f3n se extiende: AUD\/USD se estabiliz\u00f3 en 0.6541, con una subida del 0.33% despu\u00e9s de moverse entre 0.6502 y 0.6554, continuando con la recuperaci\u00f3n desde el m\u00ednimo de finales de agosto en 0.6420. El par ha recuperado las medias m\u00f3viles de 50 y 200 d\u00edas, lo que da m\u00e1s confianza a los compradores, y ahora se negocia en la mitad superior de la banda de consolidaci\u00f3n m\u00e1s amplia de 0.6400\u20130.6640. La resistencia en 0.6560\u20130.6600 ha demostrado ser dif\u00edcil de superar, pero un cierre por encima de esta zona se\u00f1alar\u00eda un renovado impulso alcista y abrir\u00eda la puerta para probar 0.6640. El soporte inicial se mantiene firme en 0.6500, con la media m\u00f3vil de 100 d\u00edas convergiendo alrededor de 0.6480 para proporcionar una segunda l\u00ednea de defensa.<\/li>\n\n\n\n<li>El USD\/JPY retrocede debido a que los repuntes se estancan: El USD\/JPY cerr\u00f3 en 148.14, bajando un 0.15% despu\u00e9s de haber operado entre 147.88 y 149.14, retrocediendo desde el rebote de ayer. El par ha estado fijado alrededor del nivel de 148 durante semanas, con intentos repetidos por encima de 149 que no lograron mantenerse, dejando la resistencia firmemente en su lugar. La recuperaci\u00f3n desde el m\u00ednimo de 144.50 en julio se detuvo poco antes de alcanzar 151, y una secuencia de m\u00e1ximos m\u00e1s bajos desde la semana pasada refleja un creciente agotamiento en el repunte. Los vendedores est\u00e1n comenzando a probar el lado bajista, aunque la demanda en las ca\u00eddas persiste cerca de 147.50. Un cierre diario por debajo de 147.80 ser\u00eda la primera se\u00f1al clara de tracci\u00f3n bajista, exponiendo 147.00 y luego la base de finales de agosto en 146.50. Para que los compradores recuperen el control, se necesita una ruptura limpia por encima de 149.20, lo que reabrir\u00eda el camino para volver a probar 150.<\/li>\n\n\n\n<li>El oro alcanza nuevos m\u00e1ximos hist\u00f3ricos a medida que se acelera la ruptura: el oro termin\u00f3 en $3,564, subiendo un 0.90% despu\u00e9s de negociarse entre $3,526 y un nuevo m\u00e1ximo hist\u00f3rico de $3,578, continuando su poderoso avance. La ruptura despu\u00e9s de meses de consolidaci\u00f3n ha llevado al metal a territorio inexplorado, con la resistencia previa en $3,450\u2013$3,500 ahora actuando como una fuerte zona de soporte para los compradores. El impulso sigue siendo firmemente alcista, con cierres sucesivos m\u00e1s altos reforzando la confianza, aunque la magnitud del rally deja espacio para pausas correctivas. El enfoque inmediato est\u00e1 en una ruptura clara a trav\u00e9s de $3,578, lo que desbloquear\u00eda el umbral psicol\u00f3gico de $3,600 como el pr\u00f3ximo objetivo. A la baja, el primer soporte se encuentra en $3,526, seguido por $3,500, donde se espera que la demanda resurja si los precios retroceden.<\/li>\n<\/ul>\n\n\n\n<p>Movimientos de Mercado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Alphabet se dispara gracias al alivio de una sentencia judicial: Alphabet subi\u00f3 un 9.1% despu\u00e9s de que un juez federal dictaminara que la empresa puede conservar su navegador Chrome, pero debe compartir datos y evitar acuerdos de b\u00fasqueda exclusivos.<\/li>\n\n\n\n<li>Apple sube gracias a la asociaci\u00f3n de b\u00fasqueda asegurada: Apple subi\u00f3 un 3.8% despu\u00e9s de que la sentencia le permitiera mantener Google Search como el motor de b\u00fasqueda predeterminado en los iPhones, un acuerdo valorado en aproximadamente $20 mil millones anuales.<\/li>\n\n\n\n<li>Macy\u2019s se dispara con s\u00f3lidos resultados del segundo trimestre: Macy\u2019s subi\u00f3 m\u00e1s del 20% despu\u00e9s de reportar ventas netas del segundo trimestre de $4.81 mil millones frente a los $4.71 mil millones esperados. El minorista tambi\u00e9n elev\u00f3 su gu\u00eda anual a $21.15\u2013$21.45 mil millones, se\u00f1alando una demanda del consumidor resiliente.<\/li>\n\n\n\n<li>Campbell Soup se dispara tras superar expectativas de ganancias: Campbell Soup avanz\u00f3 m\u00e1s del 7% despu\u00e9s de reportar un EPS ajustado de 62 centavos en el cuarto trimestre, superando las previsiones de 56 centavos.<\/li>\n\n\n\n<li>Bruker se desploma tras una oferta de acciones de $600 millones: Bruker cay\u00f3 m\u00e1s del 11% tras anunciar una venta p\u00fablica de acciones preferentes convertibles obligatorias, generando preocupaciones de diluci\u00f3n entre los accionistas.<\/li>\n<\/ul>\n\n\n\n<p>La \u00faltima sesi\u00f3n de Wall Street destac\u00f3 la creciente divergencia del mercado, con los grandes nombres de la tecnolog\u00eda avanzando mientras los sectores c\u00edclicos rezagaban bajo el peso de se\u00f1ales econ\u00f3micas m\u00e1s d\u00e9biles y la ca\u00edda del petr\u00f3leo. El repunte en Europa fue impulsado por la fortaleza corporativa, pero los datos regionales confirmaron que el crecimiento sigue siendo desigual, y los mercados asi\u00e1ticos mostraron la tensi\u00f3n de los rendimientos de bonos al alza. La hist\u00f3rica subida del oro subray\u00f3 la demanda de refugios seguros, mientras que la ca\u00edda del petr\u00f3leo reflej\u00f3 los riesgos de oferta que volvieron a un super\u00e1vit. Con los datos de empleo en EE.UU. programados para el viernes y los mercados de bonos ya vol\u00e1tiles, los inversores enfrentan una prueba cr\u00edtica que podr\u00eda determinar si septiembre cumple con su reputaci\u00f3n de ser un mes dif\u00edcil para las acciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo<a href=\"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":28,"featured_media":23882,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[878,172,896],"tags":[917,914,923],"class_list":["post-23896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-market-news","tag-market-updates","tag-international-news","tag-whats-new"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFINOX\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-09-04T06:39:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-09-04T06:39:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#blogposting\",\"name\":\"El rally tecnol\\u00f3gico liderado por Alphabet impulsa al S&P 500 y Nasdaq, mientras la cautela econ\\u00f3mica limita las ganancias. - INFINOX\",\"headline\":\"El rally tecnol\\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\\u00f3mica limita las ganancias.\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/21-scaled.jpg\",\"width\":2560,\"height\":1280},\"datePublished\":\"2025-09-04T06:39:48+00:00\",\"dateModified\":\"2025-09-04T06:39:54+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Noticias del mercado, Actualizaciones del mercado, Noticias internacionales, Novedades, Espa\\u00f1ol, pll_68b931998455d\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Investigaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Investigaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#listItem\",\"name\":\"El rally tecnol\\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\\u00f3mica limita las ganancias.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Investigaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#listItem\",\"position\":5,\"name\":\"El rally tecnol\\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\\u00f3mica limita las ganancias.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/\",\"name\":\"INFINOX\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"INFINOX\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/\",\"name\":\"El rally tecnol\\u00f3gico liderado por Alphabet impulsa al S&P 500 y Nasdaq, mientras la cautela econ\\u00f3mica limita las ganancias. - INFINOX\",\"description\":\"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\\u00eda de mega capitalizaci\\u00f3n compens\\u00f3 la debilidad en el sector de energ\\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\\u00e9s de un fallo antimonopolio favorable. Apple gan\\u00f3 terreno ya que su acuerdo de b\\u00fasqueda predeterminada en los iPhones se mantuvo\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/09\\\/21-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#mainImage\",\"width\":2560,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\\\/#mainImage\"},\"datePublished\":\"2025-09-04T06:39:48+00:00\",\"dateModified\":\"2025-09-04T06:39:54+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX","description":"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo","canonical_url":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#blogposting","name":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX","headline":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias.","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/21-scaled.jpg","width":2560,"height":1280},"datePublished":"2025-09-04T06:39:48+00:00","dateModified":"2025-09-04T06:39:54+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#webpage"},"articleSection":"IX Daily, IX Intel, Noticias del mercado, Actualizaciones del mercado, Noticias internacionales, Novedades, Espa\u00f1ol, pll_68b931998455d"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","name":"Investigaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","position":3,"name":"Investigaci\u00f3n","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#listItem","name":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","name":"Investigaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#listItem","position":5,"name":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/infinox\/","name":"INFINOX","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g","width":96,"height":96,"caption":"INFINOX"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#webpage","url":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/","name":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX","description":"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/09\/21-scaled.jpg","@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#mainImage","width":2560,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/#mainImage"},"datePublished":"2025-09-04T06:39:48+00:00","dateModified":"2025-09-04T06:39:54+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX","og:description":"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo","og:url":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/","article:published_time":"2025-09-04T06:39:48+00:00","article:modified_time":"2025-09-04T06:39:54+00:00","twitter:card":"summary_large_image","twitter:title":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias. - INFINOX","twitter:description":"Las acciones estadounidenses terminaron mixtas ya que un poderoso repunte en la tecnolog\u00eda de mega capitalizaci\u00f3n compens\u00f3 la debilidad en el sector de energ\u00eda y bancos, con un aumento de Alphabet marcando la pauta despu\u00e9s de un fallo antimonopolio favorable. Apple gan\u00f3 terreno ya que su acuerdo de b\u00fasqueda predeterminada en los iPhones se mantuvo"},"aioseo_meta_data":{"post_id":"23896","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-09-18 11:09:39","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-04 06:39:05","updated":"2025-09-18 11:09:39"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/\" title=\"Investigaci\u00f3n\">Investigaci\u00f3n<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tEl rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/"},{"label":"Investigaci\u00f3n","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/"},{"label":"El rally tecnol\u00f3gico liderado por Alphabet impulsa al S&amp;P 500 y Nasdaq, mientras la cautela econ\u00f3mica limita las ganancias.","link":"https:\/\/www.infinox.com\/global\/es\/el-rally-tecnologico-liderado-por-alphabet-impulsa-al-sp-500-y-nasdaq-mientras-la-cautela-economica-limita-las-ganancias\/"}],"lang":"es","translations":{"es":23896,"vi":23884,"en":23881,"zh_cn":23886,"pt":23888,"th":23890,"ko":23892,"zh_tw":23894,"jp":23898},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/23896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=23896"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/23896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/23882"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=23896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=23896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=23896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}