{"id":23290,"date":"2025-08-14T11:24:31","date_gmt":"2025-08-14T11:24:31","guid":{"rendered":"https:\/\/www.infinox.com\/global\/?p=23290"},"modified":"2025-08-14T11:24:55","modified_gmt":"2025-08-14T11:24:55","slug":"dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/","title":{"rendered":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde."},"content":{"rendered":"\n<p>O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta temporada de lucros do segundo trimestre e um renovado interesse em a\u00e7\u00f5es de empresas de menor capitaliza\u00e7\u00e3o, que devem se beneficiar dos custos de empr\u00e9stimos mais baixos. O sentimento positivo foi ainda refor\u00e7ado por um movimento acentuado nos mercados de criptomoedas, com o ether subindo mais de 5% e se aproximando de seu recorde de 2021 em meio ao aumento dos fluxos de entrada de ETFs e previs\u00f5es de longo prazo atualizadas. Os ganhos na Europa e na \u00c1sia refletiram o tom otimista, com os principais \u00edndices se aproximando de m\u00e1ximas de v\u00e1rias semanas, enquanto a libra atingiu um pico de tr\u00eas semanas em rela\u00e7\u00e3o ao d\u00f3lar devido \u00e0s expectativas divergentes de taxas de juros. As aten\u00e7\u00f5es agora se voltam para o relat\u00f3rio do \u00edndice de pre\u00e7os ao produtor dos EUA na quinta-feira, em busca de mais pistas sobre as tend\u00eancias da infla\u00e7\u00e3o antes do aguardado encontro de Jackson Hole do Federal Reserve ainda este m\u00eas.<\/p>\n\n\n\n<p>Principias Pontos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dow sobe pelo segundo dia: O \u00edndice Dow Jones Industrial Average subiu 463,66 pontos, ou 1,04%, fechando em 44.922,27, ampliando a alta de ter\u00e7a-feira ap\u00f3s dados de infla\u00e7\u00e3o dos EUA mais fracos do que o esperado fortalecerem as expectativas de um corte na taxa de juros pelo Federal Reserve em setembro. Os ganhos foram generalizados, com os investidores voltando-se para empresas de pequena capitaliza\u00e7\u00e3o, o que fez o \u00edndice Russell 2000 subir 2%.<\/li>\n\n\n\n<li>S&amp;P 500 Marca Outro Recorde de Fechamento: O S&amp;P 500 subiu 0,32% para 6.466,58, registrando seu segundo recorde consecutivo de fechamento com o apoio das a\u00e7\u00f5es de tecnologia. A AMD saltou 5,4%, a Apple ganhou 1,6% e a Paramount Skydance disparou 36,7%, ajudando a compensar a leve fraqueza em outros nomes megacap.<\/li>\n\n\n\n<li>Nasdaq Sobe para Novo Recorde: O \u00edndice Nasdaq Composite subiu 0,14%, fechando em 21.713,14, estabelecendo um novo recorde de fechamento pelo segundo dia consecutivo. O \u00edmpeto de negocia\u00e7\u00e3o diminuiu em compara\u00e7\u00e3o com a alta de ter\u00e7a-feira, mas os nomes ligados a semicondutores e IA permaneceram em foco.<\/li>\n\n\n\n<li>Mercados Europeus Continuam em Alta: O \u00edndice pan-europeu Stoxx 600 avan\u00e7ou 0,55%, acumula alta de 2,7% desde o in\u00edcio de agosto, \u00e0 medida que o sentimento melhorou junto com os recordes do mercado dos EUA. O FTSE 100 de Londres adicionou 17,42 pontos, ou 0,19%, para 9.165,23, enquanto o CAC 40 de Paris subiu 0,66%. O FTSE MIB de Mil\u00e3o subiu 0,6% para 42.186, e o DAX de Frankfurt ganhou 0,67%. A infla\u00e7\u00e3o espanhola subiu para 2,7% em julho, em compara\u00e7\u00e3o com 2,3% em junho, em linha com as previs\u00f5es, com a infla\u00e7\u00e3o subjacente tamb\u00e9m avan\u00e7ando. A libra esterlina atingiu $1,3585, seu ponto mais forte desde 25 de julho, \u00e0 medida que os investidores precificaram um ritmo mais lento de cortes da taxa de juros no Reino Unido em rela\u00e7\u00e3o aos EUA.<\/li>\n\n\n\n<li>Mercados da \u00c1sia acompanham ganhos de Wall Street: o Nikkei 225 do Jap\u00e3o disparou 1,3% para um recorde de 43.274,67, com o Topix subindo 0,83%. O Hang Seng de Hong Kong saltou 2,6% para uma m\u00e1xima de duas semanas de 25.614, marcando seu maior ganho di\u00e1rio desde meados de maio, enquanto o CSI 300 da China subiu 0,79% e o Composto de Xangai atingiu seu n\u00edvel intradi\u00e1rio mais alto desde dezembro de 2021. O Kospi da Coreia do Sul subiu 1,08%, o Kosdaq ganhou 0,86%, e o S&amp;P\/ASX 200 da Austr\u00e1lia caiu 0,6%.<\/li>\n\n\n\n<li>Pre\u00e7os do Petr\u00f3leo Caim devido ao Aumento de Estoques de Petr\u00f3leo Bruto dos EUA: O Brent caiu 0,74% para $65,63 por barril, e o WTI deslizou 0,82% para $62,65 ap\u00f3s os estoques de petr\u00f3leo bruto dos EUA aumentarem inesperadamente em 3 milh\u00f5es de barris na semana passada. As perdas foram limitadas enquanto os traders aguardavam uma reuni\u00e3o na sexta-feira entre o presidente dos EUA, Donald Trump, e o presidente russo, Vladimir Putin, onde san\u00e7\u00f5es energ\u00e9ticas poderiam ser discutidas.<\/li>\n\n\n\n<li>Os Rendimentos do Tesouro Caem \u00e0 Medida que a Infla\u00e7\u00e3o Arrefece: O rendimento do Tesouro dos EUA de 2 anos caiu 5 pontos base para 3,681%, o rendimento de 10 anos caiu 6 pontos base para 4,238%, e o rendimento de 30 anos diminuiu para 4,828% \u00e0 medida que os traders consideravam quase certa uma redu\u00e7\u00e3o da taxa pelo Federal Reserve em setembro.<\/li>\n\n\n\n<li>Ether Aproxima-se de Recorde de 2021: Ether subiu mais de 5%, alcan\u00e7ando $4.740,48, faltando menos de $200 para atingir seu recorde hist\u00f3rico de novembro de 2021, impulsionado por $1,5 bilh\u00e3o em entradas de ETFs at\u00e9 agora nesta semana. O Standard Chartered elevou sua meta de pre\u00e7o para o final do ano para $7.500 e projetou $25.000 at\u00e9 2028, citando a crescente demanda institucional.<\/li>\n<\/ul>\n\n\n\n<p>FX Hoje:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1964\" height=\"792\" src=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/08\/Currency-Strenght-13Aug25-12.png\" alt=\"\" class=\"wp-image-23291\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/08\/Currency-Strenght-13Aug25-12.png 1964w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/08\/Currency-Strenght-13Aug25-12-768x310.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/08\/Currency-Strenght-13Aug25-12-1536x619.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/08\/Currency-Strenght-13Aug25-12-710x286.png 710w\" sizes=\"(max-width: 1964px) 100vw, 1964px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>EUR\/USD se Mant\u00e9m Firme Acima de 1.1650 enquanto a Resist\u00eancia se Aproxima: O EUR\/USD fechou em 1.1700, alta de 0,21% ap\u00f3s negociar entre 1.1670 e 1.1730, estendendo a recupera\u00e7\u00e3o das m\u00ednimas do in\u00edcio de agosto perto de 1.1600. O par permanece apoiado por uma estrutura de alta em vigor desde a quebra de meados de abril, com todas as m\u00e9dias m\u00f3veis principais alinhadas para cima, a m\u00e9dia de 50 dias em 1.1621, a de 100 dias em 1.1427 e a de 200 dias em 1.0974. O momentum tem vindo a aumentar gradualmente, marcado por uma s\u00e9rie de m\u00ednimas mais altas, mas a zona de resist\u00eancia de 1.1750\u20131.1800 continua a limitar ganhos adicionais. Um fechamento decisivo acima desta faixa provavelmente dispararia um avan\u00e7o em dire\u00e7\u00e3o ao pico de junho pr\u00f3ximo de 1.1900, enquanto um deslize de volta abaixo de 1.1650 poderia mudar o pre\u00e7o para uma fase de consolida\u00e7\u00e3o mais ampla. A tend\u00eancia de curto prazo permanece otimista enquanto o par negocia acima da SMA de 50 dias.<\/li>\n\n\n\n<li>GBP\/USD Estende Rally Pr\u00f3ximo a 1,3600 enquanto Touros Mant\u00eam Controle: GBP\/USD terminou o dia a 1,3574, uma alta de 0,55%, ap\u00f3s avan\u00e7ar de 1,3492 para uma m\u00e1xima de 1,3585, marcando o terceiro ganho di\u00e1rio consecutivo. A quebra acima da m\u00e9dia m\u00f3vel simples de 50 dias em 1,3520 confirmou o renovado momentum de alta, com suporte adicional da m\u00e9dia m\u00f3vel de 100 dias em 1,3379 e da m\u00e9dia m\u00f3vel de 200 dias em 1,3002. O pre\u00e7o agora se aproxima do topo de seu intervalo de consolida\u00e7\u00e3o desde o in\u00edcio de junho, com resist\u00eancia chave em 1,3650\u20131,3700, \u00faltima testada em meados de julho. Um movimento sustentado acima de 1,3600 abriria caminho para um desafio \u00e0 m\u00e1xima de julho, enquanto uma queda abaixo de 1,3520 poderia convidar a uma retra\u00e7\u00e3o em dire\u00e7\u00e3o a 1,3450. No geral, a perspectiva permanece construtiva acima da m\u00e9dia m\u00f3vel de 50 dias, com quedas provavelmente atraindo compradores.<\/li>\n\n\n\n<li>EUR\/GBP desliza em dire\u00e7\u00e3o \u00e0 SMA de 50 dias enquanto vendedores testam suporte: EUR\/GBP caiu 0,32%, fechando em 0,8618 ap\u00f3s recuar de 0,8654 para finalizar na m\u00ednima da sess\u00e3o. O decl\u00ednio aproxima o par da SMA de 50 dias em 0,8604, um n\u00edvel testado pela \u00faltima vez no final de junho, enquanto a SMA de 100 dias em 0,8538 e a de 200 dias em 0,8434 permanecem bem abaixo como suporte de longo prazo. O pre\u00e7o enfraqueceu desde a alta no final de julho, perto de 0,8720, formando m\u00e1ximas mais baixas e sinalizando uma mudan\u00e7a de curto prazo no momentum a favor dos vendedores. Uma quebra abaixo de 0,8600 poderia abrir caminho para um recuo mais profundo em dire\u00e7\u00e3o a 0,8560\u20130,8550, enquanto a estabiliza\u00e7\u00e3o acima da SMA favoreceria uma recupera\u00e7\u00e3o em dire\u00e7\u00e3o a 0,8660 e potencialmente 0,8700.<\/li>\n\n\n\n<li>USD\/JPY Mant\u00e9m Faixa M\u00e9dia enquanto Momentum Estagna Abaixo de 148.50: O USD\/JPY caiu 0,27%, para 147,44, ap\u00f3s reverter de 148,17 para uma baixa de 147,09. O par continua a consolidar-se entre a SMA de 50 dias em 146,32 e a SMA de 200 dias em 149,29, ap\u00f3s a rejei\u00e7\u00e3o no final de julho perto de 150,00. Os vendedores t\u00eam defendido repetidamente a zona de 148,50, enquanto uma queda abaixo de 146,30 poderia expor 145,50 e 143,50. Um rompimento acima de 149,00 reenergizaria o momentum de alta e traria 150,00 de volta ao foco. Por enquanto, o com\u00e9rcio de faixa domina enquanto ambos os lados aguardam uma ruptura decisiva.<\/li>\n\n\n\n<li>O ouro se mant\u00e9m est\u00e1vel acima de $3.350 conforme a consolida\u00e7\u00e3o persiste: O ouro terminou a $3.358, com alta de 0,29%, ap\u00f3s oscilar entre $3.343 e $3.371, mantendo-se acima da m\u00e9dia m\u00f3vel simples de 50 dias em $3.349 para manter o momento altista de curto prazo intacto. O metal permanece suportado pela m\u00e9dia m\u00f3vel de 100 dias em $3.289 e pela de 200 dias em $3.022, com compradores defendendo repetidamente quedas na \u00e1rea de $3.340\u2013$3.350. A resist\u00eancia \u00e9 definida por $3.370 e pela zona mais ampla de $3.400\u2013$3.420, que limitou os ganhos em julho. Um fechamento acima de $3.370 poderia impulsionar um novo teste de $3.420, enquanto um movimento abaixo de $3.320 colocaria em risco uma queda em dire\u00e7\u00e3o a $3.290.<\/li>\n<\/ul>\n\n\n\n<p>Movimentos de Mercado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A Cisco cai ap\u00f3s pequena supera\u00e7\u00e3o e orienta\u00e7\u00e3o cautelosa: As a\u00e7\u00f5es ca\u00edram quase 3% ap\u00f3s o EPS ajustado de $0,99 em $14,67 bilh\u00f5es superar as previs\u00f5es por pouco, enquanto a orienta\u00e7\u00e3o apenas excedeu ligeiramente as expectativas.<\/li>\n\n\n\n<li>Queda das A\u00e7\u00f5es da Ibotta devido a Perspectiva Fraca: As a\u00e7\u00f5es despencaram mais de 21% j\u00e1 que o lucro por a\u00e7\u00e3o (EPS) no segundo trimestre foi de $0,08 comparado aos esperados $0,19, e a receita foi de $86 milh\u00f5es em compara\u00e7\u00e3o aos $90,5 milh\u00f5es esperados, com uma orienta\u00e7\u00e3o mais fraca para o terceiro trimestre aumentando a press\u00e3o.<\/li>\n\n\n\n<li>Coherent cai ao vender unidade Aeroespacial e de Defesa: A\u00e7\u00f5es ca\u00edram mais de 16% mesmo com EPS de $1,00 em $1,53 bilh\u00f5es, superando as estimativas; a empresa concordou em vender seu neg\u00f3cio aeroespacial e de defesa para a Advent por $400 milh\u00f5es.<\/li>\n\n\n\n<li>Ganhos Otimistas Ap\u00f3s Estreia no IPO: A troca de criptomoedas subiu mais de 3% ap\u00f3s o expediente; abriu a $90 na NYSE, 143% acima do pre\u00e7o de IPO de $37, e fechou a $68, com uma alta de quase 84% no primeiro dia.<\/li>\n\n\n\n<li>CoreWeave Cai por Perspectiva de Custos Elevados: CRWV caiu mais de 20% ap\u00f3s sinalizar custos de capital mais altos e margens mais estreitas que obscurecem a lucratividade de curto prazo.<\/li>\n\n\n\n<li>Hanesbrands dispara com acordo da Gildan; Gildan tamb\u00e9m sobe: HBI subiu 3,7% ap\u00f3s um aumento de 28% na ter\u00e7a-feira, quando uma compra de a\u00e7\u00f5es no valor de $2.2 bilh\u00f5es pela Gildan foi confirmada; GIL subiu 11,8% com o an\u00fancio.<\/li>\n\n\n\n<li>C3.ai se Recupera Apesar da Rebaixamento de Corretora: As a\u00e7\u00f5es da C3.ai subiram cerca de 10%, mesmo com a Oppenheimer rebaixando a classifica\u00e7\u00e3o para &#8220;desempenho de mercado&#8221; ap\u00f3s resultados preliminares fracos, com os investidores voltando a se interessar por nomes expostos \u00e0 IA.<\/li>\n\n\n\n<li>KinderCare cai devido \u00e0 menor inscri\u00e7\u00e3o e redu\u00e7\u00e3o na orienta\u00e7\u00e3o: KLC caiu 22% ap\u00f3s resultados decepcionantes no segundo trimestre e uma redu\u00e7\u00e3o na orienta\u00e7\u00e3o para o ano inteiro, devido a tend\u00eancias de inscri\u00e7\u00e3o mais fracas do que o esperado.<\/li>\n<\/ul>\n\n\n\n<p>O rally de Wall Street se estendeu para uma segunda sess\u00e3o na quarta-feira, impulsionado pela renovada convic\u00e7\u00e3o de que o Federal Reserve come\u00e7ar\u00e1 a cortar taxas j\u00e1 em setembro, juntamente com um fluxo constante de resultados corporativos resilientes. Ganhos na Europa e na \u00c1sia sublinharam a amplitude global do movimento, enquanto o avan\u00e7o da libra esterlina e a r\u00e1pida subida do \u00e9ter em dire\u00e7\u00e3o a territ\u00f3rios recordes destacaram a for\u00e7a em v\u00e1rias classes de ativos. Rendimentos mais baixos dos t\u00edtulos do Tesouro e leituras moderadas de infla\u00e7\u00e3o mantiveram o apetite por risco intacto, mesmo com a queda dos pre\u00e7os do petr\u00f3leo devido a um inesperado aumento dos estoques de petr\u00f3leo bruto dos EUA. Com o \u00edndice de pre\u00e7os ao produtor dos EUA previsto para quinta-feira e o simp\u00f3sio de Jackson Hole se aproximando, os investidores est\u00e3o prontos para avaliar se esse \u00edmpeto otimista pode ser sustentado nas semanas finais do ver\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta<a href=\"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":28,"featured_media":23284,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[530,30,548],"tags":[3564,3565,3568],"class_list":["post-23290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-market-news","tag-atualizacoes-de-mercado","tag-mercados-financeiros-26","tag-noticias-internacionais-16"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFINOX\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-14T11:24:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-14T11:24:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#blogposting\",\"name\":\"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX\",\"headline\":\"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde.\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/08\\\/27-scaled.jpg\",\"width\":2560,\"height\":1280},\"datePublished\":\"2025-08-14T11:24:31+00:00\",\"dateModified\":\"2025-08-14T11:24:55+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Not\\u00edcias do mercado, Atualiza\\u00e7\\u00f5es de mercado, mercados financeiros, Not\\u00edcias internacionais, Portugu\\u00eas, pll_689dc2775ed54\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Pesquisa\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#listItem\",\"name\":\"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#listItem\",\"position\":5,\"name\":\"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/\",\"name\":\"INFINOX\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"INFINOX\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/\",\"name\":\"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX\",\"description\":\"O \\u00cdndice Industrial Dow Jones disparou pela segunda sess\\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\\u00e7\\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\\u00e7\\u00f5es globais. O avan\\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/08\\\/27-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#mainImage\",\"width\":2560,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\\\/#mainImage\"},\"datePublished\":\"2025-08-14T11:24:31+00:00\",\"dateModified\":\"2025-08-14T11:24:55+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX","description":"O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta","canonical_url":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#blogposting","name":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX","headline":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde.","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/08\/27-scaled.jpg","width":2560,"height":1280},"datePublished":"2025-08-14T11:24:31+00:00","dateModified":"2025-08-14T11:24:55+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#webpage"},"articleSection":"IX Daily, IX Intel, Not\u00edcias do mercado, Atualiza\u00e7\u00f5es de mercado, mercados financeiros, Not\u00edcias internacionais, Portugu\u00eas, pll_689dc2775ed54"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","position":3,"name":"Pesquisa","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#listItem","name":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#listItem","position":5,"name":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/infinox\/","name":"INFINOX","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g","width":96,"height":96,"caption":"INFINOX"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#webpage","url":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/","name":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX","description":"O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/08\/27-scaled.jpg","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#mainImage","width":2560,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/#mainImage"},"datePublished":"2025-08-14T11:24:31+00:00","dateModified":"2025-08-14T11:24:55+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX","og:description":"O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta","og:url":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/","article:published_time":"2025-08-14T11:24:31+00:00","article:modified_time":"2025-08-14T11:24:55+00:00","twitter:card":"summary_large_image","twitter:title":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde. - INFINOX","twitter:description":"O \u00cdndice Industrial Dow Jones disparou pela segunda sess\u00e3o consecutiva nesta quarta-feira, subindo mais de 460 pontos, impulsionado pelo otimismo em rela\u00e7\u00e3o aos cortes iminentes nas taxas de juros dos EUA, que alimentou uma nova alta nas a\u00e7\u00f5es globais. O avan\u00e7o de Wall Street foi apoiado por fortes ganhos no setor de tecnologia, uma robusta"},"aioseo_meta_data":{"post_id":"23290","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-09-18 12:09:23","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-08-14 11:24:37","updated":"2025-09-18 12:09:23"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/\" title=\"Pesquisa\">Pesquisa<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tDow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/"},{"label":"Pesquisa","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/"},{"label":"Dow estende rali enquanto apostas em cortes de juros impulsionam ganhos no mercado global e Ether se aproxima de recorde.","link":"https:\/\/www.infinox.com\/global\/pt\/dow-estende-rali-enquanto-apostas-em-cortes-de-juros-impulsionam-ganhos-no-mercado-global-e-ether-se-aproxima-de-recorde\/"}],"lang":"pt","translations":{"pt":23290,"vi":23286,"en":23283,"zh_cn":23288,"th":23292,"ko":23294,"zh_tw":23297,"es":23299,"jp":23301},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/23290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=23290"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/23290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/23284"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=23290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=23290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=23290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}