{"id":21757,"date":"2025-06-12T07:58:06","date_gmt":"2025-06-12T07:58:06","guid":{"rendered":"https:\/\/www.infinox.com\/global\/?p=21757"},"modified":"2025-06-12T07:58:15","modified_gmt":"2025-06-12T07:58:15","slug":"la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/","title":{"rendered":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado."},"content":{"rendered":"\n<p>Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El S&amp;P 500 baj\u00f3 ligeramente, mientras que el Dow se mantuvo pr\u00e1cticamente sin cambios, y el Nasdaq tuvo un rendimiento inferior, arrastrado por las acciones de semiconductores. Los precios al consumidor subieron solo un 0,1% en mayo, lo que alivi\u00f3 las preocupaciones sobre una inflaci\u00f3n impulsada por los aranceles, mientras que los desarrollos comerciales mostraron progreso pero segu\u00edan incompletos. El sentimiento fue puesto a prueba adem\u00e1s por el aumento de los riesgos geopol\u00edticos en el Medio Oriente, lo que impuls\u00f3 un aumento en los precios del petr\u00f3leo.<\/p>\n\n\n\n<p>Puntos Clave:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Dow Jones termina plano a pesar del optimismo comercial: El promedio industrial Dow Jones permaneci\u00f3 pr\u00e1cticamente sin cambios, cayendo solo 1.1 puntos para cerrar en 42,865.77. Los comerciantes dejaron de lado el entusiasmo inicial sobre el marco comercial entre Estados Unidos y China mientras esperaban la confirmaci\u00f3n de ambos presidentes.<\/li>\n\n\n\n<li>El S&amp;P 500 rompe su racha ganadora ante se\u00f1ales mixtas: El S&amp;P 500 cay\u00f3 un 0,27% para finalizar en 6,022.24, deteniendo un rally de tres d\u00edas. Los datos del IPC m\u00e1s d\u00e9biles de lo esperado calmaron los temores de inflaci\u00f3n, pero los inversores contin\u00faan mostrando cautela.<\/li>\n\n\n\n<li>El Nasdaq cae mientras las acciones de chips se desploman: El Nasdaq Composite baj\u00f3 un 0.5% a 19,615.88, presionado por una debilidad generalizada en las acciones de semiconductores. Intel lider\u00f3 las p\u00e9rdidas, cayendo m\u00e1s del 6%, mientras que AMD, Marvell y Texas Instruments tambi\u00e9n registraron descensos.<\/li>\n\n\n\n<li>Europa mixta mientras Londres alcanza un r\u00e9cord hist\u00f3rico: Los mercados europeos terminaron una sesi\u00f3n vol\u00e1til mayormente a la baja el mi\u00e9rcoles mientras los inversores diger\u00edan los primeros contornos del acuerdo comercial entre Estados Unidos y China junto con los desarrollos regionales. El Stoxx 600 paneuropeo cay\u00f3 un 0,19%, con el DAX de Alemania bajando aproximadamente un 0,2% a 23,976 y el CAC 40 de Francia descendiendo 40 puntos, o un 0,52%. El FTSE MIB de Italia baj\u00f3 ligeramente, cerrando cerca de 40,180 mientras los inversores evaluaban las perspectivas comerciales y los riesgos persistentes de inflaci\u00f3n. En contraste, el FTSE 100 del Reino Unido subi\u00f3 un 0,13% a 8,864.35, marcando su cierre m\u00e1s alto de la historia. Los constructores de viviendas cotizados en Londres extendieron su repunte por segundo d\u00eda despu\u00e9s de que el gobierno confirmara un aumento de \u00a339 mil millones para viviendas sociales y asequibles.<\/li>\n\n\n\n<li>Asia se recupera debido a un avance en el comercio y un cambio en las divisas: Las acciones de Asia-Pac\u00edfico subieron el mi\u00e9rcoles, ya que los mercados celebraron el progreso en el marco comercial entre Estados Unidos y China, y se\u00f1ales de un cambio regional que se aleja de la dependencia del d\u00f3lar. El \u00edndice CSI 300 de China avanz\u00f3 un 0,75% hasta los 3,894.63, y el Hang Seng de Hong Kong sum\u00f3 un 0,79%, impulsado por el optimismo en las aprobaciones de exportaci\u00f3n y la reducci\u00f3n de restricciones tecnol\u00f3gicas en el acuerdo propuesto. El Nikkei 225 de Jap\u00f3n gan\u00f3 un 0,55% hasta los 38,421.19, mientras que el Topix se mantuvo sin cambios. El Kospi de Corea del Sur salt\u00f3 un 1,23% hasta los 2,907.04, su nivel m\u00e1s alto desde enero de 2022, mientras que el Kosdaq de peque\u00f1a capitalizaci\u00f3n subi\u00f3 casi un 2%. El ASX 200 de Australia aument\u00f3 ligeramente en un 0,06% despu\u00e9s de alcanzar un nuevo m\u00e1ximo durante la sesi\u00f3n, y el Nifty 50 de India subi\u00f3 un 0,43%. Mientras tanto, la nueva estrategia econ\u00f3mica de la ASEAN para promover el comercio en moneda local a\u00f1adi\u00f3 \u00edmpetu, ya que los inversores dieron la bienvenida a un cambio en el enfoque de la pol\u00edtica monetaria regional. Los temas de desdolarizaci\u00f3n y el optimismo arancelario se combinaron para impulsar el apetito por el riesgo en todo el continente.<\/li>\n\n\n\n<li>El petr\u00f3leo sube m\u00e1s del 4% por la escalada en el Medio Oriente: Los precios del petr\u00f3leo se dispararon mientras aumentaban las tensiones en el Medio Oriente. El crudo WTI de EE. UU. subi\u00f3 $3.17, o un 4.9%, a $68.15 por barril, mientras que el Brent gan\u00f3 un 4.3% para cerrar en $69.77. EE. UU. autoriz\u00f3 evacuaciones parciales de su embajada en Irak, y los funcionarios de defensa de Ir\u00e1n emitieron fuertes advertencias. Los temores a interrupciones en el suministro impulsaron la subida en los mercados energ\u00e9ticos.<\/li>\n\n\n\n<li>Los rendimientos del Tesoro caen debido a un IPC moderado y una subasta fuerte: El rendimiento del bono del Tesoro a 10 a\u00f1os cay\u00f3 6 puntos b\u00e1sicos hasta el 4.12% despu\u00e9s de que los datos de inflaci\u00f3n fueran inferiores a las expectativas. El rendimiento a 2 a\u00f1os tambi\u00e9n se redujo a 3.947%, mientras que el rendimiento a 30 a\u00f1os baj\u00f3 a 4.926%. Una subasta de $39 mil millones de bonos a 10 a\u00f1os fue bien recibida, lo que indica una s\u00f3lida demanda a pesar de las preocupaciones sobre la pol\u00edtica fiscal. Los datos de inflaci\u00f3n m\u00e1s suaves aumentaron las apuestas del mercado sobre posibles recortes de tasas por parte de la Fed m\u00e1s adelante este a\u00f1o.<\/li>\n\n\n\n<li>La inflaci\u00f3n en EE.UU. sube menos de lo esperado en mayo: El IPC de EE.UU. aument\u00f3 un 0.1% en mayo, por debajo del 0.2% pronosticado, y el IPC subyacente tambi\u00e9n aument\u00f3 solo un 0.1%. En t\u00e9rminos anuales, la inflaci\u00f3n general se mantuvo en 2.4%, mientras que la subyacente subi\u00f3 a 2.8%, ambas ligeramente por debajo de las estimaciones. La ca\u00edda en los precios de la gasolina y los veh\u00edculos compens\u00f3 los aumentos en refugio y alimentos. Los ingresos reales promedio por hora aumentaron un 0.3% mes a mes y un 1.4% a\u00f1o tras a\u00f1o, reflejando presiones salariales limitadas.<\/li>\n<\/ul>\n\n\n\n<p>FX Hoy:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1962\" height=\"786\" src=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/06\/Currency-Strenght-12Jun25-7.png\" alt=\"\" class=\"wp-image-21758\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/06\/Currency-Strenght-12Jun25-7.png 1962w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/06\/Currency-Strenght-12Jun25-7-768x308.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/06\/Currency-Strenght-12Jun25-7-1536x615.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/06\/Currency-Strenght-12Jun25-7-710x284.png 710w\" sizes=\"(max-width: 1962px) 100vw, 1962px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>EUR\/USD Extiende el Rally Hacia el 1.1500: El EUR\/USD cerr\u00f3 en 1.1486 tras subir un 0.57% el mi\u00e9rcoles, marcando su quinta ganancia diaria consecutiva. El par toc\u00f3 brevemente un m\u00e1ximo intrad\u00eda de 1.1499 antes de retroceder ligeramente. La acci\u00f3n del precio se mantuvo alcista, con m\u00e1ximos m\u00e1s altos y m\u00ednimos m\u00e1s altos en las sesiones recientes, y todas las medias m\u00f3viles principales inclinadas hacia arriba por debajo del precio actual. La media m\u00f3vil simple (SMA) de 50 d\u00edas se encuentra en 1.1294, mientras que las SMAs de 100 y 200 d\u00edas est\u00e1n en 1.0948 y 1.0826 respectivamente. El reciente repunte comenz\u00f3 despu\u00e9s de una ruptura por encima de 1.1150 a principios de junio, y no ha habido una correcci\u00f3n significativa desde entonces. La estructura t\u00e9cnica sigue siendo firmemente alcista, con un soporte a corto plazo visto en 1.1420\u20131.1440. Una ruptura decisiva por encima de 1.1500 abrir\u00eda la puerta a un nuevo tramo al alza, sin una resistencia importante por delante.<\/li>\n\n\n\n<li>GBP\/USD se mantiene firme por encima de 1.3500: GBP\/USD gan\u00f3 un 0.34% para cerrar en 1.3543 despu\u00e9s de alcanzar un m\u00e1ximo intrad\u00eda de 1.3567. A pesar del aumento, el par se mantuvo apenas por debajo del pico del lunes en 1.3573. Este fue el tercer cierre diario consecutivo por encima del nivel de 1.3500, indicando una fuerza continua. La SMA de 50 d\u00edas est\u00e1 en 1.3312, y las SMAs de 100 y 200 d\u00edas est\u00e1n posicionadas en 1.3009 y 1.2916, todas en tendencia ascendente. El precio se mantiene en la mitad superior de un canal ascendente que comenz\u00f3 a mediados de abril, con m\u00ednimos intrad\u00eda que se mantienen repetidamente por encima de 1.3460. Los compradores han defendido consistentemente esa zona y ninguna acci\u00f3n del precio ha probado por debajo de 1.3400 esta semana. Un cierre por encima de 1.3573 confirmar\u00eda la continuaci\u00f3n de la actual subida, mientras que el rango de 1.3460\u20131.3570 sigue siendo una zona clave de consolidaci\u00f3n.<\/li>\n\n\n\n<li>El USD\/JPY cae mientras el impulso de recuperaci\u00f3n se desvanece: El USD\/JPY cay\u00f3 un 0.20% el mi\u00e9rcoles, finalizando la sesi\u00f3n en 144.58 despu\u00e9s de haber alcanzado un m\u00e1ximo de 145.464 m\u00e1s temprano en el d\u00eda. El par form\u00f3 una vela de cuerpo peque\u00f1o con una mecha superior m\u00e1s larga, reflejando presi\u00f3n de venta cerca de la resistencia a corto plazo. La media m\u00f3vil simple (SMA) de 50 d\u00edas se encuentra cerca del cierre del mi\u00e9rcoles en 144.22, mientras que las SMAs de 100 y 200 d\u00edas est\u00e1n en 147.58 y 149.38, respectivamente. A pesar de m\u00faltiples intentos, el precio no ha logrado retomar la media de 100 d\u00edas desde principios de abril, y los repuntes hacia ese nivel han encontrado una oferta constante. La tendencia general sigue siendo bajista, con el par a\u00fan descendiendo desde el pico de abril cerca de 157.50. La resistencia inmediata ahora se observa en 145.50, mientras que el l\u00edmite inferior del rango actual se sit\u00faa alrededor de 143.20. A menos que el precio rompa cualquiera de estos l\u00edmites, el par permanece sin direcci\u00f3n y atrapado dentro de medias m\u00f3viles convergentes.<\/li>\n\n\n\n<li>El oro se acerca a los m\u00e1ximos del rango en $3,360: El oro se estableci\u00f3 en $3,353, subiendo un 0,92%, construyendo un soporte a partir del SMA de 50 d\u00edas en ascenso, que se encuentra en $3,269. El metal precioso mostr\u00f3 una fuerte vela alcista despu\u00e9s de dos sesiones de consolidaci\u00f3n lateral, avanzando nuevamente hacia la resistencia alrededor de los $3,360. La tendencia general se mantiene al alza, respaldada por el SMA de 100 d\u00edas en $3,088 y el de 200 d\u00edas en $2,862. El rally mantiene al oro dentro de su rango m\u00e1s amplio entre $3,300 y $3,425, con el precio a\u00fan limitado por los m\u00e1ximos del mes pasado. Los compradores contin\u00faan defendiendo las ca\u00eddas hacia la zona de $3,300, con mayor soporte por debajo en el promedio de 50 d\u00edas. Una ruptura por encima de $3,425 confirmar\u00eda la continuaci\u00f3n alcista, mientras que un cierre por debajo de $3,269 podr\u00eda abrir una baja hacia $3,100. Por ahora, el impulso sigue siendo positivo pero a\u00fan esperando un detonante de ruptura.<\/li>\n\n\n\n<li>Retiro de la plata despu\u00e9s de probar m\u00e1ximos de varios a\u00f1os: La plata disminuy\u00f3 un 0,77% el mi\u00e9rcoles, cerrando en $36,25, retrocediendo despu\u00e9s de tocar un m\u00e1ximo intrad\u00eda de $36,64. La sesi\u00f3n form\u00f3 una vela de cuerpo peque\u00f1o con una notable mecha superior, indicando resistencia cerca de los m\u00e1ximos recientes. A pesar del retroceso, el metal se mantiene firmemente por encima de todas las medias m\u00f3viles clave, con la SMA de 50 d\u00edas en $32,99, la de 100 d\u00edas en $32,64 y la de 200 d\u00edas en $31,74, todas en tendencia alcista. La resistencia a corto plazo est\u00e1 ahora firmemente establecida alrededor de $36,64, con el soporte visto cerca de $35,50. Aunque el impulso parece estar enfri\u00e1ndose, la tendencia general sigue intacta a menos que el precio cierre por debajo de $34,60 o rompa la media ascendente de 50 d\u00edas.<\/li>\n<\/ul>\n\n\n\n<p>Movimientos de Mercado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Intel lidera las ca\u00eddas tecnol\u00f3gicas mientras las acciones de chips se deslizan: Las acciones de Intel cayeron m\u00e1s del 6%, arrastrando al S&amp;P 500 y al Nasdaq 100 en medio de una debilidad generalizada en el sector de semiconductores. ON Semiconductor y GlobalFoundries perdieron cada una m\u00e1s del 2%, mientras que AMD, Texas Instruments y Marvell Technology cayeron m\u00e1s del 1%, afectando el sentimiento en el sector tecnol\u00f3gico.<\/li>\n\n\n\n<li>Las acer\u00edas caen ante la especulaci\u00f3n de reducci\u00f3n de aranceles: Cleveland-Cliffs cay\u00f3 m\u00e1s del 8% y Nucor se hundi\u00f3 m\u00e1s del 6% despu\u00e9s de informes de que Estados Unidos y M\u00e9xico est\u00e1n cerca de un acuerdo para levantar aranceles sobre algunas importaciones de acero. Steel Dynamics y Commercial Metals tambi\u00e9n registraron una ca\u00edda de m\u00e1s del 2%.<\/li>\n\n\n\n<li>La empresa American Superconductor cae por la venta de acciones con descuento: Las acciones de American Superconductor Corp se desplomaron m\u00e1s de un 14% despu\u00e9s de que la compa\u00f1\u00eda fijara el precio de una oferta p\u00fablica de acciones entre $28 y $29 por acci\u00f3n, muy por debajo del cierre del martes de $34.35.<\/li>\n\n\n\n<li>Chewy cae por debajo de las expectativas de margen en los resultados del primer trimestre: Las acciones de Chewy cayeron m\u00e1s del 11% despu\u00e9s de que la empresa reportara un margen bruto del primer trimestre del 29.6%, por debajo de las expectativas de los analistas de 29.9%.<\/li>\n\n\n\n<li>Gitlab se desploma por pron\u00f3stico de ingresos blandos: Gitlab cay\u00f3 m\u00e1s del 10% despu\u00e9s de proyectar ingresos para el segundo trimestre entre $226 millones y $227 millones, ligeramente por debajo de la estimaci\u00f3n de consenso de $227.1 millones.<\/li>\n<\/ul>\n\n\n\n<p>El entusiasmo de los inversores se enfri\u00f3 el mi\u00e9rcoles mientras los mercados diger\u00edan el marco preliminar del acuerdo comercial entre Estados Unidos y China y otro indicador moderado de inflaci\u00f3n. Aunque las acciones retrocedieron modestamente, la lectura m\u00e1s suave del IPC aument\u00f3 las esperanzas de posibles recortes de tasas m\u00e1s adelante en el a\u00f1o, ayudando a limitar las p\u00e9rdidas. Las acciones energ\u00e9ticas superaron debido al aumento de los precios del petr\u00f3leo, pero la debilidad en semiconductores, fabricantes de acero y aerol\u00edneas arrastr\u00f3 a los \u00edndices m\u00e1s amplios a la baja. Con el acuerdo comercial pendiente de aprobaci\u00f3n final y las tensiones geopol\u00edticas en aumento en el Medio Oriente, los mercados podr\u00edan permanecer vol\u00e1tiles en las pr\u00f3ximas sesiones. El foco ahora se desplaza a los pr\u00f3ximos datos econ\u00f3micos de EE. UU. y a la confirmaci\u00f3n oficial del acuerdo arancelario transpac\u00edfico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El<a href=\"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":28,"featured_media":21741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[878,172,896],"tags":[917,914,923],"class_list":["post-21757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-market-news","tag-market-updates","tag-international-news","tag-whats-new"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFINOX\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-06-12T07:58:06+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-06-12T07:58:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#blogposting\",\"name\":\"La inflaci\\u00f3n m\\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX\",\"headline\":\"La inflaci\\u00f3n m\\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado.\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/06\\\/12jun25-scaled.jpg\",\"width\":2560,\"height\":1280},\"datePublished\":\"2025-06-12T07:58:06+00:00\",\"dateModified\":\"2025-06-12T07:58:15+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Noticias del mercado, Actualizaciones del mercado, Noticias internacionales, Novedades, Espa\\u00f1ol, pll_684a85553d325\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Investigaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Investigaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#listItem\",\"name\":\"La inflaci\\u00f3n m\\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Investigaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#listItem\",\"position\":5,\"name\":\"La inflaci\\u00f3n m\\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/\",\"name\":\"INFINOX\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"INFINOX\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/\",\"name\":\"La inflaci\\u00f3n m\\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX\",\"description\":\"Los mercados se enfriaron el mi\\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\\u00f3n m\\u00e1s bajos de lo esperado. Despu\\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \\u00edndices clave se manten\\u00edan cerca de los niveles de cierre anteriores. El\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/06\\\/12jun25-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#mainImage\",\"width\":2560,\"height\":1280},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\\\/#mainImage\"},\"datePublished\":\"2025-06-12T07:58:06+00:00\",\"dateModified\":\"2025-06-12T07:58:15+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX","description":"Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El","canonical_url":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#blogposting","name":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX","headline":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado.","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/06\/12jun25-scaled.jpg","width":2560,"height":1280},"datePublished":"2025-06-12T07:58:06+00:00","dateModified":"2025-06-12T07:58:15+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#webpage"},"articleSection":"IX Daily, IX Intel, Noticias del mercado, Actualizaciones del mercado, Noticias internacionales, Novedades, Espa\u00f1ol, pll_684a85553d325"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","name":"Investigaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","position":3,"name":"Investigaci\u00f3n","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#listItem","name":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","name":"Investigaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#listItem","position":5,"name":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/infinox\/","name":"INFINOX","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g","width":96,"height":96,"caption":"INFINOX"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#webpage","url":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/","name":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX","description":"Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/06\/12jun25-scaled.jpg","@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#mainImage","width":2560,"height":1280},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/#mainImage"},"datePublished":"2025-06-12T07:58:06+00:00","dateModified":"2025-06-12T07:58:15+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX","og:description":"Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El","og:url":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/","article:published_time":"2025-06-12T07:58:06+00:00","article:modified_time":"2025-06-12T07:58:15+00:00","twitter:card":"summary_large_image","twitter:title":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado. - INFINOX","twitter:description":"Los mercados se enfriaron el mi\u00e9rcoles mientras los inversores evaluaban un marco preliminar de comercio entre Estados Unidos y China y datos de inflaci\u00f3n m\u00e1s bajos de lo esperado. Despu\u00e9s de tres sesiones consecutivas de ganancias, las acciones hicieron una pausa mientras los \u00edndices clave se manten\u00edan cerca de los niveles de cierre anteriores. El"},"aioseo_meta_data":{"post_id":"21757","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-09-22 07:12:15","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-06-12 07:58:10","updated":"2025-09-22 07:12:15"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/\" title=\"Investigaci\u00f3n\">Investigaci\u00f3n<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tLa inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/"},{"label":"Investigaci\u00f3n","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/"},{"label":"La inflaci\u00f3n m\u00e1s moderada y la incertidumbre comercial detienen el impulso del mercado.","link":"https:\/\/www.infinox.com\/global\/es\/la-inflacion-mas-moderada-y-la-incertidumbre-comercial-detienen-el-impulso-del-mercado\/"}],"lang":"es","translations":{"es":21757,"zh_cn":21742,"en":21739,"zh_tw":21746,"vi":21748,"th":21750,"ko":21752,"pt":21755,"jp":21759},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/21757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=21757"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/21757\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/21741"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=21757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=21757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=21757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}