{"id":21178,"date":"2025-05-22T07:04:38","date_gmt":"2025-05-22T07:04:38","guid":{"rendered":"https:\/\/www.infinox.com\/global\/?p=21178"},"modified":"2025-05-22T07:04:45","modified_gmt":"2025-05-22T07:04:45","slug":"wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/","title":{"rendered":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo."},"content":{"rendered":"\n<p>Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&amp;P 500 y el Nasdaq tambi\u00e9n bajando despu\u00e9s de que una d\u00e9bil subasta de bonos a 20 a\u00f1os intensificara los temores sobre el apetito de los inversores por la deuda estadounidense. Los activos de riesgo enfrentaron una nueva presi\u00f3n ya que los rendimientos a largo plazo se dispararon a niveles no vistos desde octubre de 2023. A pesar del tono general de aversi\u00f3n al riesgo, el bitcoin salt\u00f3 por encima de los $109,000 durante el d\u00eda antes de recortar ganancias, impulsado por preocupaciones inflacionarias y un renovado inter\u00e9s en almacenes de valor alternativos. El d\u00eda marc\u00f3 una divisi\u00f3n vol\u00e1til en el sentimiento entre los mercados tradicionales y digitales.<\/p>\n\n\n\n<p>Puntos Clave:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El Dow sufre la mayor ca\u00edda desde marzo: El Promedio Industrial Dow Jones se desplom\u00f3 816.80 puntos, o un 1.91%, hasta los 41,860.44 el mi\u00e9rcoles, ya que el aumento de los rendimientos del Tesoro y las preocupaciones fiscales desencadenaron una venta masiva generalizada, marcando el peor d\u00eda del \u00edndice en m\u00e1s de dos meses.<\/li>\n\n\n\n<li>El S&amp;P 500 se desploma tras una fuerte racha: El S&amp;P 500 cay\u00f3 un 1,61% para finalizar en 5.844,61, poniendo fin a una reciente serie de sesiones fuertes. Las acciones tecnol\u00f3gicas sensibles a las tasas y las acciones de consumo lideraron las ca\u00eddas, con los inversores tomando ganancias despu\u00e9s de un rally del 13% durante el \u00faltimo mes.<\/li>\n\n\n\n<li>El Nasdaq retrocede mientras las acciones tecnol\u00f3gicas caen: El Nasdaq Composite cay\u00f3 un 1.41% hasta los 18,872.64, arrastrado por las p\u00e9rdidas en Apple, Amazon y otros grandes nombres tecnol\u00f3gicos. La retirada marc\u00f3 la segunda p\u00e9rdida diaria consecutiva del Nasdaq despu\u00e9s de una s\u00f3lida racha de varias semanas.<\/li>\n\n\n\n<li>Europa termina mixta mientras que las acciones alemanas superan: Los mercados europeos cerraron en general planos el mi\u00e9rcoles, manteni\u00e9ndose estables a pesar de la debilidad en las acciones estadounidenses. El \u00edndice paneuropeo Stoxx 600 baj\u00f3 solo un 0.04%. El DAX de Alemania se destac\u00f3, subiendo un 0.4% a un r\u00e9cord de 24,118, ya que las medidas de apoyo fiscal continuaron atrayendo capital. El FTSE 100 de Londres subi\u00f3 un 0.06% a 8,786.46, mientras que el FTSE MIB de Italia aument\u00f3 un 0.07%. El CAC 40 de Francia tuvo un rendimiento inferior, cayendo un 0.4% debido a la debilidad en los nombres de consumo y algunas tomas de ganancias. Mientras tanto, la inflaci\u00f3n brit\u00e1nica subi\u00f3 inesperadamente al 3.5% en abril, frente al 2.6% en marzo, impulsada por aumentos pronunciados en los precios de los servicios p\u00fablicos y del agua. La inflaci\u00f3n subyacente tambi\u00e9n aument\u00f3 al 3.8%.<\/li>\n\n\n\n<li>Asia sube a pesar de la debilidad de Jap\u00f3n y las preocupaciones comerciales: La mayor\u00eda de los principales mercados de Asia-Pac\u00edfico terminaron al alza, ignorando la pausa en el rally de Wall Street. Corea del Sur lider\u00f3 las ganancias, con el Kospi subiendo un 0,91% y el Kosdaq avanzando un 1,13%. El ASX 200 de Australia a\u00f1adi\u00f3 un 0,52%, y el Hang Seng de Hong Kong subi\u00f3 un 0,62%, con compras en acciones financieras e inmobiliarias que ayudaron a elevar el sentimiento. El CSI 300 de China continental gan\u00f3 un 0,47%, continuando su recuperaci\u00f3n a pesar de la incertidumbre comercial. El Banco de Indonesia entreg\u00f3 un sorpresivo recorte de la tasa al 5,5%, citando un d\u00e9bil crecimiento en el primer trimestre y un debilitamiento de la rupia. El Nikkei 225 de Jap\u00f3n fue la excepci\u00f3n, cayendo un 0,61% despu\u00e9s de que el crecimiento de las exportaciones se desacelerara por segundo mes consecutivo.<\/li>\n\n\n\n<li>El petr\u00f3leo cae por sorprendentes aumentos en los inventarios: Los precios del petr\u00f3leo bajaron despu\u00e9s de que la EIA informara aumentos inesperados en los inventarios de crudo y productos en EE. UU. antes de la temporada de conducci\u00f3n de verano. El Brent se estableci\u00f3 en $64.64, con una ca\u00edda del 1.13%, mientras que el WTI baj\u00f3 a $61.33. Las ganancias anteriores relacionadas con las tensiones en el Medio Oriente se desvanecieron ya que los datos de suministro bajistas y el aumento de la producci\u00f3n en EE. UU. pesaron en el mercado. Kazajist\u00e1n tambi\u00e9n desafi\u00f3 las expectativas de la OPEP+ aumentando su producci\u00f3n, lo que aument\u00f3 las preocupaciones sobre el exceso de oferta.<\/li>\n\n\n\n<li>Los rendimientos del Tesoro se disparan por temor al d\u00e9ficit y las subastas: Los rendimientos aumentaron ya que los inversores se pusieron nerviosos por los crecientes niveles de deuda de EE. UU. y la disminuci\u00f3n de la demanda de bonos a largo plazo. El rendimiento a 30 a\u00f1os salt\u00f3 al 5.08%, mientras que el de 10 a\u00f1os subi\u00f3 al 4.59%. Una mala subasta a 20 a\u00f1os gener\u00f3 alarmas sobre el apetito de los inversores por nuevas emisiones. Las tasas hipotecarias tambi\u00e9n aumentaron, con la media fija a 30 a\u00f1os alcanzando el 6.92%, la m\u00e1s alta desde febrero, lo que provoc\u00f3 una ca\u00edda del 5.1% en las solicitudes de pr\u00e9stamos hipotecarios.<\/li>\n\n\n\n<li>Bitcoin alcanza un nuevo m\u00e1ximo antes de recortar ganancias a medida que aumentan los rendimientos: El Bitcoin subi\u00f3 hasta un 3% intrad\u00eda para alcanzar un r\u00e9cord hist\u00f3rico de $109,857 el mi\u00e9rcoles antes de retroceder y estabilizarse alrededor de $106,678. El movimiento inicial fue impulsado por vientos de cola macroecon\u00f3micos favorables, incluidos datos de inflaci\u00f3n suave y la distensi\u00f3n en las tensiones comerciales entre Estados Unidos y China. Los operadores ahora miran hacia la volatilidad alrededor de la marca de $110,000, con soporte visto cerca de $103,000 y una demanda m\u00e1s fuerte probablemente cerca de la zona de consolidaci\u00f3n previa alrededor de $100,000.<\/li>\n<\/ul>\n\n\n\n<p>FX Hoy:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1962\" height=\"784\" src=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/05\/Currency-Strenght-22May25-7.png\" alt=\"\" class=\"wp-image-21179\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/05\/Currency-Strenght-22May25-7.png 1962w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/05\/Currency-Strenght-22May25-7-768x307.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/05\/Currency-Strenght-22May25-7-1536x614.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/05\/Currency-Strenght-22May25-7-710x284.png 710w\" sizes=\"(max-width: 1962px) 100vw, 1962px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>EUR\/USD Extiende el Rally a Medida que el Precio se Acerca a la Resistencia de Mediados de Mayo: EUR\/USD subi\u00f3 un 0.41% para finalizar en 1.1328, continuando su recuperaci\u00f3n de las p\u00e9rdidas anteriores de mayo y registrando su quinta ganancia en seis sesiones. El precio se mantiene c\u00f3modamente por encima de la SMA de 50 d\u00edas en 1.1130, que ayud\u00f3 a contener la \u00faltima correcci\u00f3n, mientras que las SMAs de 100 d\u00edas y 200 d\u00edas en 1.0789 y 1.0804, respectivamente, se inclinan hacia arriba y refuerzan la tendencia alcista m\u00e1s amplia. La pr\u00f3xima prueba t\u00e9cnica para los alcistas se encuentra entre 1.1370 y 1.1400, donde surgi\u00f3 presi\u00f3n de venta a principios de este mes. Una ruptura por encima de esta zona podr\u00eda abrir la puerta a una nueva prueba del m\u00e1ximo de abril cerca de 1.1500. A la baja, se observa soporte inmediato alrededor de 1.1250, seguido de una demanda m\u00e1s firme cerca de 1.1180 y la SMA de 50 d\u00edas. Mientras el par se mantenga por encima de la regi\u00f3n de 1.1100, la inclinaci\u00f3n de la tendencia sigue siendo alcista.<\/li>\n\n\n\n<li>GBP\/USD Sube Hacia 1.3450 a Medida que la Ruptura Alcista Gana Impulso: GBP\/USD subi\u00f3 un 0.24% para cerrar en 1.3425, registrando su cuarta ganancia en cinco sesiones mientras el par extend\u00eda su ascenso hacia una resistencia clave. Despu\u00e9s de pasar m\u00e1s de una semana consolid\u00e1ndose entre 1.3300 y 1.3400, el par avanz\u00f3, respaldado por una media m\u00f3vil simple (SMA) de 50 d\u00edas en fuerte ascenso a 1.3143. La estructura m\u00e1s amplia sigue siendo alcista, con las SMAs de 100 d\u00edas y 200 d\u00edas en 1.2829 y 1.2882 respectivamente, ambas inclinadas hacia arriba y bien por debajo del precio. GBP\/USD cerr\u00f3 justo por debajo de la zona de resistencia de 1.3450, y un movimiento sostenido por encima de ese nivel abrir\u00eda el camino hacia el pico de marzo cerca de 1.3550, seguido de 1.3600 y 1.3660. A la baja, se observa soporte en 1.3300, seguido por el \u00e1rea de 1.3150 alineada con la SMA de 50 d\u00edas.<\/li>\n\n\n\n<li>La reducci\u00f3n del USD\/JPY se intensifica bajo presi\u00f3n bajista: El USD\/JPY cay\u00f3 un 0,60% para cerrar en 143,62, marcando una quinta sesi\u00f3n consecutiva de descensos. Despu\u00e9s de repetidos fracasos en mantenerse por encima de 146,00 la semana pasada, el par ha roto niveles de soporte clave y contin\u00faa cotizando por debajo de todas las medias m\u00f3viles simples (SMA) principales. La SMA de 50 d\u00edas en 145,90 se ha inclinado hacia abajo, aline\u00e1ndose con las SMA de 100 d\u00edas y 200 d\u00edas en 149,55 y 149,54, respectivamente, lo que confirma un cambio en el sesgo a mediano plazo. El cierre del mi\u00e9rcoles se mantuvo justo por encima de 143,00, que previamente hab\u00eda actuado como soporte a principios de mayo. Una ruptura confirmada por debajo de este nivel podr\u00eda abrir un movimiento hacia 141,50 y posiblemente 140,00. A menos que los compradores recuperen la zona de 145,00 en un cierre, el camino de menor resistencia sigue siendo hacia abajo.<\/li>\n\n\n\n<li>El USD\/CAD ampl\u00eda sus p\u00e9rdidas a medida que persiste la presi\u00f3n a la baja: El USD\/CAD cay\u00f3 un 0.44% el mi\u00e9rcoles para cerrar en 1.3854, continuando su movimiento correctivo a la baja despu\u00e9s de no lograr recuperar el nivel de 1.4000. El par ha estado en un descenso constante desde que alcanz\u00f3 un pico por encima de 1.4200 en abril. La SMA de 50 d\u00edas en 1.4040 ha cambiado de direcci\u00f3n recientemente, mientras que las SMA de 100 d\u00edas y 200 d\u00edas en 1.4193 y 1.4015, respectivamente, se mantienen muy por encima de los niveles actuales, confirmando el cambio hacia una estructura bajista. Una ruptura por debajo de este nivel abrir\u00eda el camino hacia 1.3660, nivel visto por \u00faltima vez en marzo. La resistencia a\u00fan se define en 1.3950, con un techo m\u00e1s firme en el grupo de medias m\u00f3viles cerca de 1.4050.<\/li>\n\n\n\n<li>El oro sube hacia m\u00e1ximos recientes: El oro cerr\u00f3 a $3,319, ganando un 0.90% mientras el impulso alcista se extendi\u00f3 por segundo d\u00eda consecutivo. El metal recuper\u00f3 decisivamente la marca de $3,300, continuando su recuperaci\u00f3n desde la ca\u00edda de la semana pasada cerca de la media m\u00f3vil simple (SMA) de 50 d\u00edas en $3,184. Ahora, el oro se negocia muy por encima de las SMA de 100 y 200 d\u00edas, en $2,994 y $2,802 respectivamente, subrayando la fortaleza de la estructura a largo plazo. Los objetivos al alza emergen en $3,350, donde el mercado enfrent\u00f3 anteriormente toma de ganancias, y una ruptura por encima de esta zona podr\u00eda desencadenar un movimiento hacia el m\u00e1ximo de abril cerca de $3,500. A la baja, el soporte ha subido a $3,250, seguido por $3,200 y la SMA de 50 d\u00edas.<\/li>\n<\/ul>\n\n\n\n<p>Movimientos de Mercado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Target se desploma debido a una perspectiva d\u00e9bil y preocupaciones arancelarias: Target cay\u00f3 un 5.2% despu\u00e9s de recortar su pron\u00f3stico de ventas para todo el a\u00f1o, atribuyendo la disminuci\u00f3n a una demanda del consumidor m\u00e1s d\u00e9bil. La gerencia tambi\u00e9n mencion\u00f3 la incertidumbre relacionada con los aranceles y una reacci\u00f3n negativa a las iniciativas reducidas de inclusi\u00f3n.<\/li>\n\n\n\n<li>UnitedHealth lidera las ca\u00eddas del Dow despu\u00e9s de una degradaci\u00f3n: Las acciones de UnitedHealth se hundieron un 5.8% despu\u00e9s de que HSBC degradara la calificaci\u00f3n de la acci\u00f3n, advirtiendo sobre un riesgo continuo a la baja. La aseguradora ha perdido casi un 39% este a\u00f1o, presionada por la inflaci\u00f3n de costos y la incertidumbre pol\u00edtica.<\/li>\n\n\n\n<li>El ganso canadiense se dispara tras una sorpresa positiva: Canad\u00e1 Goose subi\u00f3 un 19.6% despu\u00e9s de informar ganancias del cuarto trimestre mejores de lo esperado, impulsadas por la demanda internacional. La administraci\u00f3n retuvo la orientaci\u00f3n fiscal para 2026 debido a la incertidumbre macroecon\u00f3mica.<\/li>\n\n\n\n<li>Xpeng se dispara por una p\u00e9rdida menor de lo esperado: Xpeng subi\u00f3 un 13% despu\u00e9s de reportar una p\u00e9rdida m\u00e1s reducida en el primer trimestre, lo que alivi\u00f3 las preocupaciones de los inversores. El fabricante de veh\u00edculos el\u00e9ctricos proyect\u00f3 entregas entre 102,000 y 108,000 para el segundo trimestre. Esto representar\u00eda un aumento interanual de m\u00e1s del 200%.<\/li>\n\n\n\n<li>Take-Two cae debido a una oferta de acciones de $1 mil millones: Take-Two Interactive cay\u00f3 un 4.5% despu\u00e9s de anunciar planes para recaudar $1 mil millones a trav\u00e9s de una oferta p\u00fablica de acciones. JPMorgan y Goldman Sachs liderar\u00e1n la transacci\u00f3n. La medida gener\u00f3 preocupaciones sobre la diluci\u00f3n a pesar del s\u00f3lido cat\u00e1logo de juegos de la compa\u00f1\u00eda.<\/li>\n\n\n\n<li>Modine Manufacturing cae a pesar de superar las expectativas de ganancias: Las acciones de Modine cayeron un 11,7% a pesar de haber superado las estimaciones de ganancias y ingresos del cuarto trimestre. Los inversionistas parecen estar preocupados por la sostenibilidad del crecimiento futuro. La toma de ganancias tambi\u00e9n influy\u00f3 despu\u00e9s del reciente rendimiento destacado de la acci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>La fuerte ca\u00edda del mi\u00e9rcoles destac\u00f3 la renovada tensi\u00f3n entre los riesgos de pol\u00edtica fiscal y la confianza de los inversores, con el aumento de los rendimientos de los bonos reavivando los temores sobre la sostenibilidad de la deuda de Estados Unidos. La venta masiva borr\u00f3 las recientes ganancias en acciones, particularmente en tecnolog\u00eda y salud, ya que el aumento de los costos de financiamiento presion\u00f3 las valorizaciones. Los mercados en el extranjero se mantuvieron mejor, impulsados por la fortaleza corporativa y el est\u00edmulo regional, a pesar de que los riesgos de inflaci\u00f3n y comercio se cern\u00edan. Mientras que el oro extendi\u00f3 su repunte por la demanda de refugio seguro, el petr\u00f3leo retrocedi\u00f3 debido a preocupaciones sobre el exceso de oferta. Con la atenci\u00f3n ahora en el desarrollo de la reforma fiscal y m\u00e1s datos econ\u00f3micos, los mercados enfrentan una prueba clave al navegar por las tasas en aumento y el sentimiento fr\u00e1gil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&amp;P 500<a href=\"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":28,"featured_media":21165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[878,172,896],"tags":[917,923],"class_list":["post-21178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-market-news","tag-market-updates","tag-whats-new"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&amp;P 500\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFINOX\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&amp;P 500\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-22T07:04:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-05-22T07:04:45+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&amp;P 500\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#blogposting\",\"name\":\"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\\u00e9cord m\\u00e1ximo. - INFINOX\",\"headline\":\"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\\u00e9cord m\\u00e1ximo.\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/Wall-Street-Sinks-Bitcoin-ATH-1.png\",\"width\":1792,\"height\":1024},\"datePublished\":\"2025-05-22T07:04:38+00:00\",\"dateModified\":\"2025-05-22T07:04:45+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Noticias del mercado, Actualizaciones del mercado, Novedades, Espa\\u00f1ol, pll_682ec7ef34c0b\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Investigaci\\u00f3n\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Investigaci\\u00f3n\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#listItem\",\"name\":\"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\\u00e9cord m\\u00e1ximo.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Investigaci\\u00f3n\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#listItem\",\"position\":5,\"name\":\"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\\u00e9cord m\\u00e1ximo.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/\",\"name\":\"INFINOX\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"INFINOX\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/\",\"name\":\"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\\u00e9cord m\\u00e1ximo. - INFINOX\",\"description\":\"Los mercados estuvieron bajo presi\\u00f3n el mi\\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\\u00f3 a un nuevo m\\u00e1ximo hist\\u00f3rico. El Dow se desplom\\u00f3 m\\u00e1s de 800 puntos, con el S&P 500\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/05\\\/Wall-Street-Sinks-Bitcoin-ATH-1.png\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#mainImage\",\"width\":1792,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/es\\\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\\\/#mainImage\"},\"datePublished\":\"2025-05-22T07:04:38+00:00\",\"dateModified\":\"2025-05-22T07:04:45+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX","description":"Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&P 500","canonical_url":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#blogposting","name":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX","headline":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo.","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/05\/Wall-Street-Sinks-Bitcoin-ATH-1.png","width":1792,"height":1024},"datePublished":"2025-05-22T07:04:38+00:00","dateModified":"2025-05-22T07:04:45+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#webpage"},"articleSection":"IX Daily, IX Intel, Noticias del mercado, Actualizaciones del mercado, Novedades, Espa\u00f1ol, pll_682ec7ef34c0b"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","name":"Investigaci\u00f3n"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","position":3,"name":"Investigaci\u00f3n","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#listItem","name":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/#listItem","name":"Investigaci\u00f3n"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#listItem","position":5,"name":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/infinox\/","name":"INFINOX","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g","width":96,"height":96,"caption":"INFINOX"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#webpage","url":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/","name":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX","description":"Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&P 500","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/05\/Wall-Street-Sinks-Bitcoin-ATH-1.png","@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#mainImage","width":1792,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/#mainImage"},"datePublished":"2025-05-22T07:04:38+00:00","dateModified":"2025-05-22T07:04:45+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX","og:description":"Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&amp;P 500","og:url":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/","article:published_time":"2025-05-22T07:04:38+00:00","article:modified_time":"2025-05-22T07:04:45+00:00","twitter:card":"summary_large_image","twitter:title":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo. - INFINOX","twitter:description":"Los mercados estuvieron bajo presi\u00f3n el mi\u00e9rcoles debido a que el aumento de los rendimientos del Tesoro y las preocupaciones sobre el d\u00e9ficit desencadenaron una fuerte venta masiva en las acciones, mientras que el bitcoin brevemente se dispar\u00f3 a un nuevo m\u00e1ximo hist\u00f3rico. El Dow se desplom\u00f3 m\u00e1s de 800 puntos, con el S&amp;P 500"},"aioseo_meta_data":{"post_id":"21178","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-15 14:25:55","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-05-22 07:04:42","updated":"2025-08-15 14:25:55"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/\" title=\"Investigaci\u00f3n\">Investigaci\u00f3n<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tWall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/"},{"label":"Investigaci\u00f3n","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/es\/ix-intel\/research\/espresso-morning-call\/"},{"label":"Wall Street se hunde mientras los rendimientos suben y Bitcoin alcanza un r\u00e9cord m\u00e1ximo.","link":"https:\/\/www.infinox.com\/global\/es\/wall-street-se-hunde-mientras-los-rendimientos-suben-y-bitcoin-alcanza-un-record-maximo\/"}],"lang":"es","translations":{"es":21178,"vi":21166,"en":21163,"zh_cn":21168,"pt":21170,"th":21172,"ko":21174,"zh_tw":21176,"jp":21180},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/21178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=21178"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/21178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/21165"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=21178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=21178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=21178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}