{"id":20433,"date":"2025-04-14T11:18:43","date_gmt":"2025-04-14T11:18:43","guid":{"rendered":"https:\/\/www.infinox.com\/global\/?p=20433"},"modified":"2025-04-14T11:18:46","modified_gmt":"2025-04-14T11:18:46","slug":"o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/","title":{"rendered":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana"},"content":{"rendered":"\n<p>Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 &#8220;otimista&#8221; em chegar a um acordo com Pequim. Apesar das oscila\u00e7\u00f5es severas no in\u00edcio da semana, todos os tr\u00eas principais \u00edndices registraram fortes ganhos semanais. No entanto, a incerteza permanece alta \u00e0 medida que as tarifas de retalia\u00e7\u00e3o aumentam, as expectativas de infla\u00e7\u00e3o sobem e a confian\u00e7a do consumidor despenca.<\/p>\n\n\n\n<p>Principias Pontos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dow dispara mais de 600 pontos para encerrar semana ca\u00f3tica: o Dow Jones Industrial Average subiu 619,05 pontos, ou 1,56%, encerrando aos 40.212,71. O \u00edndice se recuperou acentuadamente da queda de 1.000 pontos na quinta-feira, terminando a semana com alta de quase 5%, apesar das negocia\u00e7\u00f5es turbulentas causadas pelos temores de tarifas e pela mudan\u00e7a no sentimento de risco.<\/li>\n\n\n\n<li>S&amp;P 500 e Nasdaq t\u00eam melhor semana desde 2023: O S&amp;P 500 subiu 1,81% para 5.363,36, enquanto o Nasdaq cresceu 2,06% para 16.724,46. O rali hist\u00f3rico de quarta-feira, impulsionado por uma pausa tempor\u00e1ria nas tarifas, ajudou o S&amp;P a registrar um ganho semanal de 5,7%\u2014o melhor desde novembro de 2023. O Nasdaq disparou 7,3%, sua melhor performance semanal desde novembro de 2022.<\/li>\n\n\n\n<li>Mercados Europeus Fecham em Baixa Apesar da Surpresa de Crescimento do Reino Unido: As a\u00e7\u00f5es europeias fecharam em baixa na sexta-feira, encerrando uma semana vol\u00e1til dominada pela escalada das tarifas. Os dados de destaque vieram do Reino Unido, onde o PIB de fevereiro subiu 0,5% em rela\u00e7\u00e3o ao m\u00eas anterior, superando em muito a estimativa de 0,1%. A surpresa foi impulsionada por um aumento de 0,3% na produ\u00e7\u00e3o de servi\u00e7os e um aumento acentuado de 2,2% na produ\u00e7\u00e3o manufatureira, o mais forte em 20 meses. Apesar dos n\u00fameros positivos, o FTSE 100 caiu 1,13% na semana, para 7.964,18, j\u00e1 que os temores sobre o com\u00e9rcio global pesaram no sentimento. O Stoxx 600 caiu 0,1%, o DAX da Alemanha perdeu 0,92%, o CAC 40 da Fran\u00e7a caiu 0,3% e o FTSE MIB da It\u00e1lia recuou 0,73%.<\/li>\n\n\n\n<li>Mercados Asi\u00e1ticos Caem enquanto China Revida com Aumento de Tarifas: Os mercados acion\u00e1rios asi\u00e1ticos terminaram a semana mistos, mas tendendo para a queda, \u00e0 medida que as tens\u00f5es comerciais aumentaram. O Nikkei 225 do Jap\u00e3o despencou 2,96%, enquanto o Kospi da Coreia do Sul caiu 0,5% e o ASX 200 da Austr\u00e1lia recuou 0,82%. O CSI 300 da China subiu 0,41%, e o Hang Seng de Hong Kong ganhou 1,13%. O sentimento do mercado permaneceu fr\u00e1gil depois que a China aumentou as tarifas sobre bens dos EUA de 84% para 125%, retaliando contra o rec\u00e9m-confirmado imposto universal de 145% dos EUA. O minist\u00e9rio das finan\u00e7as chin\u00eas denunciou a medida como irracional e prometeu uma retalia\u00e7\u00e3o econ\u00f4mica.<\/li>\n\n\n\n<li>Pre\u00e7os do Petr\u00f3leo Subiram com Amea\u00e7a de Proibi\u00e7\u00e3o de Exporta\u00e7\u00e3o do Ir\u00e3: Os pre\u00e7os do petr\u00f3leo bruto subiram acentuadamente depois que o Secret\u00e1rio de Energia dos EUA, Chris Wright, sinalizou um poss\u00edvel fim das exporta\u00e7\u00f5es de petr\u00f3leo iraniano como parte de uma estrat\u00e9gia nuclear mais ampla. O Brent fechou a $64,76, um aumento de $1,43 ou 2,26%, enquanto o WTI subiu para $61,50, ganhando 2,38%. Medos de oferta relacionados ao Ir\u00e3 e tens\u00f5es geopol\u00edticas mais amplas superaram as preocupa\u00e7\u00f5es sobre a queda da demanda devido ao crescimento econ\u00f4mico global mais lento causado pelos efeitos de tarifas.<\/li>\n\n\n\n<li>Os rendimentos do Tesouro disparam enquanto vendedores estrangeiros saem dos t\u00edtulos dos EUA: o rendimento do Tesouro a 10 anos subiu 9 pontos-base, chegando a 4,486%, encerrando uma semana que viu os rendimentos dispararem mais de 50 pontos-base\u2014o movimento mais acentuado em anos. O rendimento do t\u00edtulo a 2 anos subiu para 3,97%. Analistas citaram poss\u00edveis vendas por parte da China e do Jap\u00e3o em meio ao aumento das fric\u00e7\u00f5es comerciais, invertendo o papel tradicional de ref\u00fagio seguro da d\u00edvida dos EUA durante a volatilidade.<\/li>\n\n\n\n<li>Os pre\u00e7os no atacado dos EUA caem inesperadamente em mar\u00e7o: Os pre\u00e7os ao produtor ca\u00edram 0,4% em mar\u00e7o, contrariando as expectativas consensuais de aumento. O n\u00facleo do PPI tamb\u00e9m diminuiu, sinalizando press\u00f5es inflacion\u00e1rias mais brandas. Os pre\u00e7os dos bens despencaram 0,9%, enquanto os servi\u00e7os ca\u00edram 0,2%. Os dados chegam enquanto os EUA se preparam para aumentos de custos impulsionados por tarifas nos pr\u00f3ximos meses.<\/li>\n\n\n\n<li>Sentimento do Consumidor Cai Bruscamente por Temores de Infla\u00e7\u00e3o: O \u00edndice de sentimento do consumidor da Universidade de Michigan caiu para 50,8 em abril, seu n\u00edvel mais baixo desde 1981. As expectativas de infla\u00e7\u00e3o de um ano aumentaram para 6,7%, enquanto as expectativas de cinco anos subiram para 4,4%. Os dados refletem uma ansiedade generalizada sobre o aumento dos pre\u00e7os e a incerteza econ\u00f4mica, especialmente em meio \u00e0s crescentes tens\u00f5es comerciais.<\/li>\n<\/ul>\n\n\n\n<p>FX Hoje:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1940\" height=\"772\" src=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/04\/Currency-Strenght-14Apr25-3.png\" alt=\"\" class=\"wp-image-20434\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/04\/Currency-Strenght-14Apr25-3.png 1940w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/04\/Currency-Strenght-14Apr25-3-768x306.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/04\/Currency-Strenght-14Apr25-3-1536x611.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/04\/Currency-Strenght-14Apr25-3-710x283.png 710w\" sizes=\"(max-width: 1940px) 100vw, 1940px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>EUR\/USD dispara para a m\u00e1xima de 10 meses com impulso de breakout: O par EUR\/USD subiu 1,25% na quinta-feira, fechando a 1,1338, marcando seu n\u00edvel mais alto desde junho de 2024. O par ganhou quase 450 pips desde a baixa no in\u00edcio de mar\u00e7o e agora est\u00e1 negociado bem acima de todas as m\u00e9dias m\u00f3veis principais. A SMA de 50 dias em 1,0689 cruzou acima da SMA de 100 dias em 1,0556, formando um cruzamento de alta, com ambas agora inclinadas para cima. O pre\u00e7o quebrou claramente acima da resist\u00eancia em 1,1100, desencadeando um rali em dire\u00e7\u00e3o \u00e0 zona de 1,1300\u20131,1350. O pr\u00f3ximo alvo de subida est\u00e1 em 1,1450, enquanto 1,1500 permanece um \u00edm\u00e3 psicol\u00f3gico chave. No lado negativo, 1,1200 agora atua como suporte inicial, seguido por 1,1100. Os indicadores de momentum permanecem fortes, sugerindo mais altas a menos que ocorra uma mudan\u00e7a macro.<\/li>\n\n\n\n<li>GBP\/USD Estende Recupera\u00e7\u00e3o para M\u00e1xima de Dois Meses, Surpreendendo com Dados do Reino Unido: O GBP\/USD fechou a 1,3078, subindo 0,83% e registrando seu fechamento mais alto desde fevereiro. O movimento seguiu dados inesperadamente fortes do PIB do Reino Unido (+0,5% m\/m em fevereiro), juntamente com uma produ\u00e7\u00e3o manufatureira robusta (+2,2%), ambos impulsionando o sentimento dos investidores. O pre\u00e7o subiu acima da M\u00e9dia M\u00f3vel Simples (SMA) de 50 dias em 1,2771, da SMA de 100 dias em 1,2641 e da SMA de 200 dias em 1,2818, todas agora em alta. O rali superou a resist\u00eancia em 1,3000, com 1,3150 e 1,3200 identificados como pr\u00f3ximos alvos de alta. No lado negativo, a faixa de 1,2950\u20131,2900 fornece uma zona de demanda crucial. A estrutura de alta permanece intacta enquanto o pre\u00e7o se mantiver acima do cluster ascendente de SMAs.<\/li>\n\n\n\n<li>AUD\/USD Sobe pelo Quinto Dia, Mirando Rompimento Acima de Resist\u00eancia Chave: AUD\/USD subiu 1,13% para fechar em 0,6294, registrando um quinto avan\u00e7o di\u00e1rio consecutivo. O par recuperou mais de 350 pips desde sua baixa em abril pr\u00f3ximo de 0,5940 e agora est\u00e1 desafiando uma zona de resist\u00eancia importante entre 0,6300 e 0,6350. O pre\u00e7o subiu acima tanto da SMA de 50 dias (0,6279) quanto da SMA de 100 dias (0,6294), embora continue abaixo da SMA de 200 dias em 0,6486. Um fechamento di\u00e1rio decisivo acima de 0,6350 poderia abrir o caminho em dire\u00e7\u00e3o a 0,6480\u20130,6500. O suporte imediato \u00e9 visto em 0,6220, seguido por um piso chave em torno de 0,6150. A estrutura do par sugere que uma recupera\u00e7\u00e3o est\u00e1 em andamento, mas a revers\u00e3o de tend\u00eancia de longo prazo depende de retomar o n\u00edvel da SMA de 200 dias.<\/li>\n\n\n\n<li>USD\/CHF cai para nova m\u00ednima de v\u00e1rios meses conforme a tend\u00eancia de baixa se aprofunda: USD\/CHF fechou a 0,8158, uma queda de 0,94%, atingindo seu n\u00edvel mais baixo desde meados de 2023. O par est\u00e1 agora firmemente entrincheirado em uma tend\u00eancia de baixa, negociando bem abaixo de todas as principais m\u00e9dias m\u00f3veis \u2014 a de 50 dias (0,8857), 100 dias (0,8921) e 200 dias (0,8788) \u2014 cada uma inclinada para baixo. Ap\u00f3s repetidas rejei\u00e7\u00f5es perto de 0,8550 e 0,8700 em mar\u00e7o, os vendedores tomaram o controle, conduzindo sucessivas m\u00e1ximas e m\u00ednimas mais baixas. O pr\u00f3ximo suporte importante encontra-se na zona psicologicamente importante de 0,8000, onde o pre\u00e7o anteriormente encontrou compradores em maio\u2013junho de 2023. A resist\u00eancia agora est\u00e1 em 0,8400, depois em 0,8550.<\/li>\n\n\n\n<li>Ouro Bate Recorde com Aumento na Demanda por Ref\u00fagios Seguros: O ouro subiu 1,70% para fechar a $3.229, alcan\u00e7ando um novo recorde hist\u00f3rico, \u00e0 medida que a incerteza sobre a infla\u00e7\u00e3o e os riscos geopol\u00edticos impulsionaram a demanda por ref\u00fagios seguros. Este \u00e9 o s\u00e9timo ganho em oito sess\u00f5es, com o rali se estendendo bem al\u00e9m do seu recorde anterior, pr\u00f3ximo a $3.175. A m\u00e9dia m\u00f3vel simples de 50 dias est\u00e1 subindo acentuadamente a $2.969, enquanto as m\u00e9dias de 100 dias e 200 dias est\u00e3o em $2.820 e $2.688, respectivamente. O pre\u00e7o continua em uma subida quase parab\u00f3lica, com m\u00ednimas retra\u00e7\u00f5es intradi\u00e1rias. Se o momentum persistir, os alvos s\u00e3o $3.250 e $3.300. O suporte agora est\u00e1 em $3.175, seguido por $3.100. Enquanto o pre\u00e7o se mantiver acima do n\u00edvel de rompimento, \u00e9 prov\u00e1vel que as quedas sejam agressivamente compradas.<\/li>\n<\/ul>\n\n\n\n<p>Movimentos de Mercado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Frontier Group cai devido \u00e0 demanda mais fraca: As a\u00e7\u00f5es da Frontier Airlines ca\u00edram 5,6% ap\u00f3s a empresa reduzir suas expectativas de receita para o primeiro trimestre e retirar sua previs\u00e3o para o ano inteiro. A administra\u00e7\u00e3o apontou para o enfraquecimento da demanda por viagens e para os crescentes ventos macroecon\u00f4micos contr\u00e1rios, decepcionando os investidores que j\u00e1 estavam preocupados com a lucratividade em um ambiente de alto custo.<\/li>\n\n\n\n<li>JPMorgan tem alta ap\u00f3s superar expectativas de receita e alerta do CEO: JPMorgan subiu 4% ap\u00f3s reportar uma receita de US$ 46,01 bilh\u00f5es no primeiro trimestre, bem acima da estimativa de consenso de US$ 44,11 bilh\u00f5es. O lucro l\u00edquido tamb\u00e9m superou as previs\u00f5es. Apesar do desempenho, o CEO Jamie Dimon alertou que a economia dos EUA enfrenta &#8220;consider\u00e1vel turbul\u00eancia&#8221; nos pr\u00f3ximos meses.<\/li>\n\n\n\n<li>BlackRock ganha ap\u00f3s supera\u00e7\u00e3o das expectativas nos lucros e entradas de recursos constantes: A gestora de ativos subiu 2,3% ap\u00f3s registrar um lucro ajustado por a\u00e7\u00e3o de $11,30 em compara\u00e7\u00e3o com os $10,14 esperados. Apesar da volatilidade mais ampla do mercado, a empresa relatou entradas de recursos s\u00f3lidas. O CEO Larry Fink observou que os EUA podem j\u00e1 estar em recess\u00e3o, mas os resultados sinalizaram resili\u00eancia operacional.<\/li>\n\n\n\n<li>Os mineradores de ouro disparam com pre\u00e7os recordes do metal e upgrade do UBS: Barrick Gold e Newmont Corp. subiram 7% e 7,9%, respectivamente, acompanhando a alta do ouro para um novo recorde hist\u00f3rico. O UBS elevou a classifica\u00e7\u00e3o da Newmont de \u201cneutra\u201d para \u201ccompra\u201d, citando a melhora dos fundamentos e o potencial de supera\u00e7\u00e3o dos lucros se os pre\u00e7os permanecerem elevados.<\/li>\n\n\n\n<li>Apple recupera junto com o setor de tecnologia, j\u00e1 que riscos de tarifas s\u00e3o reavaliados: As a\u00e7\u00f5es da Apple subiram 4% na sexta-feira, trazendo ganhos semanais para 5,2% ap\u00f3s um in\u00edcio de abril turbulento. Apesar das preocupa\u00e7\u00f5es com tarifas sobre iPhones fabricados na China, os investidores parecem estar olhando al\u00e9m dos riscos de curto prazo.<\/li>\n\n\n\n<li>MicroStrategy dispara com o impulso das criptomoedas e recupera\u00e7\u00e3o do risco: As a\u00e7\u00f5es dispararam 10,2%, espelhando os ganhos do Bitcoin durante a sess\u00e3o de sexta-feira. Como um grande detentor de BTC, a MicroStrategy frequentemente negocia como um proxy para o sentimento das criptomoedas. O rali foi ainda mais impulsionado por uma recupera\u00e7\u00e3o mais ampla dos ativos de risco e sinais de renovada compra institucional.<\/li>\n<\/ul>\n\n\n\n<p>Os mercados encerraram uma semana ca\u00f3tica com uma forte recupera\u00e7\u00e3o, mas o caminho \u00e0 frente continua repleto de incertezas. Embora as esperan\u00e7as de uma resolu\u00e7\u00e3o comercial entre os EUA e a China tenham elevado os \u00edndices de a\u00e7\u00f5es na sexta-feira, a r\u00e1pida escalada das tarifas retaliat\u00f3rias e as oscila\u00e7\u00f5es acentuadas nos rendimentos do Tesouro ressaltam o qu\u00e3o fr\u00e1gil continua o sentimento. Uma infla\u00e7\u00e3o no atacado mais branda trouxe al\u00edvio tempor\u00e1rio, mas a deteriora\u00e7\u00e3o da confian\u00e7a do consumidor e sinais de desinvestimento estrangeiro da d\u00edvida dos EUA apontam para preocupa\u00e7\u00f5es mais profundas. Os investidores agora mudar\u00e3o o foco para a temporada de resultados das empresas, os pr\u00f3ximos \u00edndices de infla\u00e7\u00e3o e quaisquer novos desenvolvimentos na diplomacia comercial global. Com a volatilidade ainda elevada, a pr\u00f3xima semana pode ser t\u00e3o crucial quanto a \u00faltima.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 &#8220;otimista&#8221;<a href=\"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":28,"featured_media":20426,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[530,30,548],"tags":[569,560,566,575],"class_list":["post-20433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-market-news","tag-market-updates","tag-financial-trading","tag-international-news","tag-whats-new"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 &quot;otimista&quot;\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"INFINOX\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 &quot;otimista&quot;\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-04-14T11:18:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-04-14T11:18:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 &quot;otimista&quot;\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#blogposting\",\"name\":\"O Caos das Tarifas Desencadeia Oscila\\u00e7\\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX\",\"headline\":\"O Caos das Tarifas Desencadeia Oscila\\u00e7\\u00f5es Selvagens Antes da Alta no Final da Semana\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/04\\\/SP500-Nasdaq-oil-dollars.png\",\"width\":1792,\"height\":1024},\"datePublished\":\"2025-04-14T11:18:43+00:00\",\"dateModified\":\"2025-04-14T11:18:46+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Not\\u00edcias do mercado, Atualiza\\u00e7\\u00f5es de mercado, Negocia\\u00e7\\u00e3o financeira, Not\\u00edcias internacionais, O que h\\u00e1 de novo, Portugu\\u00eas, pll_67fcebe346092\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Pesquisa\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#listItem\",\"name\":\"O Caos das Tarifas Desencadeia Oscila\\u00e7\\u00f5es Selvagens Antes da Alta no Final da Semana\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#listItem\",\"position\":5,\"name\":\"O Caos das Tarifas Desencadeia Oscila\\u00e7\\u00f5es Selvagens Antes da Alta no Final da Semana\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/\",\"name\":\"INFINOX\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"INFINOX\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/\",\"name\":\"O Caos das Tarifas Desencadeia Oscila\\u00e7\\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX\",\"description\":\"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\\u00e1teis da mem\\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\\u00e7as de al\\u00edvio nas tens\\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\\u00e1rios da Casa Branca sugerindo que o presidente Trump est\\u00e1 \\\"otimista\\\"\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/infinox\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/04\\\/SP500-Nasdaq-oil-dollars.png\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#mainImage\",\"width\":1792,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\\\/#mainImage\"},\"datePublished\":\"2025-04-14T11:18:43+00:00\",\"dateModified\":\"2025-04-14T11:18:46+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX","description":"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 \"otimista\"","canonical_url":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#blogposting","name":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX","headline":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/04\/SP500-Nasdaq-oil-dollars.png","width":1792,"height":1024},"datePublished":"2025-04-14T11:18:43+00:00","dateModified":"2025-04-14T11:18:46+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#webpage"},"articleSection":"IX Daily, IX Intel, Not\u00edcias do mercado, Atualiza\u00e7\u00f5es de mercado, Negocia\u00e7\u00e3o financeira, Not\u00edcias internacionais, O que h\u00e1 de novo, Portugu\u00eas, pll_67fcebe346092"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","position":3,"name":"Pesquisa","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#listItem","name":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#listItem","position":5,"name":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/infinox\/","name":"INFINOX","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3ec8d2fe76e0d872403c4d80405ee45f333f1824d23cf82da0152afac9e04991?s=96&d=blank&r=g","width":96,"height":96,"caption":"INFINOX"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#webpage","url":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/","name":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX","description":"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 \"otimista\"","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/infinox\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2025\/04\/SP500-Nasdaq-oil-dollars.png","@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#mainImage","width":1792,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/#mainImage"},"datePublished":"2025-04-14T11:18:43+00:00","dateModified":"2025-04-14T11:18:46+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX","og:description":"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 &quot;otimista&quot;","og:url":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/","article:published_time":"2025-04-14T11:18:43+00:00","article:modified_time":"2025-04-14T11:18:46+00:00","twitter:card":"summary_large_image","twitter:title":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana - INFINOX","twitter:description":"Wall Street rugiu na sexta-feira para encerrar uma das semanas mais vol\u00e1teis da mem\u00f3ria recente, com o Dow saltando mais de 600 pontos em meio a novas esperan\u00e7as de al\u00edvio nas tens\u00f5es comerciais entre os EUA e a China. Os investidores responderam positivamente aos coment\u00e1rios da Casa Branca sugerindo que o presidente Trump est\u00e1 &quot;otimista&quot;"},"aioseo_meta_data":{"post_id":"20433","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-15 13:14:02","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2025-04-14 11:18:47","updated":"2025-11-27 05:42:59"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/\" title=\"Pesquisa\">Pesquisa<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tO Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/"},{"label":"Pesquisa","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/"},{"label":"O Caos das Tarifas Desencadeia Oscila\u00e7\u00f5es Selvagens Antes da Alta no Final da Semana","link":"https:\/\/www.infinox.com\/global\/pt\/o-caos-das-tarifas-desencadeia-oscilacoes-selvagens-antes-da-alta-no-final-da-semana\/"}],"lang":"pt","translations":{"pt":20433,"vi":20429,"zh_cn":20431,"th":20435,"zh_tw":20437,"es":20439},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/20433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=20433"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/20433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/20426"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=20433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=20433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=20433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}