{"id":15694,"date":"2024-09-26T14:09:57","date_gmt":"2024-09-26T14:09:57","guid":{"rendered":"https:\/\/www.infinox.com\/fsc\/?p=15694"},"modified":"2024-09-26T14:09:59","modified_gmt":"2024-09-26T14:09:59","slug":"acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/","title":{"rendered":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow, Quebrando Sequ\u00eancia de Quatro Dias de Alta"},"content":{"rendered":"\n<p>Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos e o S&amp;P 500 recuando de altas recordes. Dados habitacionais mais fracos do que o esperado e um forte decl\u00ednio nas a\u00e7\u00f5es de energia e automotivas impactaram negativamente o sentimento dos investidores. Embora as a\u00e7\u00f5es de tecnologia tenham fornecido algum al\u00edvio, especialmente <a href=\"https:\/\/www.nvidia.com\/pt-br\/\" title=\"Nvidia\">Nvidia<\/a> e Hewlett Packard Enterprise, a cautela prevaleceu no mercado geral. Com preocupa\u00e7\u00f5es sobre uma desacelera\u00e7\u00e3o econ\u00f4mica e sinais mistos dos mercados globais, os traders ficaram nervosos, aguardando mais dados econ\u00f4micos e desenvolvimentos do Federal Reserve.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Principias Pontos:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dow cai 297 pontos:<\/strong> O Dow Jones Industrial Average caiu 297 pontos, ou 0,7%, fechando em 34.567, marcando o fim de sua sequ\u00eancia de quatro dias de alta. Uma queda de 5% nas a\u00e7\u00f5es da Amgen, juntamente com perdas na General Motors e Ford, que ca\u00edram 5% e 4%, respectivamente, ap\u00f3s serem rebaixadas pelo Morgan Stanley, contribu\u00edram para a queda. Sete dos 11 setores do S&amp;P 500 estavam em territ\u00f3rio negativo, refletindo uma fraqueza mais ampla no mercado.<\/li>\n\n\n\n<li><strong>S&amp;P 500 Cai de M\u00e1xima Recorde:<\/strong> O S&amp;P 500 caiu 0,2%, fechando em 4.567 ap\u00f3s alcan\u00e7ar m\u00e1ximas recordes no in\u00edcio das negocia\u00e7\u00f5es. As a\u00e7\u00f5es de energia lideraram a queda, com os futuros do petr\u00f3leo bruto dos EUA caindo mais de 2%, fechando a $69,81 por barril. A Chevron viu uma queda de 2% como parte desta venda mais ampla no setor de energia. O mercado tamb\u00e9m foi pressionado por preocupa\u00e7\u00f5es sobre uma economia em desacelera\u00e7\u00e3o, especialmente \u00e0 luz de dados de habita\u00e7\u00e3o mais fracos.<\/li>\n\n\n\n<li><strong>Nasdaq Permanece Est\u00e1vel \u00e0 Medida que Ganhos em Tecnologia Compensam Perdas:<\/strong> O Nasdaq Composite manteve-se pr\u00f3ximo da linha de estabilidade, sustentado pela for\u00e7a das a\u00e7\u00f5es de tecnologia. A Hewlett Packard Enterprise subiu mais de 4% ap\u00f3s uma atualiza\u00e7\u00e3o de classifica\u00e7\u00e3o do Barclays, enquanto a Nvidia adicionou 2%, elevando sua capitaliza\u00e7\u00e3o de mercado acima de $3 trilh\u00f5es pela primeira vez. Esses ganhos ajudaram a compensar as quedas em outros setores.<\/li>\n\n\n\n<li><strong>Mercado Imobili\u00e1rio dos EUA Desacelera:<\/strong> As vendas de novas casas unifamiliares nos EUA ca\u00edram 4,7% em agosto, chegando a uma taxa anualizada de 716.000 unidades, em compara\u00e7\u00e3o com 751.000 em julho. Apesar da queda mensal, as vendas continuam 9,8% mais altas em compara\u00e7\u00e3o com o ano anterior. Com as taxas de hipoteca em torno de 6%, o setor habitacional continua a mostrar sinais de desacelera\u00e7\u00e3o \u00e0 medida que a incerteza econ\u00f4mica persiste.<\/li>\n\n\n\n<li><strong>Mercados Europeus Fecham em Baixa:<\/strong> Os mercados europeus terminaram o dia ligeiramente em baixa, \u00e0 medida que o otimismo em torno dos an\u00fancios de est\u00edmulo da China diminuiu. O \u00edndice pan-europeu Stoxx 600 perdeu 0,11%, enquanto o DAX da Alemanha caiu 0,4%, para 18.920, e o CAC 40 da Fran\u00e7a recuou 0,50%. O FTSE 100 do Reino Unido declinou 0,17%, fechando em 8.268,70. As a\u00e7\u00f5es de bancos europeus foram particularmente fracas, com o \u00edndice banc\u00e1rio caindo 0,73%, em meio \u00e0 cautela dos investidores em rela\u00e7\u00e3o \u00e0 maior participa\u00e7\u00e3o do UniCredit no Commerzbank.<\/li>\n\n\n\n<li><strong>Mercados Asi\u00e1ticos Avan\u00e7am com Medidas de Est\u00edmulo da China:<\/strong> O CSI 300 da China continental disparou 4,33%, registrando seu melhor dia em mais de quatro anos, ap\u00f3s o Banco do Povo da China anunciar medidas significativas de afrouxamento da pol\u00edtica, incluindo uma redu\u00e7\u00e3o de 50 pontos-base no \u00edndice de reserva obrigat\u00f3ria para os bancos. O \u00edndice Hang Seng de Hong Kong tamb\u00e9m subiu quase 4%, enquanto o Nikkei 225 do Jap\u00e3o ganhou 0,57% para fechar em 37.940,59, ultrapassando a marca de 38.000 pela primeira vez em semanas durante a sess\u00e3o. O Kospi da Coreia do Sul subiu 1,14%, registrando seu sexto dia consecutivo de ganhos. Em contraste, o S&amp;P\/ASX 200 da Austr\u00e1lia caiu 0,13% depois que o Banco da Reserva da Austr\u00e1lia manteve sua taxa de pol\u00edtica est\u00e1vel em 4,35%.<\/li>\n\n\n\n<li><strong>Pre\u00e7os do Petr\u00f3leo Caem Mais de 2% com Al\u00edvio das Preocupa\u00e7\u00f5es com o Abastecimento na L\u00edbia:<\/strong> Os pre\u00e7os do petr\u00f3leo ca\u00edram acentuadamente na quarta-feira, \u00e0 medida que as preocupa\u00e7\u00f5es com o abastecimento na L\u00edbia diminu\u00edram. O Brent crude caiu $1,64, ou 2,18%, para se fixar em $73,53 por barril, enquanto o US West Texas Intermediate crude caiu $1,75, ou 2,45%, para fechar em $69,81. Apesar das medidas de est\u00edmulo da China, as preocupa\u00e7\u00f5es com a fraca demanda global, especialmente da China, continuaram a pesar nos mercados de petr\u00f3leo.<\/li>\n\n\n\n<li><strong>Rendimentos do Tesouro Sobem Enquanto Investidores Avaliam Dados Econ\u00f4micos:<\/strong> Os rendimentos dos t\u00edtulos do Tesouro dos EUA subiram, com o rendimento do t\u00edtulo de 10 anos aumentando 5,3 pontos base para 3,789% e o rendimento do t\u00edtulo de 2 anos ganhando 4,1 pontos base para 3,561%. Os investidores est\u00e3o monitorando de perto os indicadores econ\u00f4micos, \u00e0 medida que os recentes cortes nas taxas de juros pelo Federal Reserve mudam o foco para o crescimento econ\u00f4mico, a infla\u00e7\u00e3o e os pr\u00f3ximos lan\u00e7amentos de dados, como solicita\u00e7\u00f5es de seguro-desemprego e gastos do consumidor.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">FX Hoje:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>EUR\/USD Mant\u00e9m Estabilidade em Meio ao Foco Econ\u00f4mico nos EUA: <\/strong>O par EUR\/USD foi negociado a 1,1130, mostrando uma ligeira queda em rela\u00e7\u00e3o \u00e0 sua m\u00e1xima intradi\u00e1ria de 1,1139. O par permanece acima de n\u00edveis de suporte chave, com a SMA de 50 per\u00edodos em 1,1136 e a SMA de 200 per\u00edodos em 1,1082. \u00c0 medida que os investidores ponderam o impacto do recente corte de taxa do Federal Reserve e a perspectiva econ\u00f4mica mais ampla dos EUA, o euro continua sustentado pela fraqueza cont\u00ednua do d\u00f3lar dos EUA. A resist\u00eancia imediata situa-se em 1,1150, com potencial para mais ganhos se os dados econ\u00f4micos continuarem a apoiar um sentimento positivo na Zona do Euro. No entanto, uma quebra abaixo de 1,1082 poderia sinalizar uma retra\u00e7\u00e3o mais ampla.<\/li>\n\n\n\n<li><strong>GBP\/USD recua das altas, mas mant\u00e9m vi\u00e9s de alta:<\/strong> GBP\/USD recuou ligeiramente para 1,3317 ap\u00f3s atingir uma alta de 1,3333 no in\u00edcio da sess\u00e3o. Apesar da pequena queda, o par permanece bem-suportado, com a m\u00e9dia m\u00f3vel simples de 50 per\u00edodos em 1,3269 e a m\u00e9dia m\u00f3vel simples de 200 per\u00edodos em 1,3110 se mantendo firmes. Com a libra esterlina se beneficiando de fortes dados econ\u00f4micos do Reino Unido e um d\u00f3lar americano mais fraco, o par continua em tend\u00eancia de alta. Um maior movimento ascendente pode encontrar resist\u00eancia em 1,3400, com um poss\u00edvel alvo em 1,3450 se o momento de compra aumentar. No lado negativo, uma quebra abaixo de 1,3110 indicaria uma corre\u00e7\u00e3o mais profunda.<\/li>\n\n\n\n<li><strong>USD\/CHF se Estabiliza \u00e0 medida que o Franco Su\u00ed\u00e7o Permanece Forte: <\/strong>USD\/CHF negociou em torno de 0,8499, mostrando pouco movimento ap\u00f3s atingir uma alta intradi\u00e1ria de 0,8502. O par continua a enfrentar press\u00e3o de baixa, com a SMA de 50 per\u00edodos em 0,8468 e a SMA de 200 per\u00edodos em 0,8516 atuando como indicadores t\u00e9cnicos chave. Enquanto o d\u00f3lar americano luta em meio a dados econ\u00f4micos mistos, o franco su\u00ed\u00e7o tem permanecido forte, mantendo o par em uma tend\u00eancia de baixa. Se o USD\/CHF romper abaixo de 0,8468, uma queda adicional \u00e9 prov\u00e1vel, com o pr\u00f3ximo n\u00edvel de suporte em 0,8450. No lado positivo, um rompimento acima de 0,8516 poderia desencadear uma potencial revers\u00e3o.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.infinox.com\/fsc\/pt\/instruments\/forex\/\" title=\"AUD\/USD\">AUD\/USD<\/a> Consolida Ap\u00f3s Ganhos Recentes: <\/strong>O par AUD\/USD est\u00e1 atualmente sendo negociado a 0,6824, tendo recuado ligeiramente do seu pico anterior de 0,6833. O par permanece acima dos n\u00edveis de suporte chave, com a SMA de 50 per\u00edodos a 0,6799 e a SMA de 200 per\u00edodos a 0,6721. Apoiado por um sentimento de risco positivo e pela fraqueza do d\u00f3lar americano, o d\u00f3lar australiano tem mantido seu impulso ascendente. Uma resist\u00eancia imediata \u00e9 observada em 0,6850, com potencial para subir mais se o sentimento atual se mantiver. No entanto, uma quebra abaixo de 0,6721 poderia sinalizar uma mudan\u00e7a de tend\u00eancia, levando a uma poss\u00edvel corre\u00e7\u00e3o para a baixa.<\/li>\n\n\n\n<li><strong>Ouro Consolida Ap\u00f3s Recente Rally:<\/strong> Os pre\u00e7os do ouro (XAU\/USD) mostraram uma leve consolida\u00e7\u00e3o hoje, sendo negociados a $2.660,39 ap\u00f3s atingir um m\u00e1ximo intradi\u00e1rio de $2.661,72. Apesar deste pequeno recuo, o metal precioso permanece em uma tend\u00eancia de alta, bem sustentado pela cont\u00ednua incerteza econ\u00f4mica global e pela demanda dos investidores por ativos de ref\u00fagio seguro. A SMA de 50 per\u00edodos em $2.603,77 continua a oferecer forte suporte, com resist\u00eancia imediata em $2.661,72. Uma quebra acima deste n\u00edvel pode levar os pre\u00e7os do ouro em dire\u00e7\u00e3o \u00e0 marca de $2.700 no curto prazo. Por outro lado, se os pre\u00e7os ca\u00edrem abaixo da SMA de 200 per\u00edodos em $2.525,20, isso pode indicar uma potencial mudan\u00e7a de momentum, levando a uma corre\u00e7\u00e3o descendente adicional.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1962\" height=\"776\" src=\"https:\/\/www.infinox.com\/fsc\/wp-content\/uploads\/sites\/5\/2024\/09\/Currency-Strenght-26Sep.png\" alt=\"\" class=\"wp-image-15695\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/09\/Currency-Strenght-26Sep.png 1962w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/09\/Currency-Strenght-26Sep-768x304.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/09\/Currency-Strenght-26Sep-1536x608.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/09\/Currency-Strenght-26Sep-710x281.png 710w\" sizes=\"(max-width: 1962px) 100vw, 1962px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Movimentos de Mercado:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Amgen puxa Dow com queda de 5%:<\/strong> As a\u00e7\u00f5es da Amgen despencaram 5%, contribuindo significativamente para a queda de 297 pontos do Dow. O gigante farmac\u00eautico enfrentou uma forte press\u00e3o vendedora, que pesou no \u00edndice geral, quebrando sua sequ\u00eancia de quatro dias de vit\u00f3rias.<\/li>\n\n\n\n<li><strong>General Motors e Ford caem ap\u00f3s rebaixamentos: <\/strong>Tanto a General Motors quanto a Ford sofreram perdas acentuadas ap\u00f3s rebaixamentos do Morgan Stanley. A General Motors caiu 5%, enquanto a Ford caiu 4%. Analistas est\u00e3o preocupados com o enfraquecimento do cr\u00e9dito ao consumidor nos EUA e o aumento da capacidade de produ\u00e7\u00e3o na China.<\/li>\n\n\n\n<li><strong>Hewlett Packard Enterprise se destaca com otimismo em rela\u00e7\u00e3o \u00e0 IA:<\/strong> as a\u00e7\u00f5es da Hewlett Packard Enterprise subiram mais de 4% ap\u00f3s um upgrade do Barclays, que citou a crescente demanda por infraestrutura de centros de dados de intelig\u00eancia artificial.<\/li>\n\n\n\n<li><strong>Valoriza\u00e7\u00e3o da Nvidia Ultrapassa $3 Trilh\u00f5es:<\/strong> A gigante de chips Nvidia subiu 2%, elevando sua capitaliza\u00e7\u00e3o de mercado acima de $3 trilh\u00f5es pela primeira vez. A empresa continua a se destacar com a forte demanda por suas tecnologias de semicondutores, especialmente no setor de IA.<\/li>\n\n\n\n<li><strong>Valmet sobe com grande pedido:<\/strong> A empresa de engenharia finlandesa Valmet viu suas a\u00e7\u00f5es subirem quase 12% ap\u00f3s garantir um grande pedido avaliado em aproximadamente 1 bilh\u00e3o de euros (1,1 bilh\u00f5es de d\u00f3lares) de uma f\u00e1brica de celulose no Brasil.<\/li>\n\n\n\n<li><strong>Ganhos de Commerzbank de 0,82% em meio ao aumento de participa\u00e7\u00e3o do UniCredit: <\/strong>As a\u00e7\u00f5es do Commerzbank subiram 0,82% depois que o UniCredit, o segundo maior banco da It\u00e1lia, anunciou ter aumentado sua participa\u00e7\u00e3o no banco alem\u00e3o para cerca de 21%. A not\u00edcia seguiu a movimenta\u00e7\u00e3o anterior do UniCredit para adquirir uma participa\u00e7\u00e3o de 9% no Commerzbank neste m\u00eas, com planos adicionais de aumentar sua participa\u00e7\u00e3o para 29,9%.<\/li>\n\n\n\n<li><strong>SAP cai 2,4% devido a investiga\u00e7\u00e3o de fixa\u00e7\u00e3o de pre\u00e7os nos EUA: <\/strong>O gigante alem\u00e3o de software SAP caiu 2,4% ap\u00f3s relatos de que a empresa est\u00e1 sob investiga\u00e7\u00e3o nos EUA devido a alega\u00e7\u00f5es de fixa\u00e7\u00e3o de pre\u00e7os. A not\u00edcia pressionou as a\u00e7\u00f5es da SAP, empurrando-as para a parte inferior do \u00edndice Stoxx 600, \u00e0 medida que cresciam as preocupa\u00e7\u00f5es entre os investidores sobre poss\u00edveis implica\u00e7\u00f5es legais.<\/li>\n<\/ul>\n\n\n\n<p>No fechamento dos mercados em um dia vol\u00e1til, a queda de 297 pontos do Dow Jones e o recuo do S&amp;P 500 de seus recordes ressaltaram as crescentes preocupa\u00e7\u00f5es com os dados econ\u00f4micos e desafios espec\u00edficos de setores. A ind\u00fastria automotiva enfrentou fortes quedas, com a General Motors e a Ford gravemente atingidas por rebaixamentos, enquanto as a\u00e7\u00f5es de energia ca\u00edram com a queda de mais de 2% nos pre\u00e7os do petr\u00f3leo bruto. Apesar desses desafios, o Nasdaq encontrou suporte atrav\u00e9s dos ganhos em a\u00e7\u00f5es de tecnologia, como Nvidia e Hewlett Packard Enterprise, ajudando a manter-se pr\u00f3ximo da linha de estabilidade. Enquanto isso, os mercados europeus e asi\u00e1ticos tiveram desempenhos mistos, \u00e0 medida que o otimismo inicial com as medidas de est\u00edmulo da China come\u00e7ou a se dissipar. Com investidores observando de perto os pr\u00f3ximos dados econ\u00f4micos dos EUA, especialmente os pedidos de aux\u00edlio-desemprego e os \u00edndices de infla\u00e7\u00e3o, a incerteza permanece alta \u00e0 medida que os mercados globais navegam por este cen\u00e1rio em mudan\u00e7a.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos e o S&amp;P 500 recuando de altas recordes. <\/p>\n","protected":false},"author":30,"featured_media":15696,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[530,30,524],"tags":[1390,1541,1824,1434,1561,563,1499,1396,1388,566],"class_list":["post-15694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-research","tag-acoes","tag-dolar","tag-dow","tag-educacao","tag-euro","tag-forex","tag-indices","tag-mercados-financeiros","tag-noticias","tag-international-news"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Arshia Hadidi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-09-26T14:09:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-09-26T14:09:59+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#blogposting\",\"name\":\"A\\u00e7\\u00f5es de Energia e Autom\\u00f3veis Derrubam o Dow. - INFINOX\",\"headline\":\"A\\u00e7\\u00f5es de Energia e Autom\\u00f3veis Derrubam o Dow, Quebrando Sequ\\u00eancia de Quatro Dias de Alta\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/09\\\/Energy-sector-stock.png\",\"width\":1792,\"height\":1024},\"datePublished\":\"2024-09-26T14:09:57+00:00\",\"dateModified\":\"2024-09-26T14:09:59+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Pesquisa, a\\u00e7\\u00f5es, d\\u00f3lar, dow, educa\\u00e7\\u00e3o, euro, FOREX, Indices, mercados financeiros, not\\u00edcias, Not\\u00edcias internacionais, Portugu\\u00eas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Pesquisa\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#listItem\",\"name\":\"A\\u00e7\\u00f5es de Energia e Autom\\u00f3veis Derrubam o Dow, Quebrando Sequ\\u00eancia de Quatro Dias de Alta\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#listItem\",\"position\":5,\"name\":\"A\\u00e7\\u00f5es de Energia e Autom\\u00f3veis Derrubam o Dow, Quebrando Sequ\\u00eancia de Quatro Dias de Alta\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/\",\"name\":\"Arshia Hadidi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2be44dc8aa362b458a8375c7d03f8f3ff8565587e220464cfa25e3a9e723f17?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Arshia Hadidi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/\",\"name\":\"A\\u00e7\\u00f5es de Energia e Autom\\u00f3veis Derrubam o Dow. - INFINOX\",\"description\":\"Os mercados dos EUA enfrentaram uma sess\\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\\u00eancia de quatro dias de ganhos.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/09\\\/Energy-sector-stock.png\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#mainImage\",\"width\":1792,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\\\/#mainImage\"},\"datePublished\":\"2024-09-26T14:09:57+00:00\",\"dateModified\":\"2024-09-26T14:09:59+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX","description":"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos.","canonical_url":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#blogposting","name":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX","headline":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow, Quebrando Sequ\u00eancia de Quatro Dias de Alta","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/09\/Energy-sector-stock.png","width":1792,"height":1024},"datePublished":"2024-09-26T14:09:57+00:00","dateModified":"2024-09-26T14:09:59+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#webpage"},"articleSection":"IX Daily, IX Intel, Pesquisa, a\u00e7\u00f5es, d\u00f3lar, dow, educa\u00e7\u00e3o, euro, FOREX, Indices, mercados financeiros, not\u00edcias, Not\u00edcias internacionais, Portugu\u00eas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","position":3,"name":"Pesquisa","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#listItem","name":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow, Quebrando Sequ\u00eancia de Quatro Dias de Alta"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#listItem","position":5,"name":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow, Quebrando Sequ\u00eancia de Quatro Dias de Alta","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/","name":"Arshia Hadidi","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c2be44dc8aa362b458a8375c7d03f8f3ff8565587e220464cfa25e3a9e723f17?s=96&d=blank&r=g","width":96,"height":96,"caption":"Arshia Hadidi"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#webpage","url":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/","name":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX","description":"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/09\/Energy-sector-stock.png","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#mainImage","width":1792,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/#mainImage"},"datePublished":"2024-09-26T14:09:57+00:00","dateModified":"2024-09-26T14:09:59+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX","og:description":"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos.","og:url":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/","article:published_time":"2024-09-26T14:09:57+00:00","article:modified_time":"2024-09-26T14:09:59+00:00","twitter:card":"summary_large_image","twitter:title":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. - INFINOX","twitter:description":"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos."},"aioseo_meta_data":{"post_id":"15694","title":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow. #separator_sa #site_title","description":"Os mercados dos EUA enfrentaram uma sess\u00e3o turbulenta na quarta-feira, com o Dow Jones Industrial Average interrompendo sua sequ\u00eancia de quatro dias de ganhos.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-15 08:27:39","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-09-26 14:08:53","updated":"2025-11-27 04:29:50"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/\" title=\"Pesquisa\">Pesquisa<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tA\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow, Quebrando Sequ\u00eancia de Quatro Dias de Alta\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/"},{"label":"Pesquisa","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/"},{"label":"A\u00e7\u00f5es de Energia e Autom\u00f3veis Derrubam o Dow, Quebrando Sequ\u00eancia de Quatro Dias de Alta","link":"https:\/\/www.infinox.com\/global\/pt\/acoes-de-energia-e-automoveis-derrubam-o-dow-quebrando-sequencia-de-quatro-dias-de-alta\/"}],"lang":"pt","translations":{"pt":15694},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/15694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=15694"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/15694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/15696"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=15694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=15694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=15694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}