{"id":13364,"date":"2024-06-04T12:24:39","date_gmt":"2024-06-04T12:24:39","guid":{"rendered":"https:\/\/www.infinox.com\/fsc\/?p=13364"},"modified":"2024-06-04T12:24:41","modified_gmt":"2024-06-04T12:24:41","slug":"dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/","title":{"rendered":"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos."},"content":{"rendered":"\n<p>O Dow Jones Industrial Average iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica mais ampla. Apesar da queda do Dow, o S&amp;P 500 conseguiu um leve ganho, enquanto o Nasdaq Composite registrou um crescimento maior, impulsionado pelo forte desempenho do setor de tecnologia. Este desempenho misto destaca a confian\u00e7a incerta no mercado, \u00e0 medida que os traders navegam entre os desafios impostos pelos indicadores econ\u00f4micos e o entusiasmo em torno dos avan\u00e7os tecnol\u00f3gicos, como os novos an\u00fancios de chips de IA da Nvidia. As negocia\u00e7\u00f5es do dia sublinharam a volatilidade cont\u00ednua e os diversos fatores que influenciam o sentimento do investidor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Principias Pontos:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dow Jones Cai em Meio a Preocupa\u00e7\u00f5es Econ\u00f4micas:<\/strong> O \u00cdndice Dow Jones Industrial Average recuou 115,29 pontos, ou 0,30%, para fechar em 38.571,03. Essa queda ocorreu ap\u00f3s dados fracos da manufatura nos EUA levantarem preocupa\u00e7\u00f5es sobre a for\u00e7a da economia, com a\u00e7\u00f5es c\u00edclicas, como os setores de energia, industriais e materiais, fechando no vermelho.<\/li>\n\n\n\n<li><strong>S&amp;P 500 e Nasdaq em Alta Apesar da Volatilidade:<\/strong> O S&amp;P 500 conseguiu um leve ganho de 0,11%, encerrando a sess\u00e3o em 5.283,40 pontos. O Nasdaq Composite subiu 0,56%, alcan\u00e7ando 16.828,67 pontos, impulsionado pelo forte desempenho das a\u00e7\u00f5es de tecnologia, em particular da Nvidia, que subiu quase 5% ap\u00f3s o an\u00fancio de uma nova linha de chips de intelig\u00eancia artificial.<\/li>\n\n\n\n<li><strong>Queda nos Rendimentos dos T\u00edtulos do Tesouro:<\/strong> Os rendimentos dos t\u00edtulos do Tesouro dos EUA ca\u00edram \u00e0 medida que os investidores reagiram a dados fracos de manufatura. O rendimento do t\u00edtulo do Tesouro de 10 anos caiu mais de 8 pontos base, para 4,43%, enquanto o rendimento do t\u00edtulo do Tesouro de 2 anos caiu 5 pontos base, para 4,83%.<\/li>\n\n\n\n<li><strong>Mercados Europeus Sobem:<\/strong> O \u00edndice pan-europeu Stoxx 600 registrou uma alta positiva, aumentando 0,32%, impulsionado principalmente pelo forte desempenho do setor de constru\u00e7\u00e3o, que liderou os ganhos com uma eleva\u00e7\u00e3o de 1,74%. No Reino Unido, o \u00edndice FTSE 100 caiu ligeiramente 0,15% para fechar em 8.262,75, mostrando um recuo modesto em meio aos ganhos mais amplos na Europa. Enquanto isso, o CAC 40 da Fran\u00e7a subiu 0,06% para 7.998, continuando sua tend\u00eancia de alta da semana anterior.<\/li>\n\n\n\n<li><strong>Mercados Asi\u00e1ticos Rally com Altas Recordes na \u00cdndia:<\/strong> Os mercados asi\u00e1ticos tiveram fortes desempenhos, liderados pela \u00cdndia, onde o Nifty 50 e o S&amp;P BSE Sensex subiram ambos 3%. O Nikkei 225 do Jap\u00e3o fechou 1,13% acima, aproximando-se de n\u00edveis recordes, enquanto o \u00edndice Topix mais amplo subiu 0,9%. Na China, o \u00edndice CSI 300 aumentou 0,25% para 3.588,75, fortalecido por uma pesquisa privada mostrando que o PMI de manufatura subiu para 51,7 em maio. O \u00edndice Hang Seng de Hong Kong tamb\u00e9m ganhou 1,77%, e o Kospi da Coreia do Sul avan\u00e7ou 1,74%. Enquanto isso, o S&amp;P\/ASX 200 da Austr\u00e1lia adicionou 0,77%.<\/li>\n\n\n\n<li><strong>Atividade da F\u00e1brica dos EUA e Gastos com Constru\u00e7\u00e3o Caem:<\/strong> A atividade manufatureira dos EUA desacelerou pelo segundo m\u00eas consecutivo em maio, com o \u00edndice de manufatura do ISM caindo para 48,7 em compara\u00e7\u00e3o a 49,2 em abril. Esse decl\u00ednio, marcado por uma queda significativa nos novos pedidos de bens, sinaliza uma contra\u00e7\u00e3o no setor. Al\u00e9m disso, os gastos com projetos de constru\u00e7\u00e3o ca\u00edram inesperadamente, refletindo a desacelera\u00e7\u00e3o econ\u00f4mica mais ampla.<\/li>\n\n\n\n<li><strong>A\u00e7\u00f5es da Berkshire Hathaway Parecem Cair 99,9% em Meio a Falha T\u00e9cnica na NYSE:<\/strong> Uma falha t\u00e9cnica na Bolsa de Valores de Nova York causou uma exibi\u00e7\u00e3o tempor\u00e1ria e err\u00f4nea de uma queda de 99,9% nas a\u00e7\u00f5es A da Berkshire Hathaway (BRK-A). O problema foi resolvido mais tarde no mesmo dia, mas a volatilidade afetou a negocia\u00e7\u00e3o, com as a\u00e7\u00f5es BRK-B caindo at\u00e9 1,1% durante o incidente.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">FX Hoje:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.infinox.com\/fsc\/pt\/instruments\/forex\/\" title=\"EUR\/USD\">EUR\/USD<\/a> Sobe com Dados Fracos de Manufatura nos EUA:<\/strong> O par EUR\/USD subiu para $1,09, seu n\u00edvel mais alto em 10 semanas, ap\u00f3s uma queda no PMI de Manufatura dos EUA. O par atingiu um pico semanal de $1,0998, quase alcan\u00e7ando o n\u00edvel cr\u00edtico de $1,1000. No lado negativo, o suporte encontra-se em $1,0788, a baixa semanal de $1,0788, e a SMA de 200 dias em $1,0760.<\/li>\n\n\n\n<li><strong>GBP\/USD Testa M\u00e1ximos de M\u00faltiplas Semanas:<\/strong> O GBP\/USD avan\u00e7ou para 1,2800, tocando m\u00e1ximos de v\u00e1rias semanas. N\u00edveis-chave de resist\u00eancia incluem 1,2810 e o m\u00e1ximo do ano at\u00e9 agora de 1,2893. Se o par cair abaixo de 1,2700, pode cair em dire\u00e7\u00e3o ao suporte em torno de 1,2643 e mais abaixo para 1,2600.<\/li>\n\n\n\n<li><strong>USD\/CAD Mant\u00e9m-se em Faixa:<\/strong> O USD\/CAD teve dificuldades para romper o n\u00edvel de 1,3600, com o par consolidando pr\u00f3ximo \u00e0 m\u00e9dia m\u00f3vel exponencial (EMA) de 50 dias em 1,3645. O suporte \u00e9 observado na EMA de 200 dias, pr\u00f3xima a 1,3560, enquanto a resist\u00eancia se encontra nas ofertas m\u00e1ximas de 2024, perto de 1,3850.<\/li>\n\n\n\n<li><strong>USD\/MXN Sob Press\u00e3o Em Meio \u00e0 Incerteza Pol\u00edtica: <\/strong>USD\/MXN subiu acima da SMA de 200 dias de 17.15, ap\u00f3s a vit\u00f3ria de Claudia Sheinbaum e a maioria de Morena no Congresso. O par pode subir para 18.00, o m\u00e1ximo do ano de 18.15, e potencialmente mais alto para 18.48. Por outro lado, uma queda abaixo de 17.00 pode abrir caminho para testar o m\u00ednimo do ano de 16.25.<\/li>\n\n\n\n<li><strong>Ouro Recupera Ap\u00f3s Dados de Manufatura dos EUA:<\/strong> O ouro \u00e0 vista subiu 0,9% para $2,348.06 por on\u00e7a, continuando sua trajet\u00f3ria ascendente ap\u00f3s registrar um ganho de 2% no m\u00eas passado. Os futuros do ouro nos EUA subiram cerca de 1% para $2,368.60 por on\u00e7a. Recentemente, os pre\u00e7os atingiram um m\u00e1ximo de $2,449.89 em 20 de maio.<\/li>\n\n\n\n<li><strong>Pre\u00e7os do Petr\u00f3leo Caem em Meio a An\u00fancios da OPEP+: <\/strong>Os pre\u00e7os do petr\u00f3leo bruto nos EUA ca\u00edram mais de 3%, com o contrato de julho do West Texas Intermediate fixando-se em $74,22 por barril, uma queda de $2,77 ou 3,6%. O petr\u00f3leo Brent para agosto tamb\u00e9m recuou $2,75 ou 3,39%, fechando a $78,36 por barril.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1972\" height=\"786\" src=\"https:\/\/www.infinox.com\/fsc\/wp-content\/uploads\/sites\/5\/2024\/06\/Currency-Strenght-4Jun-1.png\" alt=\"\" class=\"wp-image-13365\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/06\/Currency-Strenght-4Jun-1.png 1972w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/06\/Currency-Strenght-4Jun-1-768x306.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/06\/Currency-Strenght-4Jun-1-1536x612.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/06\/Currency-Strenght-4Jun-1-710x283.png 710w\" sizes=\"(max-width: 1972px) 100vw, 1972px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Movimentos de mercado:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>GameStop Dispara com Especula\u00e7\u00e3o: <\/strong>As a\u00e7\u00f5es da GameStop saltaram 21% em meio \u00e0 especula\u00e7\u00e3o de que Keith Gill pode deter uma posi\u00e7\u00e3o significativa no varejista de videogames. Supostamente, Gill postou uma captura de tela de seu portf\u00f3lio, indicando a posse de cinco milh\u00f5es de a\u00e7\u00f5es no valor de mais de $100 milh\u00f5es e 120.000 op\u00e7\u00f5es de compra.<\/li>\n\n\n\n<li><strong>Stericycle Sobe Ap\u00f3s An\u00fancio de Aquisi\u00e7\u00e3o: <\/strong>As a\u00e7\u00f5es da Stericycle subiram quase 14,6% depois que a Waste Management anunciou que iria adquirir a empresa por $7,2 bilh\u00f5es. Em contraste, as a\u00e7\u00f5es da Waste Management ca\u00edram 4,5% com a not\u00edcia.<\/li>\n\n\n\n<li><strong>A\u00e7\u00f5es da <a href=\"https:\/\/www.spotify.com\/br-pt\/premium\/?utm_source=br-pt_brand_contextual_text&amp;utm_medium=paidsearch&amp;utm_campaign=alwayson_latam_br_performancemarketing_core_brand+contextual+text+br-pt+google&amp;gclsrc=aw.ds&amp;gad_source=1&amp;gclid=*\" title=\"Spotify\">Spotify<\/a> sobem ap\u00f3s aumento no pre\u00e7o da assinatura:<\/strong> As a\u00e7\u00f5es da Spotify subiram 5,7% ap\u00f3s o an\u00fancio do aumento no pre\u00e7o da assinatura premium nos EUA a partir de julho. Este \u00e9 o segundo aumento de pre\u00e7os da empresa sueca em um ano.<\/li>\n\n\n\n<li><strong>A\u00e7\u00f5es da GSK Caem com Rev\u00e9s Legal: <\/strong>As a\u00e7\u00f5es da GSK ca\u00edram mais de 8,7% ap\u00f3s um Tribunal Estadual de Delaware decidir que evid\u00eancias cient\u00edficas podem ser apresentadas em aproximadamente 75.000 casos alegando que o medicamento para azia descontinuado Zantac pode conter um carcin\u00f3geno.<\/li>\n\n\n\n<li><strong>Avan\u00e7os da Paramount Global sobre Not\u00edcias de Fus\u00e3o:<\/strong> As a\u00e7\u00f5es da Paramount Global subiram 7,5% ap\u00f3s not\u00edcias de que a empresa e a Skydance concordaram com os termos de uma fus\u00e3o. O acordo est\u00e1 aguardando a aprova\u00e7\u00e3o da acionista controladora da Paramount, Shari Redstone.<\/li>\n\n\n\n<li><strong>A\u00e7\u00f5es da Lattice Semiconductor Caem com Sa\u00edda do CEO:<\/strong> As a\u00e7\u00f5es da Lattice Semiconductor ca\u00edram 15,5% ap\u00f3s o CEO Jim Anderson sair para se juntar \u00e0 Coherent como seu novo CEO. O pre\u00e7o das a\u00e7\u00f5es da Coherent subiu 22,9% ap\u00f3s o an\u00fancio. Esam Elashmawi, chefe de marketing e estrat\u00e9gia da Lattice, foi nomeado CEO interino.<\/li>\n\n\n\n<li><strong>A\u00e7\u00f5es da MarineMax Disparam com Conversas de Aquisi\u00e7\u00e3o:<\/strong> As a\u00e7\u00f5es da MarineMax subiram 27% ap\u00f3s um relat\u00f3rio da Bloomberg News informar que a OneWater Marine est\u00e1 em negocia\u00e7\u00f5es para adquirir a empresa por $40 por a\u00e7\u00e3o. Esta not\u00edcia destaca o potencial de consolida\u00e7\u00e3o no setor de servi\u00e7os de barcos e iates.<\/li>\n\n\n\n<li><strong>AMD e Nvidia Respondem a An\u00fancios de Chips de IA:<\/strong> As a\u00e7\u00f5es da AMD ca\u00edram cerca de 2% ap\u00f3s o an\u00fancio de novos chips de IA, enquanto as a\u00e7\u00f5es da Nvidia subiram 4,9% ap\u00f3s a revela\u00e7\u00e3o de seus chips de IA de pr\u00f3xima gera\u00e7\u00e3o, que devem suceder seu produto anterior &#8220;Blackwell&#8221; lan\u00e7ado em mar\u00e7o.<\/li>\n\n\n\n<li><strong>Atos despenca devido a preocupa\u00e7\u00f5es com acordo de resgate: <\/strong>As a\u00e7\u00f5es da empresa francesa de TI Atos ca\u00edram 18,31% ap\u00f3s anunciar que est\u00e1 trabalhando com credores financeiros para garantir apoio a um acordo de resgate at\u00e9 5 de junho. A empresa visa chegar a um acordo final sobre a reestrutura\u00e7\u00e3o at\u00e9 julho, levantando preocupa\u00e7\u00f5es dos investidores sobre uma poss\u00edvel dilui\u00e7\u00e3o significativa.<\/li>\n\n\n\n<li><strong>As a\u00e7\u00f5es da Structure Therapeutics disparam com resultados positivos de ensaios cl\u00ednicos:<\/strong> As a\u00e7\u00f5es da Structure Therapeutics subiram 54,2% ap\u00f3s a divulga\u00e7\u00e3o de resultados positivos de um ensaio cl\u00ednico de fase intermedi\u00e1ria para seu medicamento experimental contra a obesidade, que ajudou os pacientes a perderem cerca de 6% do peso inicial ap\u00f3s 12 semanas de tratamento.<\/li>\n<\/ul>\n\n\n\n<p>\u00c0 medida que junho come\u00e7a, o desempenho misto do Dow, S&amp;P 500 e Nasdaq destaca a positividade cautelosa do mercado em meio a incertezas econ\u00f4micas cont\u00ednuas. Enquanto o Dow caiu mais de 100 pontos devido a dados fracos de manufatura, o Nasdaq, impulsionado pela tecnologia, e o S&amp;P 500, de base ampla, mostraram resili\u00eancia com ganhos, impulsionados por desempenhos fortes de empresas como a Nvidia. Os rendimentos oscilantes do Tesouro e a recupera\u00e7\u00e3o dos pre\u00e7os do ouro refletem o sentimento dos investidores navegando entre as preocupa\u00e7\u00f5es com a desacelera\u00e7\u00e3o econ\u00f4mica e a antecipa\u00e7\u00e3o de poss\u00edveis ajustes nas taxas de juros. O foco do mercado permanece nas pr\u00f3ximas atualiza\u00e7\u00f5es econ\u00f4micas, particularmente no relat\u00f3rio de empregos de maio, que pode influenciar significativamente a dire\u00e7\u00e3o da pol\u00edtica do Federal Reserve. Enquanto isso, os movimentos dram\u00e1ticos em a\u00e7\u00f5es individuais como GameStop, Stericycle e Atos sublinham a natureza din\u00e2mica do ambiente de negocia\u00e7\u00e3o atual, onde tanto os desenvolvimentos corporativos quanto os sinais econ\u00f4micos mais amplos orientam as decis\u00f5es dos investidores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Dow Jones Industrial Average iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica mais ampla. <\/p>\n","protected":false},"author":30,"featured_media":13366,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[530,30,524],"tags":[1541,1824,1434,1561,563,1499,1396,1657,1388,1854],"class_list":["post-13364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-research","tag-dolar","tag-dow","tag-educacao","tag-euro","tag-forex","tag-indices","tag-mercados-financeiros","tag-nasdaq","tag-noticias","tag-pontos"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Arshia Hadidi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Dow cai mais de 100 pontos - Nasdaq e S&amp;P 500 - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-06-04T12:24:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-04T12:24:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Dow cai mais de 100 pontos - Nasdaq e S&amp;P 500 - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#blogposting\",\"name\":\"Dow cai mais de 100 pontos - Nasdaq e S&P 500 - INFINOX\",\"headline\":\"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos.\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/Dow-Drops-Over-100-2.png\",\"width\":1792,\"height\":1024},\"datePublished\":\"2024-06-04T12:24:39+00:00\",\"dateModified\":\"2024-06-04T12:24:41+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Pesquisa, d\\u00f3lar, dow, educa\\u00e7\\u00e3o, euro, FOREX, Indices, mercados financeiros, nasdaq, not\\u00edcias, pontos, Portugu\\u00eas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Pesquisa\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#listItem\",\"name\":\"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#listItem\",\"position\":5,\"name\":\"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/\",\"name\":\"Arshia Hadidi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2be44dc8aa362b458a8375c7d03f8f3ff8565587e220464cfa25e3a9e723f17?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Arshia Hadidi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/\",\"name\":\"Dow cai mais de 100 pontos - Nasdaq e S&P 500 - INFINOX\",\"description\":\"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\\u00e7\\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\\u00f4mica ampla.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/06\\\/Dow-Drops-Over-100-2.png\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#mainImage\",\"width\":1792,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\\\/#mainImage\"},\"datePublished\":\"2024-06-04T12:24:39+00:00\",\"dateModified\":\"2024-06-04T12:24:41+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Dow cai mais de 100 pontos - Nasdaq e S&amp;P 500 - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"Dow cai mais de 100 pontos - Nasdaq e S&P 500 - INFINOX","description":"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla.","canonical_url":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#blogposting","name":"Dow cai mais de 100 pontos - Nasdaq e S&P 500 - INFINOX","headline":"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos.","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/06\/Dow-Drops-Over-100-2.png","width":1792,"height":1024},"datePublished":"2024-06-04T12:24:39+00:00","dateModified":"2024-06-04T12:24:41+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#webpage"},"articleSection":"IX Daily, IX Intel, Pesquisa, d\u00f3lar, dow, educa\u00e7\u00e3o, euro, FOREX, Indices, mercados financeiros, nasdaq, not\u00edcias, pontos, Portugu\u00eas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","position":3,"name":"Pesquisa","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#listItem","name":"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos."},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#listItem","position":5,"name":"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos.","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/","name":"Arshia Hadidi","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c2be44dc8aa362b458a8375c7d03f8f3ff8565587e220464cfa25e3a9e723f17?s=96&d=blank&r=g","width":96,"height":96,"caption":"Arshia Hadidi"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#webpage","url":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/","name":"Dow cai mais de 100 pontos - Nasdaq e S&P 500 - INFINOX","description":"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/06\/Dow-Drops-Over-100-2.png","@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#mainImage","width":1792,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/#mainImage"},"datePublished":"2024-06-04T12:24:39+00:00","dateModified":"2024-06-04T12:24:41+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"Dow cai mais de 100 pontos - Nasdaq e S&amp;P 500 - INFINOX","og:description":"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla.","og:url":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/","article:published_time":"2024-06-04T12:24:39+00:00","article:modified_time":"2024-06-04T12:24:41+00:00","twitter:card":"summary_large_image","twitter:title":"Dow cai mais de 100 pontos - Nasdaq e S&amp;P 500 - INFINOX","twitter:description":"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla."},"aioseo_meta_data":{"post_id":"13364","title":"Dow cai mais de 100 pontos - Nasdaq e S&amp;P 500 #separator_sa #site_title","description":"O Dow Jones iniciou Junho com uma queda, refletindo as preocupa\u00e7\u00f5es dos investidores sobre dados fracos da manufatura dos EUA e uma incerteza econ\u00f4mica ampla.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-15 05:03:41","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-06-04 12:23:27","updated":"2025-11-27 03:46:50"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/\" title=\"Pesquisa\">Pesquisa<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tDow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos.\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/"},{"label":"Pesquisa","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/"},{"label":"Dow cai mais de 100 pontos, enquanto Nasdaq e S&amp;P 500 apresentam resultados mistos.","link":"https:\/\/www.infinox.com\/global\/pt\/dow-cai-mais-de-100-pontos-enquanto-nasdaq-e-sp-500-apresentam-resultados-mistos\/"}],"lang":"pt","translations":{"pt":13364},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/13364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=13364"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/13364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/13366"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=13364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=13364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=13364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}