{"id":12163,"date":"2024-04-16T12:00:00","date_gmt":"2024-04-16T12:00:00","guid":{"rendered":"https:\/\/www.infinox.com\/fsc\/?p=12163"},"modified":"2024-04-16T13:12:32","modified_gmt":"2024-04-16T13:12:32","slug":"acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas","status":"publish","type":"post","link":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/","title":{"rendered":"A\u00e7\u00f5es caem \u00e0 medida que tens\u00f5es no Oriente M\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas"},"content":{"rendered":"\n<p>Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente, \u00e0 medida que os investidores lidavam com o aumento dos rendimentos dos t\u00edtulos e a escalada das tens\u00f5es no Oriente M\u00e9dio. Apesar dos resultados positivos da Goldman Sachs e dos dados de vendas no varejo nos EUA melhores do que o esperado, os mercados financeiros foram ofuscados pelo espectro do conflito e taxas de juros mais altas. O \u00cdndice Dow Jones Industrial tamb\u00e9m enfrentou uma queda significativa, aproximando-se perigosamente de seu ponto de equil\u00edbrio do ano at\u00e9 a data, uma mudan\u00e7a surpreendente de sua recente proximidade com o marco de 40.000. Esses dados econ\u00f4micos e conflitos geopol\u00edticos lan\u00e7aram uma sombra sobre a perspectiva de curto prazo do mercado, destacando a natureza fr\u00e1gil da estabilidade global e do sentimento dos investidores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Principais pontos:<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>S&amp;P 500 e Nasdaq caem enquanto Dow Jones luta \u00e0 medida que os rendimentos disparam:<\/strong> O S&amp;P 500 caiu 1,2% para fechar o dia em baixa, apesar de um ganho anterior de at\u00e9 0,9%. O Composite Nasdaq enfrentou uma queda mais acentuada, caindo 1,7%, enquanto gigantes da tecnologia como a Salesforce sofreram impactos significativos em meio ao recuo mais amplo do mercado. O \u00cdndice Dow Jones Industrial perdeu 234 pontos, uma queda de 0,6%, recuando de um pico da sess\u00e3o inicial que viu o \u00edndice subir mais de 1%. Esse recuo se aproxima de seu ponto de equil\u00edbrio para 2024, marcando uma mudan\u00e7a dram\u00e1tica de sua posi\u00e7\u00e3o pr\u00f3xima a 40.000 apenas algumas semanas atr\u00e1s.<\/li>\n\n\n\n<li><strong>Mercados europeus terminam mistos em meio a preocupa\u00e7\u00f5es geopol\u00edticas:<\/strong> O \u00edndice Stoxx 600 viu ganhos marginais, terminando ligeiramente mais alto apesar dos avan\u00e7os anteriores. As tens\u00f5es no Oriente M\u00e9dio impactaram especialmente os setores de petr\u00f3leo e g\u00e1s, que ca\u00edram 1,6%. O FTSE 100 declinou 30,05 pontos, fechando em queda de 0,38% em 7965,53, enquanto os mercados regionais exibiam rea\u00e7\u00f5es mistas ao drama geopol\u00edtico em andamento e suas implica\u00e7\u00f5es para a estabilidade global.<\/li>\n\n\n\n<li><strong>Mercados asi\u00e1ticos declinam \u00e0 medida que as tens\u00f5es entre Israel e Ir\u00e3 se intensificam: <\/strong>Os mercados asi\u00e1ticos experimentaram uma queda, com o Nikkei 225 do Jap\u00e3o caindo 0,74% para fechar em 39.232,8, e o Kospi da Coreia do Sul deslizando 0,42% para terminar em 2.670,43. No entanto, o CSI 300 da China continental desafiou a tend\u00eancia com um salto de mais de 2%, indicando diferentes rea\u00e7\u00f5es dos investidores na regi\u00e3o. Os ataques durante o fim de semana trouxeram aten\u00e7\u00e3o significativa para a estabilidade da regi\u00e3o, afetando o sentimento do mercado e focando os investidores nos pr\u00f3ximos relat\u00f3rios econ\u00f4micos da China e do Jap\u00e3o.<\/li>\n\n\n\n<li><strong>Pre\u00e7os do petr\u00f3leo podem disparar acima de $100 em retalia\u00e7\u00e3o israelense:<\/strong> Analistas alertam que os pre\u00e7os do petr\u00f3leo n\u00e3o est\u00e3o incorporando o risco de conflito direto cont\u00ednuo entre Ir\u00e3 e Israel, com pre\u00e7os potencialmente subindo acima de $100 por barril se Israel retaliar. O contrato de petr\u00f3leo bruto West Texas Intermediate (WTI) para entrega em maio perdeu 25 centavos, ou 0,29%, para se fixar em $85,41 por barril.<\/li>\n\n\n\n<li><strong>Vendas no varejo superam expectativas:<\/strong> As vendas no varejo dos EUA tiveram um aumento de 0,7% em mar\u00e7o, superando a previs\u00e3o de 0,3% dos economistas, sugerindo que o consumo continua robusto apesar das press\u00f5es inflacion\u00e1rias cont\u00ednuas.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>FX Hoje:<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>D\u00f3lar fortalece com aumento nas vendas no varejo:<\/strong> O d\u00f3lar americano atingiu um novo pico contra uma cesta de moedas, subindo para 106,23, seu ponto mais alto desde o in\u00edcio de novembro, fortalecido por dados surpreendentemente fortes de vendas no varejo. O relat\u00f3rio mostrou um aumento de 0,7% em mar\u00e7o, com revis\u00f5es nos dados de fevereiro indicando um aumento para 0,9% de 0,6%, sugerindo uma atividade econ\u00f4mica robusta que poderia influenciar as decis\u00f5es de taxas do Federal Reserve.<\/li>\n\n\n\n<li><strong>Iene atinge baixa hist\u00f3rica:<\/strong> O iene japon\u00eas enfraqueceu significativamente, caindo para seu n\u00edvel mais baixo desde 1990. O par USD\/JPY disparou para 154,45 durante a sess\u00e3o de negocia\u00e7\u00e3o, sublinhando o impacto do d\u00f3lar forte e o grande diferencial de taxas de juros entre os EUA e o Jap\u00e3o. A possibilidade de interven\u00e7\u00e3o monet\u00e1ria japonesa continua sendo um tema de grande interesse entre os traders.<\/li>\n\n\n\n<li><strong><a href=\"https:\/\/www.infinox.com\/fsc\/pt\/instruments\/forex\/\" title=\"Euro\">Euro<\/a> sob press\u00e3o em meio \u00e0 volatilidade do mercado: <\/strong>O euro caiu para seu ponto mais fraco desde 3 de novembro, tocando 1,0622 contra o d\u00f3lar. A incerteza cont\u00ednua no Oriente M\u00e9dio e indicadores econ\u00f4micos mais fortes dos EUA colocaram press\u00e3o descendente sobre o euro, especialmente \u00e0 medida que o Banco Central Europeu sinaliza poss\u00edveis cortes nas taxas em um futuro pr\u00f3ximo.<\/li>\n\n\n\n<li><strong>D\u00f3lar canadense enfrenta dificuldades enquanto os pre\u00e7os do petr\u00f3leo flutuam:<\/strong> O par USD\/CAD alcan\u00e7ou novos picos pr\u00f3ximos ao n\u00edvel de 1,3800, influenciado pela flutua\u00e7\u00e3o dos pre\u00e7os do petr\u00f3leo e pela for\u00e7a mais ampla do d\u00f3lar americano. Os traders est\u00e3o monitorando de perto os pr\u00f3ximos dados de infla\u00e7\u00e3o canadense, que podem fornecer mais pistas sobre a dire\u00e7\u00e3o da pol\u00edtica monet\u00e1ria do Banco do Canad\u00e1.<\/li>\n\n\n\n<li><strong>Libra esterlina estagna enquanto traders aguardam relat\u00f3rios econ\u00f4micos:<\/strong> O GBP\/USD permaneceu relativamente inalterado, pairando em torno da marca de 1,2440 enquanto os traders antecipam a divulga\u00e7\u00e3o do relat\u00f3rio do mercado de trabalho de fevereiro do Reino Unido. A estabilidade da libra reflete uma abordagem cautelosa dos investidores em meio \u00e0 incerteza mais ampla do mercado e aos pr\u00f3ximos lan\u00e7amentos de dados econ\u00f4micos.<\/li>\n\n\n\n<li><strong>Ouro se aproxima de recordes hist\u00f3ricos pela demanda de ref\u00fagio seguro: <\/strong>O ouro \u00e0 vista subiu 0,9% para $2,365.09 por on\u00e7a, aproximando-se do recorde de sexta-feira de $2,431.29, \u00e0 medida que as tens\u00f5es no Oriente M\u00e9dio impulsionaram a compra de ref\u00fagio seguro. Os futuros de ouro dos EUA se fixaram 0,4% mais altos em $2,383, com o potencial de subir para $2,431 e depois $2,450. No entanto, um fechamento abaixo de $2,343 poderia empurrar os pre\u00e7os para $2,300.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1946\" height=\"778\" src=\"https:\/\/www.infinox.com\/fsc\/wp-content\/uploads\/sites\/5\/2024\/04\/Currency-Strenght-16Apr.png\" alt=\"\" class=\"wp-image-12164\" srcset=\"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/04\/Currency-Strenght-16Apr.png 1946w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/04\/Currency-Strenght-16Apr-768x307.png 768w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/04\/Currency-Strenght-16Apr-1536x614.png 1536w, https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/04\/Currency-Strenght-16Apr-710x284.png 710w\" sizes=\"(max-width: 1946px) 100vw, 1946px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Movimentadores de Mercado:<\/strong><\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.salesforce.com\/br\/?ir=1\" title=\"Salesforce\">Salesforce<\/a> enfrenta forte queda:<\/strong> Salesforce emergiu como uma das maiores perdedoras do dia, com suas a\u00e7\u00f5es despencando mais de 7%. A queda foi desencadeada por relat\u00f3rios de que a empresa est\u00e1 em discuss\u00f5es avan\u00e7adas para adquirir a empresa de gerenciamento de dados Inform\u00e1tica, causando preocupa\u00e7\u00e3o entre os investidores sobre o custo potencial e os desafios de integra\u00e7\u00e3o de tal acordo.<\/li>\n\n\n\n<li><strong>Goldman Sachs dispara com fortes ganhos:<\/strong> Goldman Sachs experimentou um aumento not\u00e1vel, com as a\u00e7\u00f5es subindo aproximadamente 3% ap\u00f3s a empresa reportar ganhos do primeiro trimestre que superaram em muito as expectativas de Wall Street. O banco de investimentos registrou ganhos de $11,58 por a\u00e7\u00e3o sobre receita de $14,21 bilh\u00f5es, refletindo um desempenho robusto nos mercados de capitais e na subscri\u00e7\u00e3o.<\/li>\n\n\n\n<li><strong>Tesla anuncia redu\u00e7\u00f5es na for\u00e7a de trabalho:<\/strong> As a\u00e7\u00f5es da Tesla ca\u00edram 5,6% ap\u00f3s um memorando interno revelar planos para demitir mais de 10% de sua for\u00e7a de trabalho global. A decis\u00e3o faz parte de uma estrat\u00e9gia mais ampla para cortar custos e aumentar a produtividade \u00e0 medida que a empresa se prepara para sua pr\u00f3xima fase de crescimento.<\/li>\n\n\n\n<li><strong>Medical Properties Trust v\u00ea ganho significativo:<\/strong> Medical Properties Trust desfrutou de um aumento substancial, com as a\u00e7\u00f5es saltando 18,8% ap\u00f3s o fideicomisso de investimento imobili\u00e1rio anunciar a venda de interesses majorit\u00e1rios em cinco hospitais de Utah para uma nova joint venture por $886 milh\u00f5es, destacando o realinhamento estrat\u00e9gico de ativos da empresa.<\/li>\n\n\n\n<li><strong>Logitech \u00e9 rebaixada, a\u00e7\u00f5es caem:<\/strong> As a\u00e7\u00f5es da Logitech ca\u00edram 6,4% ap\u00f3s um rebaixamento pela Morgan Stanley de peso igual para abaixo do peso. O rebaixamento foi baseado na avalia\u00e7\u00e3o de que o mercado est\u00e1 superestimando o potencial de crescimento da empresa, com uma previs\u00e3o de apenas 3% de crescimento anual de receita at\u00e9 o ano fiscal de 2027.<\/li>\n\n\n\n<li><strong>Snap One adquirida pela Resideo Technologies: <\/strong>As a\u00e7\u00f5es da Snap One dispararam 29,5% ap\u00f3s o an\u00fancio de que a Resideo Technologies adquiriria o provedor de produtos de vida inteligente por aproximadamente $1,4 bilh\u00e3o, ou $10,75 por a\u00e7\u00e3o em dinheiro. Em contrapartida, as a\u00e7\u00f5es da Resideo ca\u00edram 3,5% enquanto o mercado digeria as implica\u00e7\u00f5es financeiras da aquisi\u00e7\u00e3o.<\/li>\n\n\n\n<li><strong>Charles Schwab publica resultados mistos: <\/strong>As a\u00e7\u00f5es da Charles Schwab viram ganhos modestos, subindo 1,7%, ap\u00f3s a empresa relatar resultados mistos do primeiro trimestre. A corretora reportou ganhos de 74 centavos por a\u00e7\u00e3o e receita de $4,74 bilh\u00f5es, superando ligeiramente a previs\u00e3o de receita de consenso de $4,71 bilh\u00f5es, sinalizando sa\u00fade financeira est\u00e1vel apesar das condi\u00e7\u00f5es de mercado desafiadoras.<\/li>\n\n\n\n<li><strong>Coupang ganha com upgrade: <\/strong>As a\u00e7\u00f5es da Coupang aumentaram 1,9% ap\u00f3s um upgrade de neutro para comprar no Citi. O banco expressou confian\u00e7a na expans\u00e3o futura das margens da Coupang enquanto o gigante do com\u00e9rcio eletr\u00f4nico com sede na Coreia do Sul planeja aumentar suas taxas de assinatura, antecipando resist\u00eancia m\u00ednima do cliente devido aos seus fortes servi\u00e7os de entrega.<\/li>\n\n\n\n<li><strong>Reddit inicia com cobertura de analistas mista:<\/strong> As a\u00e7\u00f5es do Reddit ca\u00edram 5,4% enquanto os analistas iniciavam a cobertura com opini\u00f5es mistas. Enquanto o Morgan Stanley iniciou a a\u00e7\u00e3o com peso igual e JPMorgan e Goldman Sachs emitiram uma classifica\u00e7\u00e3o neutra, sugerindo valor justo nos pre\u00e7os atuais, o Deutsche Bank e o Raymond James foram mais otimistas, rotulando o Reddit como compra e compra forte, respectivamente. Esse sentimento variado de analistas reflete as diversas perspectivas sobre a avalia\u00e7\u00e3o do Reddit e o potencial de crescimento futuro.<\/li>\n\n\n\n<li><strong>Trump Media &amp; Technology Group enfrenta forte queda:<\/strong> As a\u00e7\u00f5es da Trump Media &amp; Technology Group despencaram 18,4% ap\u00f3s a empresa anunciar planos para emitir at\u00e9 21,5 milh\u00f5es de a\u00e7\u00f5es. Desde sua estreia no mercado em 26 de mar\u00e7o, o pre\u00e7o das a\u00e7\u00f5es diminuiu dramaticamente, perdendo mais de 62% de seu valor, intensificando as preocupa\u00e7\u00f5es dos investidores sobre a estabilidade da empresa e a posi\u00e7\u00e3o no mercado diante dos desafios regulat\u00f3rios e competitivos mais amplos.<\/li>\n<\/ul>\n\n\n\n<p>A sess\u00e3o de mercado de segunda-feira foi definida por uma volatilidade aumentada \u00e0 medida que os investidores lidavam com as tens\u00f5es geopol\u00edticas crescentes entre Ir\u00e3 e Israel, juntamente com dados econ\u00f4micos inesperadamente fortes que aumentaram as preocupa\u00e7\u00f5es sobre a infla\u00e7\u00e3o persistente e um aperto monet\u00e1rio mais agressivo pelo Federal Reserve. Embora as vendas no varejo robustas e os resultados de lucros tenham inicialmente impulsionado o sentimento, a possibilidade de retalia\u00e7\u00e3o potencial ap\u00f3s o ataque sem precedentes do Ir\u00e3 ao territ\u00f3rio israelense acabou reduzindo o apetite de risco dos investidores. \u00c0 medida que a situa\u00e7\u00e3o no Oriente M\u00e9dio continua a se desenrolar, \u00e9 prov\u00e1vel que os mercados permane\u00e7am em alerta, monitorando de perto os desenvolvimentos e seu potencial impacto nas economias globais e nas decis\u00f5es pol\u00edticas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente.<\/p>\n","protected":false},"author":30,"featured_media":12165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[530,30,524],"tags":[1390,1541,1434,1561,563,1499,1396,1388,1875,1706],"class_list":["post-12163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espresso-morning-call","category-ix-intel","category-research","tag-acoes","tag-dolar","tag-educacao","tag-euro","tag-forex","tag-indices","tag-mercados-financeiros","tag-noticias","tag-oriente-medio","tag-taxas"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Arshia Hadidi\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"INFINOX -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX\" \/>\n\t\t<meta property=\"og:description\" content=\"Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-16T12:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-16T13:12:32+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#blogposting\",\"name\":\"A\\u00e7\\u00f5es caem pelas tens\\u00f5es no Oriente M\\u00e9dio - INFINOX\",\"headline\":\"A\\u00e7\\u00f5es caem \\u00e0 medida que tens\\u00f5es no Oriente M\\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas\",\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/04\\\/SP500-index-downturn.png\",\"width\":1792,\"height\":1024},\"datePublished\":\"2024-04-16T12:00:00+00:00\",\"dateModified\":\"2024-04-16T13:12:32+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#webpage\"},\"articleSection\":\"IX Daily, IX Intel, Pesquisa, a\\u00e7\\u00f5es, d\\u00f3lar, educa\\u00e7\\u00e3o, euro, FOREX, Indices, mercados financeiros, not\\u00edcias, Oriente M\\u00e9dio, taxas, Portugu\\u00eas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"position\":2,\"name\":\"IX Intel\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"position\":3,\"name\":\"Pesquisa\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/#listItem\",\"name\":\"IX Intel\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"position\":4,\"name\":\"IX Daily\",\"item\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#listItem\",\"name\":\"A\\u00e7\\u00f5es caem \\u00e0 medida que tens\\u00f5es no Oriente M\\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/#listItem\",\"name\":\"Pesquisa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#listItem\",\"position\":5,\"name\":\"A\\u00e7\\u00f5es caem \\u00e0 medida que tens\\u00f5es no Oriente M\\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/ix-intel\\\/research\\\/espresso-morning-call\\\/#listItem\",\"name\":\"IX Daily\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\",\"name\":\"www infinox dev\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/\",\"name\":\"Arshia Hadidi\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c2be44dc8aa362b458a8375c7d03f8f3ff8565587e220464cfa25e3a9e723f17?s=96&d=blank&r=g\",\"width\":96,\"height\":96,\"caption\":\"Arshia Hadidi\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#webpage\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/\",\"name\":\"A\\u00e7\\u00f5es caem pelas tens\\u00f5es no Oriente M\\u00e9dio - INFINOX\",\"description\":\"Em um dia marcado pelo aumento da incerteza global, tanto o S&P 500 quanto o Nasdaq recuaram acentuadamente.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/authors\\\/arshiahadidi\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2024\\\/04\\\/SP500-index-downturn.png\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#mainImage\",\"width\":1792,\"height\":1024},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/pt\\\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\\\/#mainImage\"},\"datePublished\":\"2024-04-16T12:00:00+00:00\",\"dateModified\":\"2024-04-16T13:12:32+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#website\",\"url\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/\",\"name\":\"www infinox dev\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.infinox.com\\\/global\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX<\/title>\n\n","aioseo_head_json":{"title":"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX","description":"Em um dia marcado pelo aumento da incerteza global, tanto o S&P 500 quanto o Nasdaq recuaram acentuadamente.","canonical_url":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#blogposting","name":"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX","headline":"A\u00e7\u00f5es caem \u00e0 medida que tens\u00f5es no Oriente M\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas","author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/04\/SP500-index-downturn.png","width":1792,"height":1024},"datePublished":"2024-04-16T12:00:00+00:00","dateModified":"2024-04-16T13:12:32+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#webpage"},"isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#webpage"},"articleSection":"IX Daily, IX Intel, Pesquisa, a\u00e7\u00f5es, d\u00f3lar, educa\u00e7\u00e3o, euro, FOREX, Indices, mercados financeiros, not\u00edcias, Oriente M\u00e9dio, taxas, Portugu\u00eas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","position":1,"name":"Home","item":"https:\/\/www.infinox.com\/global","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","position":2,"name":"IX Intel","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","position":3,"name":"Pesquisa","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/#listItem","name":"IX Intel"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","position":4,"name":"IX Daily","item":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#listItem","name":"A\u00e7\u00f5es caem \u00e0 medida que tens\u00f5es no Oriente M\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/#listItem","name":"Pesquisa"}},{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#listItem","position":5,"name":"A\u00e7\u00f5es caem \u00e0 medida que tens\u00f5es no Oriente M\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas","previousItem":{"@type":"ListItem","@id":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/#listItem","name":"IX Daily"}}]},{"@type":"Organization","@id":"https:\/\/www.infinox.com\/global\/#organization","name":"www infinox dev","url":"https:\/\/www.infinox.com\/global\/"},{"@type":"Person","@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author","url":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/","name":"Arshia Hadidi","image":{"@type":"ImageObject","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/c2be44dc8aa362b458a8375c7d03f8f3ff8565587e220464cfa25e3a9e723f17?s=96&d=blank&r=g","width":96,"height":96,"caption":"Arshia Hadidi"}},{"@type":"WebPage","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#webpage","url":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/","name":"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX","description":"Em um dia marcado pelo aumento da incerteza global, tanto o S&P 500 quanto o Nasdaq recuaram acentuadamente.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.infinox.com\/global\/#website"},"breadcrumb":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#breadcrumblist"},"author":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"creator":{"@id":"https:\/\/www.infinox.com\/global\/authors\/arshiahadidi\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.infinox.com\/global\/wp-content\/uploads\/sites\/5\/2024\/04\/SP500-index-downturn.png","@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#mainImage","width":1792,"height":1024},"primaryImageOfPage":{"@id":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/#mainImage"},"datePublished":"2024-04-16T12:00:00+00:00","dateModified":"2024-04-16T13:12:32+00:00"},{"@type":"WebSite","@id":"https:\/\/www.infinox.com\/global\/#website","url":"https:\/\/www.infinox.com\/global\/","name":"www infinox dev","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.infinox.com\/global\/#organization"}}]},"og:locale":"en_US","og:site_name":"INFINOX -","og:type":"article","og:title":"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX","og:description":"Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente.","og:url":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/","article:published_time":"2024-04-16T12:00:00+00:00","article:modified_time":"2024-04-16T13:12:32+00:00","twitter:card":"summary_large_image","twitter:title":"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio - INFINOX","twitter:description":"Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente."},"aioseo_meta_data":{"post_id":"12163","title":"A\u00e7\u00f5es caem pelas tens\u00f5es no Oriente M\u00e9dio #separator_sa #site_title","description":"Em um dia marcado pelo aumento da incerteza global, tanto o S&amp;P 500 quanto o Nasdaq recuaram acentuadamente.","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2025-08-15 04:25:48","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-04-16 13:07:56","updated":"2025-11-27 03:36:45"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/\" title=\"IX Intel\">IX Intel<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/\" title=\"Pesquisa\">Pesquisa<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/\" title=\"IX Daily\">IX Daily<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tA\u00e7\u00f5es caem \u00e0 medida que tens\u00f5es no Oriente M\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.infinox.com\/global"},{"label":"IX Intel","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/"},{"label":"Pesquisa","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/"},{"label":"IX Daily","link":"https:\/\/www.infinox.com\/global\/pt\/ix-intel\/research\/espresso-morning-call\/"},{"label":"A\u00e7\u00f5es caem \u00e0 medida que tens\u00f5es no Oriente M\u00e9dio se intensificam; Dados robustos alimentam temores de aumento de taxas","link":"https:\/\/www.infinox.com\/global\/pt\/acoes-caem-a-medida-que-tensoes-no-oriente-medio-se-intensificam-dados-robustos-alimentam-temores-de-aumento-de-taxas\/"}],"lang":"pt","translations":{"pt":12163},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/12163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/comments?post=12163"}],"version-history":[{"count":0,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/posts\/12163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media\/12165"}],"wp:attachment":[{"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/media?parent=12163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/categories?post=12163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infinox.com\/global\/wp-json\/wp\/v2\/tags?post=12163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}